{"id":783,"date":"2010-05-27T10:05:00","date_gmt":"2010-05-27T10:05:00","guid":{"rendered":"http:\/\/carideal.com\/blog\/?p=783"},"modified":"2016-10-16T15:50:54","modified_gmt":"2016-10-16T13:50:54","slug":"la-renault-fluence-concurrence-la-megane","status":"publish","type":"post","link":"https:\/\/www.carideal.com\/blog\/2010\/05\/27\/la-renault-fluence-concurrence-la-megane\/","title":{"rendered":"La Renault Fluence concurrence la Megane"},"content":{"rendered":"<p>&nbsp;<\/p>\n<h1><strong>La Renault Fluence concurrence la Megane<\/strong><\/h1>\n<p>La Renault Fluence n\u2019est pas une M\u00e9gane \u00e0 coffre comme son nom le revendique. C\u2019est en fait une alchimie de pi\u00e8ces rapport\u00e9es des diff\u00e9rentes marques du groupe Renault.<\/p>\n<p>Un bel exemple de la politique \u00e9conomique interne du groupe qui consiste \u00e0 \u00e9viter autant que possible de fabriquer de nouvelles pi\u00e8ces en cherchant \u00e0 recycler de l\u2019existant. La Fluence est \u00e0 ce titre un cas d\u2019\u00e9cole.<\/p>\n<p>Mais on aurait tord de porter un jugement \u00e0 partir de ses dessou, car la Fluence pr\u00e9sente d\u2019abord l\u2019avantage de capitaliser sur des \u00e9l\u00e9ments fiabilis\u00e9s et met th\u00e9oriquement son utilisateur un peu plus \u00e0 l'abri des pannes de jeunesse rencontr\u00e9s sur des nouveaux mod\u00e8les. La Fluence est ensuite une voiture \u00e0 part dans la gamme Renault. Son design se d\u00e9marque de sa cousine M\u00e9gane, plus rond et un peu moins homog\u00e8ne. Avec son coffre g\u00e9n\u00e9reux de 530 litres, cette berline compacte est longue (4m62) et ne c\u00e8de que 7 cm \u00e0 la Laguna.<\/p>\n<p>A bord, l\u2019univers de la M\u00e9gane 3 est repris de mani\u00e8re int\u00e9grale \u00e0 quelques exceptions pr\u00e8s. Le compteur analogique tr\u00e8s appr\u00e9ciable sur la Megane est ainsi remplac\u00e9 par un cadran \u00e0 aiguille peu lisible<\/p>\n<p>Au volant, il faut oublier les qualit\u00e9s dynamiques de la M\u00e9gane 3. Car \u00e7a flotte dans cette Fluence, l\u2019amortissement est tr\u00e8s souple, tr\u00e8s loin des standards des compacts europ\u00e9ennes et ne vous permettra pas de jouer sur les petites routes sinueuses. Une orientation d\u00e9lib\u00e9r\u00e9e de la part de Renault puisque la voiture est avant tout destin\u00e9e \u00e0 alimenter d\u2019autres march\u00e9s (bassin M\u00e9diterran\u00e9en, Moyen-Orient, Russie) o\u00f9 les routes sont parfois en mauvais \u00e9tat. N\u00e9anmoins, la Fluence se montre d\u2019un grand confort.<\/p>\n<p>La motorisation essay\u00e9e ici, le 1.5 dCi de 105chevaux, est dans la m\u00eame veine, tranquille, destin\u00e9e \u00e0 une conduite apais\u00e9e. La boite m\u00e9canique \u00e0 6 vitesses \u00e0 laquelle il est associ\u00e9 lui donne en revanche suffisamment de voix et il se montre bien insonoris\u00e9.<\/p>\n<p>La dotation en \u00e9quipement est l\u00e9g\u00e8rement plus g\u00e9n\u00e9reuse que sur la M\u00e9gane. Avec un tarif identique pour les motorisations propos\u00e9es (\u00e0 partir de 19.700 euros), elle offre quelques \u00e9quipements suppl\u00e9mentaires comme la climatisation bi-zone r\u00e9gul\u00e9e et le r\u00e9gulateur de vitesse. A noter qu\u2019il est possible ici aussi d\u2019opter pour le syst\u00e8me de navigation Carminat TomTom.<\/p>\n<p>Malgr\u00e9 son manque de charisme et de dynamisme, la Fluence a donc un coup \u00e0 jouer en s\u2019adressant aux personnes recherchant une familiale abordable et confortable.<\/p>\n<p>Renault Megane DCI 110<br \/>\nWolkswagen Golf<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; La Renault Fluence concurrence la Megane La Renault Fluence n\u2019est pas une M\u00e9gane \u00e0 coffre comme son nom le revendique. C\u2019est en fait une alchimie de pi\u00e8ces rapport\u00e9es des diff\u00e9rentes marques du groupe Renault. Un bel exemple de la politique \u00e9conomique interne du groupe qui consiste \u00e0 \u00e9viter autant que possible de fabriquer de &#8230; <a title=\"La Renault Fluence concurrence la Megane\" class=\"read-more\" href=\"https:\/\/www.carideal.com\/blog\/2010\/05\/27\/la-renault-fluence-concurrence-la-megane\/\" aria-label=\"En savoir plus sur La Renault Fluence concurrence la Megane\">Lire plus<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-783","post","type-post","status-publish","format-standard","hentry","category-marche-automobile-voiture-neuve-occasion-4x4-suv"],"wppr_data":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La Renault Fluence concurrence la Megane - Blog auto Carid\u00e9al<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.carideal.com\/blog\/2010\/05\/27\/la-renault-fluence-concurrence-la-megane\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Renault Fluence concurrence la Megane - Blog auto Carid\u00e9al\" \/>\n<meta property=\"og:description\" content=\"&nbsp; La Renault Fluence concurrence la Megane La Renault Fluence n\u2019est pas une M\u00e9gane \u00e0 coffre comme son nom le revendique. C\u2019est en fait une alchimie de pi\u00e8ces rapport\u00e9es des diff\u00e9rentes marques du groupe Renault. Un bel exemple de la politique \u00e9conomique interne du groupe qui consiste \u00e0 \u00e9viter autant que possible de fabriquer de ... Lire plus\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.carideal.com\/blog\/2010\/05\/27\/la-renault-fluence-concurrence-la-megane\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog auto Carid\u00e9al\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Carideal.mandataire.automobile\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Carideal.mandataire.automobile\/\" \/>\n<meta property=\"article:published_time\" content=\"2010-05-27T10:05:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-10-16T13:50:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2016\/03\/logo-carideal-mandataire-automobile.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"N.S Carideal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@caridealauto\" \/>\n<meta name=\"twitter:site\" content=\"@caridealauto\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"N.S Carideal\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.carideal.com\/blog\/2010\/05\/27\/la-renault-fluence-concurrence-la-megane\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/2010\/05\/27\/la-renault-fluence-concurrence-la-megane\/\"},\"author\":{\"name\":\"N.S Carideal\",\"@id\":\"https:\/\/www.carideal.com\/blog\/#\/schema\/person\/985c7e757d1042d647f21bfaf8d41ebc\"},\"headline\":\"La Renault Fluence concurrence la Megane\",\"datePublished\":\"2010-05-27T10:05:00+00:00\",\"dateModified\":\"2016-10-16T13:50:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/2010\/05\/27\/la-renault-fluence-concurrence-la-megane\/\"},\"wordCount\":457,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/#organization\"},\"articleSection\":[\"March\u00e9 automobile\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.carideal.com\/blog\/2010\/05\/27\/la-renault-fluence-concurrence-la-megane\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.carideal.com\/blog\/2010\/05\/27\/la-renault-fluence-concurrence-la-megane\/\",\"url\":\"https:\/\/www.carideal.com\/blog\/2010\/05\/27\/la-renault-fluence-concurrence-la-megane\/\",\"name\":\"La Renault Fluence concurrence la Megane - Blog auto Carid\u00e9al\",\"isPartOf\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/#website\"},\"datePublished\":\"2010-05-27T10:05:00+00:00\",\"dateModified\":\"2016-10-16T13:50:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/2010\/05\/27\/la-renault-fluence-concurrence-la-megane\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.carideal.com\/blog\/2010\/05\/27\/la-renault-fluence-concurrence-la-megane\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.carideal.com\/blog\/2010\/05\/27\/la-renault-fluence-concurrence-la-megane\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog Carid\u00e9al\",\"item\":\"https:\/\/www.carideal.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"March\u00e9 automobile\",\"item\":\"https:\/\/www.carideal.com\/blog\/marche-automobile-voiture-neuve-occasion-4x4-suv\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"La Renault Fluence concurrence la Megane\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.carideal.com\/blog\/#website\",\"url\":\"https:\/\/www.carideal.com\/blog\/\",\"name\":\"Blog auto Carid\u00e9al\",\"description\":\"Actualit\u00e9 auto par des passionn\u00e9s\",\"publisher\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.carideal.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.carideal.com\/blog\/#organization\",\"name\":\"Carideal\",\"url\":\"https:\/\/www.carideal.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.carideal.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2016\/03\/logo-carideal-mandataire-automobile.png\",\"contentUrl\":\"http:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2016\/03\/logo-carideal-mandataire-automobile.png\",\"width\":300,\"height\":300,\"caption\":\"Carideal\"},\"image\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Carideal.mandataire.automobile\",\"https:\/\/x.com\/caridealauto\",\"https:\/\/www.instagram.com\/carideal1\/\",\"https:\/\/www.linkedin.com\/company\/carideal.com\",\"https:\/\/fr.pinterest.com\/schiavonsas\/\",\"https:\/\/www.youtube.com\/user\/caridealsas\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.carideal.com\/blog\/#\/schema\/person\/985c7e757d1042d647f21bfaf8d41ebc\",\"name\":\"N.S Carideal\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.carideal.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/edb7ccdf1a4e3d14aef967760d354d0e?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/edb7ccdf1a4e3d14aef967760d354d0e?s=96&r=g\",\"caption\":\"N.S Carideal\"},\"description\":\"Depuis tout petit fan d'automobile. Il est question d'essayer et de comparer toutes ces voitures qui nous ont fait r\u00e9ver, avant que celles-ci ne devient uniquement des voitures de collection.\",\"sameAs\":[\"http:\/\/www.carideal.com\/blog\",\"https:\/\/www.facebook.com\/Carideal.mandataire.automobile\/\",\"https:\/\/www.linkedin.com\/in\/nschiavon\/\",\"https:\/\/www.youtube.com\/user\/caridealsas\/\"],\"url\":\"https:\/\/www.carideal.com\/blog\/author\/admin_carideal\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Renault Fluence concurrence la Megane - Blog auto Carid\u00e9al","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.carideal.com\/blog\/2010\/05\/27\/la-renault-fluence-concurrence-la-megane\/","og_locale":"fr_FR","og_type":"article","og_title":"La Renault Fluence concurrence la Megane - Blog auto Carid\u00e9al","og_description":"&nbsp; La Renault Fluence concurrence la Megane La Renault Fluence n\u2019est pas une M\u00e9gane \u00e0 coffre comme son nom le revendique. C\u2019est en fait une alchimie de pi\u00e8ces rapport\u00e9es des diff\u00e9rentes marques du groupe Renault. Un bel exemple de la politique \u00e9conomique interne du groupe qui consiste \u00e0 \u00e9viter autant que possible de fabriquer de ... Lire plus","og_url":"https:\/\/www.carideal.com\/blog\/2010\/05\/27\/la-renault-fluence-concurrence-la-megane\/","og_site_name":"Blog auto Carid\u00e9al","article_publisher":"https:\/\/www.facebook.com\/Carideal.mandataire.automobile","article_author":"https:\/\/www.facebook.com\/Carideal.mandataire.automobile\/","article_published_time":"2010-05-27T10:05:00+00:00","article_modified_time":"2016-10-16T13:50:54+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2016\/03\/logo-carideal-mandataire-automobile.png","type":"image\/png"}],"author":"N.S Carideal","twitter_card":"summary_large_image","twitter_creator":"@caridealauto","twitter_site":"@caridealauto","twitter_misc":{"\u00c9crit par":"N.S Carideal","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.carideal.com\/blog\/2010\/05\/27\/la-renault-fluence-concurrence-la-megane\/#article","isPartOf":{"@id":"https:\/\/www.carideal.com\/blog\/2010\/05\/27\/la-renault-fluence-concurrence-la-megane\/"},"author":{"name":"N.S Carideal","@id":"https:\/\/www.carideal.com\/blog\/#\/schema\/person\/985c7e757d1042d647f21bfaf8d41ebc"},"headline":"La Renault Fluence concurrence la Megane","datePublished":"2010-05-27T10:05:00+00:00","dateModified":"2016-10-16T13:50:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.carideal.com\/blog\/2010\/05\/27\/la-renault-fluence-concurrence-la-megane\/"},"wordCount":457,"commentCount":0,"publisher":{"@id":"https:\/\/www.carideal.com\/blog\/#organization"},"articleSection":["March\u00e9 automobile"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.carideal.com\/blog\/2010\/05\/27\/la-renault-fluence-concurrence-la-megane\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.carideal.com\/blog\/2010\/05\/27\/la-renault-fluence-concurrence-la-megane\/","url":"https:\/\/www.carideal.com\/blog\/2010\/05\/27\/la-renault-fluence-concurrence-la-megane\/","name":"La Renault Fluence concurrence la Megane - Blog auto Carid\u00e9al","isPartOf":{"@id":"https:\/\/www.carideal.com\/blog\/#website"},"datePublished":"2010-05-27T10:05:00+00:00","dateModified":"2016-10-16T13:50:54+00:00","breadcrumb":{"@id":"https:\/\/www.carideal.com\/blog\/2010\/05\/27\/la-renault-fluence-concurrence-la-megane\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.carideal.com\/blog\/2010\/05\/27\/la-renault-fluence-concurrence-la-megane\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.carideal.com\/blog\/2010\/05\/27\/la-renault-fluence-concurrence-la-megane\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog Carid\u00e9al","item":"https:\/\/www.carideal.com\/blog\/"},{"@type":"ListItem","position":2,"name":"March\u00e9 automobile","item":"https:\/\/www.carideal.com\/blog\/marche-automobile-voiture-neuve-occasion-4x4-suv\/"},{"@type":"ListItem","position":3,"name":"La Renault Fluence concurrence la Megane"}]},{"@type":"WebSite","@id":"https:\/\/www.carideal.com\/blog\/#website","url":"https:\/\/www.carideal.com\/blog\/","name":"Blog auto Carid\u00e9al","description":"Actualit\u00e9 auto par des passionn\u00e9s","publisher":{"@id":"https:\/\/www.carideal.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.carideal.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.carideal.com\/blog\/#organization","name":"Carideal","url":"https:\/\/www.carideal.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.carideal.com\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2016\/03\/logo-carideal-mandataire-automobile.png","contentUrl":"http:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2016\/03\/logo-carideal-mandataire-automobile.png","width":300,"height":300,"caption":"Carideal"},"image":{"@id":"https:\/\/www.carideal.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Carideal.mandataire.automobile","https:\/\/x.com\/caridealauto","https:\/\/www.instagram.com\/carideal1\/","https:\/\/www.linkedin.com\/company\/carideal.com","https:\/\/fr.pinterest.com\/schiavonsas\/","https:\/\/www.youtube.com\/user\/caridealsas"]},{"@type":"Person","@id":"https:\/\/www.carideal.com\/blog\/#\/schema\/person\/985c7e757d1042d647f21bfaf8d41ebc","name":"N.S Carideal","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.carideal.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/edb7ccdf1a4e3d14aef967760d354d0e?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/edb7ccdf1a4e3d14aef967760d354d0e?s=96&r=g","caption":"N.S Carideal"},"description":"Depuis tout petit fan d'automobile. Il est question d'essayer et de comparer toutes ces voitures qui nous ont fait r\u00e9ver, avant que celles-ci ne devient uniquement des voitures de collection.","sameAs":["http:\/\/www.carideal.com\/blog","https:\/\/www.facebook.com\/Carideal.mandataire.automobile\/","https:\/\/www.linkedin.com\/in\/nschiavon\/","https:\/\/www.youtube.com\/user\/caridealsas\/"],"url":"https:\/\/www.carideal.com\/blog\/author\/admin_carideal\/"}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"wppr-widget":false},"uagb_author_info":{"display_name":"N.S Carideal","author_link":"https:\/\/www.carideal.com\/blog\/author\/admin_carideal\/"},"uagb_comment_info":0,"uagb_excerpt":"&nbsp; La Renault Fluence concurrence la Megane La Renault Fluence n\u2019est pas une M\u00e9gane \u00e0 coffre comme son nom le revendique. C\u2019est en fait une alchimie de pi\u00e8ces rapport\u00e9es des diff\u00e9rentes marques du groupe Renault. Un bel exemple de la politique \u00e9conomique interne du groupe qui consiste \u00e0 \u00e9viter autant que possible de fabriquer de\u2026","_links":{"self":[{"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/posts\/783"}],"collection":[{"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/comments?post=783"}],"version-history":[{"count":0,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/posts\/783\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/media?parent=783"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/categories?post=783"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/tags?post=783"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}