{"id":7314,"date":"2015-11-02T10:40:59","date_gmt":"2015-11-02T09:40:59","guid":{"rendered":"http:\/\/www.carideal.com\/blog\/?p=7314"},"modified":"2018-10-04T13:11:39","modified_gmt":"2018-10-04T11:11:39","slug":"la-conduite-autonome-sur-le-periph-cest-pour-demain","status":"publish","type":"post","link":"https:\/\/www.carideal.com\/blog\/2015\/11\/02\/la-conduite-autonome-sur-le-periph-cest-pour-demain\/","title":{"rendered":"Conduite autonome sur le p\u00e9riph, c&rsquo;est pour demain"},"content":{"rendered":"<h1><strong>La conduite autonome sur\u00a0Le p\u00e9riph\u00e9rique, c'est pour demain !<\/strong><\/h1>\n<p>Sans les pieds, puis sans les mains et enfin sans les yeux... \u00c9tape par \u00e9tape, la <span style=\"text-decoration: underline;\"><a href=\"http:\/\/www.carideal.com\/blog\/2015\/09\/12\/voiture-autonome-a-partir-de-2016\/\">voiture autonome<\/a><\/span> se met au point. Bient\u00f4t, elle pourra \u00eatre l\u00e2\u00adch\u00e9e sur certaines voies de circulation. Guillaume Devauchelle, directeur de l'innovation chez Valeo, fait le point.<\/p>\n<p>O\u00f9 en est Valeo dans la mise au point de la conduite autonome\u00a0? Elle\u00a0a d\u00e9j\u00e0 d\u00e9marr\u00e9. Les aides \u00e0 la conduite \u00e9voluent vers le v\u00e9hicule autonome. D\u00e8s 2003, Valeo avait promis des manoeuvres de sta\u00adtionnement automatiques pour 2013. \u00c9tape par \u00e9tape, nous y sommes arriv\u00e9s : cr\u00e9neaux automatiques avec des dis\u00adtances larges, puis courtes, puis asso\u00adci\u00e9s \u00e0 des manoeuvres perpendiculaires, command\u00e9es depuis l'int\u00e9rieur du v\u00e9hi\u00adcule, puis de l'ext\u00e9rieur. Avec le \u00ab voitu\u00adrier automatique \u00bb, le v\u00e9hicule se gare seul et trouve lui-m\u00eame sa place. Au\u00adjourd'hui, 5 millions de v\u00e9hicules sont \u00e9quip\u00e9s de manoeuvres de stationne\u00adment automatique ou semi-automatique.<\/p>\n<h2>Les prochains \u00e9tapes de la conduite autonome<\/h2>\n<p>Quelles seront les prochaines \u00e9tapes ? Avec les r\u00e9gulateurs de vitesse, on a appris \u00e0 conduire sans les pieds. Main\u00adtenant, nous allons proposer de conduire sans les mains. Non seule\u00adment, le v\u00e9hicule va garder ses dis\u00adtances gr\u00e2ce au r\u00e9gulateur de vitesse adaptatif, mais il va suivre sa voie. L'\u00e9tape d'apr\u00e8s sera sans les yeux. En\u00adfin, ce sera sans la t\u00eate, car vous n'aurez plus \u00e0 vous occuper de la man\u0153uvre.<\/p>\n<p>Quel pourrait-\u00eatre le calendrier de cette \u00e9volution ? Sans les pieds, c'est d\u00e9j\u00e0 fait. Sans les mains, on peut d\u00e9j\u00e0 proposer le volant qui tourne tout seul, mais\u00a0qu'on peut accompagner. Enfin, dans une troisi\u00e8me \u00e9tape, on pourra le l\u00e2cher totalement. Il faudra alors adapter la r\u00e9glementation. La conduite autonome\u00a0sur le p\u00e9riph\u00e9rique, o\u00f9 il y a ni pi\u00e9ton, ni feu rouge, ni intersection, ni v\u00e9hicule venant en sens inverse, c'est pour demain.<\/p>\n<p>La\u00a0voiture autonome peut apprendre lui-m\u00eame. Qu'est-ce que cela veut dire ? C'est ce que nous appelons le machine learning. Par exemple, lorsque vous voyez un pi\u00e9ton qui pourrait traverser, vous faites un petit \u00e9cart pour garder une distance de s\u00e9curit\u00e9, qui, pourtant, n'est pas n\u00e9cessaire. En mode conduite auto\u00adnome, le v\u00e9hicule va vous imiter et faire ce l\u00e9ger d\u00e9port montrant qu'il a bien vu le pi\u00e9ton.<\/p>\n<p>Ce faisant, il vous mettra plus \u00e0 l'aise.<br \/>\n<iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/5Ms2O60yx8s\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><br \/>\nLa conduite autonome : Comment le conducteur passera-t-il les commandes au v\u00e9hicule ? Nous avons pr\u00e9sent\u00e9 un concept d'interface homme-machine, appel\u00e9 M\u00f4bius, qui g\u00e8re cette transition. Lorsque le syst\u00e8me d\u00e9tecte\u00a0les conditions favorables, lors d'un embouteillage, il propose de passer en automatique. Le conducteur n'a alors qu'a appuyer sur le bouton Auto Pilot. Il pourra alors lire ses mails ou regar\u00adder des vid\u00e9os... \u00c0 l'inverse, d\u00e8s que le syst\u00e8me anticipe la n\u00e9cessit\u00e9 pour le conducteur de reprendre la main, il l'indique par un signal visuel et sonore. Pour cela, il d\u00e9tecte, \u00e0 chaque instant, l'\u00e9tat de vigilance du conducteur, via une cam\u00e9ra int\u00e9rieure, et en tient compte.<\/p>\n<p>Quelles seront les principales techno\u00adlogies mises en oeuvre ? De multiples capteurs sont n\u00e9cessaires. Celui \u00e0 ultrasons d\u00e9termine la position pr\u00e9cise d'un objet ou d'un individu, mais il ne sait pas reconna\u00eetre la silhouette, pi\u00e9\u00adton, v\u00e9hicule, arbre... Pour cela, il faut une cam\u00e9ra. Un scanner Lidar indique si cet objet se d\u00e9place. Une cam\u00e9ra \u00e0 infrarouge, qui mesure la temp\u00e9ra\u00adture, pr\u00e9cise si c'est une personne. Un autre type de cam\u00e9ra d\u00e9tecte le regard du pi\u00e9ton, m\u00eame s'il porte des lunettes de soleil, qui montre l'endroit o\u00f9 il va.<\/p>\n<p>Comment acqu\u00e9rez-vous ce savoir-faire ? Plus de dix mille ing\u00e9nieurs travaillent en interne et nous acqu\u00e9\u00adrons aussi des technologies de l'ext\u00e9\u00adrieur. Nous avons ainsi des accords avec Safran, pour les cam\u00e9ras sophistiqu\u00e9es, Mobileye, pour les cam\u00e9ras frontales, scanner et laser, Peiker, pour la connectivit\u00e9, Ibeo, pour le scanner Lidar, et avec des universit\u00e9s du monde entier. Un bureau d'\u00e9tudes bas\u00e9 en Californie d\u00e9tecte les start-up dont la technologie nous int\u00e9resse. Valeo a ainsi pris 10 % d'Aledia, une soci\u00e9t\u00e9 qui fabrique des leds. Enfin, nous achetons des entreprises, comme Connaught Electronics en Irlande, sp\u00e9\u00adcialis\u00e9e dans l'agrafage d'images, qui permet de cr\u00e9er une vue d'oiseau du v\u00e9hicule. C'est une technologie n\u00e9ces\u00adsaire pour le parking automatique.<\/p>\n<p>Dans quelle mesure la maintenance pr\u00e9dictive va-t-elle changer l'univers de l'apr\u00e8s-vente ? La vision manich\u00e9enne entre premi\u00e8re monte et apr\u00e8s-vente est en train de dispara\u00eetre, car beau\u00adcoup d'\u00e9l\u00e9ments vont se t\u00e9l\u00e9charger. <a href=\"http:\/\/www.carideal.com\/blog\/marque-de-voiture-actualites-essais\/tesla\/\">Tesla<\/a> a fait il y a quelques semaines plusieurs communiqu\u00e9s majeurs de soft destin\u00e9s \u00e0 des v\u00e9hicules d\u00e9j\u00e0 sur la route. II a con\u00e7u une ergonomie qui \u00e9volue dans le temps. La maintenance pr\u00e9dictive ne se fera pas tous les six mois, mais en fonction de votre fa\u00e7on de conduire. D'autre part, les rappels seront mieux cibl\u00e9s.<\/p>\n<p>Avec la conduite autonome, la part des \u00e9quipementiers dans la valeur ajou\u00adt\u00e9e d'une automobile ne va-t-elle pas encore augmenter? Depuis les vingt derni\u00e8res ann\u00e9es, elle n'a pas cess\u00e9 de cro\u00eetre. Aujourd'hui, elle est \u00e0 plus de 70 % et pour certains v\u00e9hicules, elle est encore plus importante. L'\u00e9quipemen\u00adtier peut ainsi mieux amortir les co\u00fbts\u00a0de fabrication.<\/p>\n<p>Valeo fabrique 500 000 capteurs \u00e0 ultrasons par jour, soit plus de 100 millions par an. Aucun constructeur n'est capable d'en consommer une telle quantit\u00e9. Notre objectif, c'est que, gr\u00e2ce au volume, notre technologie soit accessible au plus grand nombre.<br \/>\n<strong>La vision manich\u00e9enne entre premi\u00e8re monte\u00a0et apr\u00e8s-vente est\u00a0en train de dispara\u00eetre,<\/strong><br \/>\n<strong>car beaucoup d'\u00e9l\u00e9ments vont se t\u00e9l\u00e9charger.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La conduite autonome sur\u00a0Le p\u00e9riph\u00e9rique, c&rsquo;est pour demain ! Sans les pieds, puis sans les mains et enfin sans les yeux&#8230; \u00c9tape par \u00e9tape, la voiture autonome se met au point. Bient\u00f4t, elle pourra \u00eatre l\u00e2\u00adch\u00e9e sur certaines voies de circulation. Guillaume Devauchelle, directeur de l&rsquo;innovation chez Valeo, fait le point. O\u00f9 en est Valeo &#8230; <a title=\"Conduite autonome sur le p\u00e9riph, c&rsquo;est pour demain\" class=\"read-more\" href=\"https:\/\/www.carideal.com\/blog\/2015\/11\/02\/la-conduite-autonome-sur-le-periph-cest-pour-demain\/\" aria-label=\"En savoir plus sur Conduite autonome sur le p\u00e9riph, c&rsquo;est pour demain\">Lire plus<\/a><\/p>\n","protected":false},"author":3,"featured_media":7317,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[21,6041,6042],"tags":[5891],"class_list":["post-7314","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites-auto","category-nouvelles-technologies","category-voiture-autonome","tag-aide-a-la-conduite"],"wppr_data":{"cwp_meta_box_check":"No"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Conduite autonome sur le p\u00e9riph, c&#039;est pour demain - Blog auto Carid\u00e9al<\/title>\n<meta name=\"description\" content=\"Conduite autonome c&#039;est pour demain, sans les pieds sans les mains et bient\u00f4t sans les yeux, Valeo y travaile d&#039;arrache pied.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.carideal.com\/blog\/2015\/11\/02\/la-conduite-autonome-sur-le-periph-cest-pour-demain\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conduite autonome sur le p\u00e9riph, c&#039;est pour demain - Blog auto Carid\u00e9al\" \/>\n<meta property=\"og:description\" content=\"Conduite autonome c&#039;est pour demain, sans les pieds sans les mains et bient\u00f4t sans les yeux, Valeo y travaile d&#039;arrache pied.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.carideal.com\/blog\/2015\/11\/02\/la-conduite-autonome-sur-le-periph-cest-pour-demain\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog auto Carid\u00e9al\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Carideal.mandataire.automobile\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/nicolas.schiavon.39\" \/>\n<meta property=\"article:published_time\" content=\"2015-11-02T09:40:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-10-04T11:11:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2015\/11\/valeo-voiture-autonome-carideal-blog-automobile.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nicolas SCHIAVON\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@caridealauto\" \/>\n<meta name=\"twitter:site\" content=\"@caridealauto\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nicolas SCHIAVON\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.carideal.com\/blog\/2015\/11\/02\/la-conduite-autonome-sur-le-periph-cest-pour-demain\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/2015\/11\/02\/la-conduite-autonome-sur-le-periph-cest-pour-demain\/\"},\"author\":{\"name\":\"Nicolas SCHIAVON\",\"@id\":\"https:\/\/www.carideal.com\/blog\/#\/schema\/person\/cd95dc7919660de90d31b366f85be1ec\"},\"headline\":\"Conduite autonome sur le p\u00e9riph, c&rsquo;est pour demain\",\"datePublished\":\"2015-11-02T09:40:59+00:00\",\"dateModified\":\"2018-10-04T11:11:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/2015\/11\/02\/la-conduite-autonome-sur-le-periph-cest-pour-demain\/\"},\"wordCount\":1008,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/2015\/11\/02\/la-conduite-autonome-sur-le-periph-cest-pour-demain\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2015\/11\/valeo-voiture-autonome-carideal-blog-automobile.jpg\",\"keywords\":[\"Aide \u00e0 la conduite\"],\"articleSection\":[\"Actualit\u00e9 automobile\",\"Nouvelles Technologies automobile\",\"Voiture autonome\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.carideal.com\/blog\/2015\/11\/02\/la-conduite-autonome-sur-le-periph-cest-pour-demain\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.carideal.com\/blog\/2015\/11\/02\/la-conduite-autonome-sur-le-periph-cest-pour-demain\/\",\"url\":\"https:\/\/www.carideal.com\/blog\/2015\/11\/02\/la-conduite-autonome-sur-le-periph-cest-pour-demain\/\",\"name\":\"Conduite autonome sur le p\u00e9riph, c'est pour demain - Blog auto Carid\u00e9al\",\"isPartOf\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/2015\/11\/02\/la-conduite-autonome-sur-le-periph-cest-pour-demain\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/2015\/11\/02\/la-conduite-autonome-sur-le-periph-cest-pour-demain\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2015\/11\/valeo-voiture-autonome-carideal-blog-automobile.jpg\",\"datePublished\":\"2015-11-02T09:40:59+00:00\",\"dateModified\":\"2018-10-04T11:11:39+00:00\",\"description\":\"Conduite autonome c'est pour demain, sans les pieds sans les mains et bient\u00f4t sans les yeux, Valeo y travaile d'arrache pied.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/2015\/11\/02\/la-conduite-autonome-sur-le-periph-cest-pour-demain\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.carideal.com\/blog\/2015\/11\/02\/la-conduite-autonome-sur-le-periph-cest-pour-demain\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.carideal.com\/blog\/2015\/11\/02\/la-conduite-autonome-sur-le-periph-cest-pour-demain\/#primaryimage\",\"url\":\"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2015\/11\/valeo-voiture-autonome-carideal-blog-automobile.jpg\",\"contentUrl\":\"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2015\/11\/valeo-voiture-autonome-carideal-blog-automobile.jpg\",\"width\":800,\"height\":533,\"caption\":\"La voiture autonome de Valeo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.carideal.com\/blog\/2015\/11\/02\/la-conduite-autonome-sur-le-periph-cest-pour-demain\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog Carid\u00e9al\",\"item\":\"https:\/\/www.carideal.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Technologie Automobile\",\"item\":\"https:\/\/www.carideal.com\/blog\/technologie-2\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Voiture autonome\",\"item\":\"https:\/\/www.carideal.com\/blog\/technologie-2\/voiture-autonome\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Conduite autonome sur le p\u00e9riph, c&rsquo;est pour demain\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.carideal.com\/blog\/#website\",\"url\":\"https:\/\/www.carideal.com\/blog\/\",\"name\":\"Blog auto Carid\u00e9al\",\"description\":\"Actualit\u00e9 auto par des passionn\u00e9s\",\"publisher\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.carideal.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.carideal.com\/blog\/#organization\",\"name\":\"Carideal\",\"url\":\"https:\/\/www.carideal.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.carideal.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2016\/03\/logo-carideal-mandataire-automobile.png\",\"contentUrl\":\"http:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2016\/03\/logo-carideal-mandataire-automobile.png\",\"width\":300,\"height\":300,\"caption\":\"Carideal\"},\"image\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Carideal.mandataire.automobile\",\"https:\/\/x.com\/caridealauto\",\"https:\/\/www.instagram.com\/carideal1\/\",\"https:\/\/www.linkedin.com\/company\/carideal.com\",\"https:\/\/fr.pinterest.com\/schiavonsas\/\",\"https:\/\/www.youtube.com\/user\/caridealsas\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.carideal.com\/blog\/#\/schema\/person\/cd95dc7919660de90d31b366f85be1ec\",\"name\":\"Nicolas SCHIAVON\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.carideal.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c17e55009e671d92cc7f5dc837dc418a?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c17e55009e671d92cc7f5dc837dc418a?s=96&r=g\",\"caption\":\"Nicolas SCHIAVON\"},\"description\":\"Nicolas Schiavon est tomb\u00e9 tout petit dans la marmite automobile. Ayant eu un garage de marque automobile, mandataire automobile de la premi\u00e8re heure d\u00e8s 1999. Nicolas a cr\u00e9\u00e9 ces premiers sites de vente de voiture et blog automobile d\u00e8s 1994. Carideal est n\u00e9 le 15 d\u00e9cembre 2000 de la volont\u00e9 de vendre des voitures d'occasions en ligne puis des voitures neuves. Il a pu essayer beaucoup de voitures tr\u00e8s diff\u00e9rentes et ayant eu personnellement quelques belles autos, Subaru Impreza, Mitsubishi Lancer Evo 7, Porsche 911, Ferrari Testarrossa, Audi RS3, RS4 et j'en passe...\",\"sameAs\":[\"http:\/\/www.carideal.com\",\"https:\/\/www.facebook.com\/nicolas.schiavon.39\",\"https:\/\/www.instagram.com\/carideal1\/\",\"https:\/\/www.linkedin.com\/in\/nschiavon\/\",\"https:\/\/x.com\/caridealauto\",\"https:\/\/www.youtube.com\/user\/caridealsas\/\"],\"url\":\"https:\/\/www.carideal.com\/blog\/author\/nschiavon\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conduite autonome sur le p\u00e9riph, c'est pour demain - Blog auto Carid\u00e9al","description":"Conduite autonome c'est pour demain, sans les pieds sans les mains et bient\u00f4t sans les yeux, Valeo y travaile d'arrache pied.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.carideal.com\/blog\/2015\/11\/02\/la-conduite-autonome-sur-le-periph-cest-pour-demain\/","og_locale":"fr_FR","og_type":"article","og_title":"Conduite autonome sur le p\u00e9riph, c'est pour demain - Blog auto Carid\u00e9al","og_description":"Conduite autonome c'est pour demain, sans les pieds sans les mains et bient\u00f4t sans les yeux, Valeo y travaile d'arrache pied.","og_url":"https:\/\/www.carideal.com\/blog\/2015\/11\/02\/la-conduite-autonome-sur-le-periph-cest-pour-demain\/","og_site_name":"Blog auto Carid\u00e9al","article_publisher":"https:\/\/www.facebook.com\/Carideal.mandataire.automobile","article_author":"https:\/\/www.facebook.com\/nicolas.schiavon.39","article_published_time":"2015-11-02T09:40:59+00:00","article_modified_time":"2018-10-04T11:11:39+00:00","og_image":[{"width":800,"height":533,"url":"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2015\/11\/valeo-voiture-autonome-carideal-blog-automobile.jpg","type":"image\/jpeg"}],"author":"Nicolas SCHIAVON","twitter_card":"summary_large_image","twitter_creator":"@caridealauto","twitter_site":"@caridealauto","twitter_misc":{"\u00c9crit par":"Nicolas SCHIAVON","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.carideal.com\/blog\/2015\/11\/02\/la-conduite-autonome-sur-le-periph-cest-pour-demain\/#article","isPartOf":{"@id":"https:\/\/www.carideal.com\/blog\/2015\/11\/02\/la-conduite-autonome-sur-le-periph-cest-pour-demain\/"},"author":{"name":"Nicolas SCHIAVON","@id":"https:\/\/www.carideal.com\/blog\/#\/schema\/person\/cd95dc7919660de90d31b366f85be1ec"},"headline":"Conduite autonome sur le p\u00e9riph, c&rsquo;est pour demain","datePublished":"2015-11-02T09:40:59+00:00","dateModified":"2018-10-04T11:11:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.carideal.com\/blog\/2015\/11\/02\/la-conduite-autonome-sur-le-periph-cest-pour-demain\/"},"wordCount":1008,"commentCount":0,"publisher":{"@id":"https:\/\/www.carideal.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.carideal.com\/blog\/2015\/11\/02\/la-conduite-autonome-sur-le-periph-cest-pour-demain\/#primaryimage"},"thumbnailUrl":"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2015\/11\/valeo-voiture-autonome-carideal-blog-automobile.jpg","keywords":["Aide \u00e0 la conduite"],"articleSection":["Actualit\u00e9 automobile","Nouvelles Technologies automobile","Voiture autonome"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.carideal.com\/blog\/2015\/11\/02\/la-conduite-autonome-sur-le-periph-cest-pour-demain\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.carideal.com\/blog\/2015\/11\/02\/la-conduite-autonome-sur-le-periph-cest-pour-demain\/","url":"https:\/\/www.carideal.com\/blog\/2015\/11\/02\/la-conduite-autonome-sur-le-periph-cest-pour-demain\/","name":"Conduite autonome sur le p\u00e9riph, c'est pour demain - Blog auto Carid\u00e9al","isPartOf":{"@id":"https:\/\/www.carideal.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.carideal.com\/blog\/2015\/11\/02\/la-conduite-autonome-sur-le-periph-cest-pour-demain\/#primaryimage"},"image":{"@id":"https:\/\/www.carideal.com\/blog\/2015\/11\/02\/la-conduite-autonome-sur-le-periph-cest-pour-demain\/#primaryimage"},"thumbnailUrl":"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2015\/11\/valeo-voiture-autonome-carideal-blog-automobile.jpg","datePublished":"2015-11-02T09:40:59+00:00","dateModified":"2018-10-04T11:11:39+00:00","description":"Conduite autonome c'est pour demain, sans les pieds sans les mains et bient\u00f4t sans les yeux, Valeo y travaile d'arrache pied.","breadcrumb":{"@id":"https:\/\/www.carideal.com\/blog\/2015\/11\/02\/la-conduite-autonome-sur-le-periph-cest-pour-demain\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.carideal.com\/blog\/2015\/11\/02\/la-conduite-autonome-sur-le-periph-cest-pour-demain\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.carideal.com\/blog\/2015\/11\/02\/la-conduite-autonome-sur-le-periph-cest-pour-demain\/#primaryimage","url":"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2015\/11\/valeo-voiture-autonome-carideal-blog-automobile.jpg","contentUrl":"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2015\/11\/valeo-voiture-autonome-carideal-blog-automobile.jpg","width":800,"height":533,"caption":"La voiture autonome de Valeo"},{"@type":"BreadcrumbList","@id":"https:\/\/www.carideal.com\/blog\/2015\/11\/02\/la-conduite-autonome-sur-le-periph-cest-pour-demain\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog Carid\u00e9al","item":"https:\/\/www.carideal.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Technologie Automobile","item":"https:\/\/www.carideal.com\/blog\/technologie-2\/"},{"@type":"ListItem","position":3,"name":"Voiture autonome","item":"https:\/\/www.carideal.com\/blog\/technologie-2\/voiture-autonome\/"},{"@type":"ListItem","position":4,"name":"Conduite autonome sur le p\u00e9riph, c&rsquo;est pour demain"}]},{"@type":"WebSite","@id":"https:\/\/www.carideal.com\/blog\/#website","url":"https:\/\/www.carideal.com\/blog\/","name":"Blog auto Carid\u00e9al","description":"Actualit\u00e9 auto par des passionn\u00e9s","publisher":{"@id":"https:\/\/www.carideal.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.carideal.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.carideal.com\/blog\/#organization","name":"Carideal","url":"https:\/\/www.carideal.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.carideal.com\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2016\/03\/logo-carideal-mandataire-automobile.png","contentUrl":"http:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2016\/03\/logo-carideal-mandataire-automobile.png","width":300,"height":300,"caption":"Carideal"},"image":{"@id":"https:\/\/www.carideal.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Carideal.mandataire.automobile","https:\/\/x.com\/caridealauto","https:\/\/www.instagram.com\/carideal1\/","https:\/\/www.linkedin.com\/company\/carideal.com","https:\/\/fr.pinterest.com\/schiavonsas\/","https:\/\/www.youtube.com\/user\/caridealsas"]},{"@type":"Person","@id":"https:\/\/www.carideal.com\/blog\/#\/schema\/person\/cd95dc7919660de90d31b366f85be1ec","name":"Nicolas SCHIAVON","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.carideal.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c17e55009e671d92cc7f5dc837dc418a?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c17e55009e671d92cc7f5dc837dc418a?s=96&r=g","caption":"Nicolas SCHIAVON"},"description":"Nicolas Schiavon est tomb\u00e9 tout petit dans la marmite automobile. Ayant eu un garage de marque automobile, mandataire automobile de la premi\u00e8re heure d\u00e8s 1999. Nicolas a cr\u00e9\u00e9 ces premiers sites de vente de voiture et blog automobile d\u00e8s 1994. Carideal est n\u00e9 le 15 d\u00e9cembre 2000 de la volont\u00e9 de vendre des voitures d'occasions en ligne puis des voitures neuves. Il a pu essayer beaucoup de voitures tr\u00e8s diff\u00e9rentes et ayant eu personnellement quelques belles autos, Subaru Impreza, Mitsubishi Lancer Evo 7, Porsche 911, Ferrari Testarrossa, Audi RS3, RS4 et j'en passe...","sameAs":["http:\/\/www.carideal.com","https:\/\/www.facebook.com\/nicolas.schiavon.39","https:\/\/www.instagram.com\/carideal1\/","https:\/\/www.linkedin.com\/in\/nschiavon\/","https:\/\/x.com\/caridealauto","https:\/\/www.youtube.com\/user\/caridealsas\/"],"url":"https:\/\/www.carideal.com\/blog\/author\/nschiavon\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2015\/11\/valeo-voiture-autonome-carideal-blog-automobile.jpg",800,533,false],"thumbnail":["https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2015\/11\/valeo-voiture-autonome-carideal-blog-automobile-150x150.jpg",150,150,true],"medium":["https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2015\/11\/valeo-voiture-autonome-carideal-blog-automobile-300x200.jpg",300,200,true],"medium_large":["https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2015\/11\/valeo-voiture-autonome-carideal-blog-automobile.jpg",768,512,false],"large":["https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2015\/11\/valeo-voiture-autonome-carideal-blog-automobile.jpg",800,533,false],"1536x1536":["https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2015\/11\/valeo-voiture-autonome-carideal-blog-automobile.jpg",800,533,false],"2048x2048":["https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2015\/11\/valeo-voiture-autonome-carideal-blog-automobile.jpg",800,533,false],"wppr-widget":["https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2015\/11\/valeo-voiture-autonome-carideal-blog-automobile.jpg",50,33,false]},"uagb_author_info":{"display_name":"Nicolas SCHIAVON","author_link":"https:\/\/www.carideal.com\/blog\/author\/nschiavon\/"},"uagb_comment_info":0,"uagb_excerpt":"La conduite autonome sur\u00a0Le p\u00e9riph\u00e9rique, c'est pour demain ! Sans les pieds, puis sans les mains et enfin sans les yeux... \u00c9tape par \u00e9tape, la voiture autonome se met au point. Bient\u00f4t, elle pourra \u00eatre l\u00e2\u00adch\u00e9e sur certaines voies de circulation. Guillaume Devauchelle, directeur de l'innovation chez Valeo, fait le point. O\u00f9 en est Valeo\u2026","_links":{"self":[{"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/posts\/7314"}],"collection":[{"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/comments?post=7314"}],"version-history":[{"count":0,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/posts\/7314\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/media\/7317"}],"wp:attachment":[{"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/media?parent=7314"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/categories?post=7314"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/tags?post=7314"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}