{"id":5112,"date":"2013-01-30T23:00:00","date_gmt":"2013-01-30T23:00:00","guid":{"rendered":"http:\/\/www.carideal.com\/blog\/2013\/01\/30\/declaration-ratan-tata-p-dg-du-groupe-tata\/"},"modified":"2019-12-04T10:02:45","modified_gmt":"2019-12-04T09:02:45","slug":"declaration-ratan-tata-p-dg-du-groupe-tata","status":"publish","type":"post","link":"https:\/\/www.carideal.com\/blog\/2013\/01\/30\/declaration-ratan-tata-p-dg-du-groupe-tata\/","title":{"rendered":"Ratan Tata PDG du groupe Tata la Chine est le plus gros march\u00e9 pour JLR"},"content":{"rendered":"<div>\n<h2>Ratan Tata PDG du groupe Tata la Chine est le plus gros march\u00e9 pour JLR<\/h2>\n<\/div>\n<blockquote><p>Ratan Tata \"Aujourd'hui, la Chine est le plus gros march\u00e9 pour Jaguar-Land Rover. Bien plus que les Etats-Unis, l'Europe et l'Angleterre...\"<\/p><\/blockquote>\n<p><strong>En 2010-11, JLR a r\u00e9alis\u00e9 autant de b\u00e9n\u00e9fices - 1,1 milliard de livres sterling que l'achat de Tata trois ans plus t\u00f4t, et environ 400 millions de livres sterling de plus au cours de l'exercice \u00e9coul\u00e9.<\/strong><\/p>\n<figure id=\"attachment_20346\" aria-describedby=\"caption-attachment-20346\" style=\"width: 470px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-20346\" src=\"http:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2013\/01\/ratantata-1359621344.jpg\" alt=\"Ratan Tata PDG du groupe Tata la Chine est le plus gros march\u00e9 pour JLR\" width=\"480\" height=\"335\" srcset=\"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2013\/01\/ratantata-1359621344.jpg 480w, https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2013\/01\/ratantata-1359621344-300x209.jpg 300w, https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2013\/01\/ratantata-1359621344-50x35.jpg 50w, https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2013\/01\/ratantata-1359621344-110x77.jpg 110w, https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2013\/01\/ratantata-1359621344-420x293.jpg 420w\" sizes=\"(max-width: 480px) 100vw, 480px\" \/><figcaption id=\"caption-attachment-20346\" class=\"wp-caption-text\">Ratan Tata PDG du groupe Tata la Chine est le plus gros march\u00e9 pour JLR<\/figcaption><\/figure>\n<h3>Les routes chinoises ne conviennent pas aux supercars fragiles.<\/h3>\n<p><a href=\"http:\/\/www.carideal.com\/blog\/marque-de-voiture-actualites-essais\/ferrari\/\">Ferrari<\/a> y a peut-\u00eatre vu ses ventes bondir gr\u00e2ce aux torrents d'argent liquide provenant des coffres des 1<a href=\"https:\/\/www.latribune.fr\/actualites\/economie\/international\/20110601trib000626185\/la-chine-compte-cinq-fois-plus-de-millionnaires-que-la-france.html\">,4 million de millionnaires<\/a> du pays, mais ce sont les marques britanniques qui tirent le plus grand profit de leurs d\u00e9penses.<\/p>\n<p>Les acheteurs chinois, dont beaucoup sont propri\u00e9taires d'usines qui ont fait fortune en exportant des biens de consommation vers l'Occident, pr\u00e9f\u00e8rent le cachet et le confort des grandes berlines de luxe britanniques au sang bleu, dont presque toutes seront conduites par un chauffeur dans les rues bouch\u00e9es du pays.<\/p>\n<p>Plus t\u00f4t cette ann\u00e9e, <a href=\"http:\/\/www.carideal.com\/blog\/marque-de-voiture-actualites-essais\/rolls-royce\/\">Rolls-Royce<\/a> a annonc\u00e9 que la Chine \u00e9tait devenue son plus grand march\u00e9, devan\u00e7ant les \u00c9tats-Unis et le Royaume-Uni pour la premi\u00e8re fois en plus d'un si\u00e8cle de commerce, tandis que les ventes de <a href=\"http:\/\/www.carideal.com\/blog\/marque-de-voiture-actualites-essais\/bentley\/\">Bentley<\/a> en Chine et aux \u00c9tats-Unis sont maintenant \u00e9gales.<\/p>\n<ul>\n<li><a href=\"http:\/\/www.carideal.com\/blog\/2014\/01\/12\/les-constructeurs-automobile-qui-vendent-le-plus-en-chine\/\">Les constructeurs qui vendent le plus en Chine<\/a><\/li>\n<\/ul>\n<p>Mais chacune de ces marques ne construit que quelques milliers de voitures par an ; les chiffres du groupe Jaguar-Land Rover sont beaucoup plus importants.<\/p>\n<p>Au cours de la derni\u00e8re ann\u00e9e, la demande de SUV de luxe comme le <a href=\"http:\/\/www.carideal.com\/blog\/2013\/01\/10\/land-rover-range-rover-44-de-luxe\/\">Range Rover<\/a>, dont la nouvelle g\u00e9n\u00e9ration a \u00e9t\u00e9 lanc\u00e9e le 15 ao\u00fbt dernier, a connu un essor consid\u00e9rable. Il est plus luxueux, avec deux si\u00e8ges arri\u00e8re en forme de tr\u00f4ne \u00e0 l'arri\u00e8re et, pour la premi\u00e8re fois, un mod\u00e8le \" stretch \" - tout pour satisfaire les go\u00fbts chinois.<\/p>\n<p>En 2003, JLR n'a vendu que 431 voitures en Chine. Au cours du dernier exercice, elle en a vendu 51 000, soit 76 % de plus que l'ann\u00e9e pr\u00e9c\u00e9dente, et d'ici la fin de l'ann\u00e9e, la Chine devrait d\u00e9passer les \u00c9tats-Unis comme premier march\u00e9 de l'entreprise.<\/p>\n<figure id=\"attachment_20345\" aria-describedby=\"caption-attachment-20345\" style=\"width: 256px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-20345\" src=\"http:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2013\/01\/vente-JLR-2013-2018.jpg\" alt=\"vente JLR 2013 2018\" width=\"266\" height=\"189\" srcset=\"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2013\/01\/vente-JLR-2013-2018.jpg 266w, https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2013\/01\/vente-JLR-2013-2018-50x36.jpg 50w, https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2013\/01\/vente-JLR-2013-2018-110x78.jpg 110w\" sizes=\"(max-width: 266px) 100vw, 266px\" \/><figcaption id=\"caption-attachment-20345\" class=\"wp-caption-text\">vente JLR 2013 2018<\/figcaption><\/figure>\n<p>Cela vient d'une entreprise qui a flirt\u00e9 avec la faillite et qui a suppli\u00e9 le gouvernement de la renflouer il y a \u00e0 peine trois ans - avant d'entamer l'une des plus \u00e9tonnantes reprises que l'industrie automobile ait jamais connues.<\/p>\n<p>Ces deux marques britanniques v\u00e9ritablement embl\u00e9matiques ne sont r\u00e9unies que depuis peu, et <a href=\"http:\/\/www.carideal.com\/blog\/marque-de-voiture-actualites-essais\/land-rover\/\">Land Rover<\/a> est confortablement le principal partenaire en termes de ventes et de profits.<\/p>\n<p><a href=\"http:\/\/www.carideal.com\/blog\/marque-de-voiture-actualites-essais\/jaguar\/\">Jaguar<\/a> a \u00e9t\u00e9 fond\u00e9e sous le nom de Swallow Sidecar Company il y a 90 ans par Sir William Lyons et son premier apog\u00e9e remonte aux ann\u00e9es 50 et 60, lorsque ses pilotes de type C et D ont \u00e9t\u00e9 d\u00e9fendus par des h\u00e9ros tels que Stirling Moss et Mike Hawthorne.<\/p>\n<p>Sur la route, la berline E-Type et la berline XJ \u00e9tablissent de nouvelles normes en mati\u00e8re d'agr\u00e9ment de conduite.<\/p>\n<p>Mais l'entreprise a \u00e9t\u00e9 aval\u00e9e par British Leyland \u00e0 la fin des ann\u00e9es 60 et nationalis\u00e9e par la suite, souffrant de la m\u00eame mauvaise qualit\u00e9 et du manque d'investissement qui ont tu\u00e9 de nombreuses anciennes marques britanniques.<br \/>\nPrivatis\u00e9e par Margaret Thatcher en 1984, elle a \u00e9t\u00e9 rachet\u00e9e par <a href=\"http:\/\/www.carideal.com\/blog\/marque-de-voiture-actualites-essais\/ford\/\">Ford<\/a> en 1989.<\/p>\n<p>Les Am\u00e9ricains se sont montr\u00e9s g\u00e9n\u00e9reux, mais des parents insistants et ing\u00e9nieux.<\/p>\n<p>Souhaitant que Jaguar soit leur rival pour les marques <a href=\"http:\/\/www.carideal.com\/blog\/marque-de-voiture-actualites-essais\/bmw\/\">BMW<\/a> et <a href=\"http:\/\/www.carideal.com\/blog\/marque-de-voiture-actualites-essais\/audi\/\">Audi<\/a> en pleine croissance, ils ont cr\u00e9\u00e9 la <a href=\"http:\/\/www.carideal.com\/blog\/2012\/06\/15\/la-jaguar-x-type\/\">Jaguar X-Type<\/a>, plus petite et moins ch\u00e8re, en s'appuyant sur une <a href=\"http:\/\/www.carideal.com\/blog\/2015\/03\/11\/ford-mondeo-le-beau-retour\/\">Ford Mondeo<\/a>.<\/p>\n<p>La voiture n'a pas \u00e9t\u00e9 bien accueillie, le plan de croissance a \u00e9chou\u00e9 et elle a \u00e9t\u00e9 supprim\u00e9e sans \u00eatre remplac\u00e9e en 2009. Jaguar a saign\u00e9 de l'argent pour presque toutes les deux d\u00e9cennies de propri\u00e9t\u00e9 de Ford.<\/p>\n<p>Le premier des deux principaux points de crise r\u00e9cents de Jaguar est survenu \u00e0 l'automne 2007.<\/p>\n<p>Ford, frapp\u00e9e par la chute des ventes sur son march\u00e9 int\u00e9rieur et d\u00e9sesp\u00e9r\u00e9e d'\u00e9viter la faillite qui allait plus tard engloutir ses rivaux de Detroit, <a href=\"http:\/\/www.carideal.com\/blog\/2011\/05\/11\/investissement-collaussaux-de-general-motors-aux-etats-unis\/\">General Motors<\/a> et <a href=\"http:\/\/www.carideal.com\/blog\/2010\/06\/08\/des-chrysler-badgees-lancia-en-europe\/\">Chrysler<\/a>, a vendu presque tous ses actifs \u00e9trangers.<\/p>\n<p>Volvo a \u00e9t\u00e9 vendue au constructeur automobile chinois Geely et <a href=\"http:\/\/www.carideal.com\/blog\/marque-de-voiture-actualites-essais\/aston-martin\/\">Aston Martin<\/a> \u00e0 un consortium priv\u00e9. Jaguar a \u00e9t\u00e9 propos\u00e9 \u00e0 la vente avec Land Rover, que Ford avait achet\u00e9 de BMW en 2000.<\/p>\n<figure id=\"attachment_20347\" aria-describedby=\"caption-attachment-20347\" style=\"width: 390px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-20347\" src=\"http:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2013\/01\/salon-chine-jlr-e1575448069717.jpg\" alt=\"La foule sur le stand de JLR sur le salon en Chine 2012\" width=\"400\" height=\"259\" \/><figcaption id=\"caption-attachment-20347\" class=\"wp-caption-text\">La foule sur le stand de JLR sur le salon en Chine 2012<\/figcaption><\/figure>\n<p>Ford a fait des erreurs, mais vers la fin, il a finalement r\u00e9ussi \u00e0 faire les choses correctement \", d\u00e9clare le professeur David Bailey, expert de l'industrie automobile \u00e0 l'Universit\u00e9 de Coventry.<\/p>\n<p>Jaguar commen\u00e7ait \u00e0 peine \u00e0 faire des b\u00e9n\u00e9fices. Mais Ford n'avait plus d'argent, et il voulait en sortir.<\/p>\n<p>Il y avait d'excellents produits dans le pipeline, le r\u00e9sultat d'un investissement lourd de la part de Ford. Quelqu'un allait le ramasser \u00e0 bon march\u00e9.<\/p>\n<p>La faillite de la banque Lehman Brothers en 2008 n'avait pas encore frapp\u00e9, mais le seul int\u00e9r\u00eat s\u00e9rieux venait de cinq soci\u00e9t\u00e9s de capital-investissement et des constructeurs automobiles indiens Tata et Mahindra.<\/p>\n<p>Au d\u00e9but, les soci\u00e9t\u00e9s de capital-investissement \u00e9taient l'option pr\u00e9f\u00e9r\u00e9e de Ford \", indique une source.<\/p>\n<p>Ford \u00e9tait sceptique quant \u00e0 ce que Tata pouvait apporter \u00e0 l'accord. Mais les firmes de PE ont commenc\u00e9 \u00e0 se demander si JLR pouvait survivre en dehors d'un grand groupe automobile, et se permettre de d\u00e9velopper de nouveaux mod\u00e8les et des groupes motopropulseurs hybrides et de faire face aux nouvelles exigences gouvernementales, s\u00e9v\u00e8res et co\u00fbteuses, en mati\u00e8re de s\u00e9curit\u00e9 et d'\u00e9missions\".<\/p>\n<p>Les Indiens \u00e9taient donc les seuls soumissionnaires s\u00e9rieux qui restaient. Si Tata n'avait pas \u00e9t\u00e9 en mesure de conclure l'accord, finalement sign\u00e9 en juin 2008, les cons\u00e9quences auraient pu \u00eatre d\u00e9sastreuses.<\/p>\n<p>Si JLR avait encore \u00e9t\u00e9 en vente lorsque la crise financi\u00e8re a frapp\u00e9 quelques mois plus tard, avec des pertes en spirale et personne n'ayant les liquidit\u00e9s pour l'acheter, Ford l'aurait peut-\u00eatre simplement ferm\u00e9.<\/p>\n<p>S'il semble difficile d'imaginer qu'un ancien nom aussi c\u00e9l\u00e8bre avec 15 000 employ\u00e9s directs au Royaume-Uni disparaisse tout simplement, souvenez-vous que la r\u00e9cession a tu\u00e9 <a href=\"http:\/\/www.carideal.com\/blog\/2013\/11\/09\/saab-reviendra-t-il\/\">Saab<\/a>, qui a fabriqu\u00e9 en 2007 plus de deux fois plus de voitures que Jaguar.<\/p>\n<p>L'ensemble de l'accord Tata \u00e9tait incroyablement romantique \", d\u00e9clare Max Warburton, le principal analyste automobile mondial.<\/p>\n<p>Je ne pense pas qu'il y ait beaucoup de gens \u00e0 l'int\u00e9rieur de Tata qui comprennent pourquoi ils ont achet\u00e9 JLR.<\/p>\n<p>La d\u00e9cision est venue du sommet absolu de l'entreprise et d'un gars qui adorait l'histoire de ces marques britanniques.<\/p>\n<p>Il n'y a pas de synergie op\u00e9rationnelle entre Tata et JLR, et presque pas de coop\u00e9ration technique entre elles.<\/p>\n<p>\"Seul un romantique pourrait \u00eatre convaincu que Jaguar peut gagner de l'argent apr\u00e8s une si longue histoire de perte.<\/p>\n<figure id=\"attachment_20348\" aria-describedby=\"caption-attachment-20348\" style=\"width: 390px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-20348\" src=\"http:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2013\/01\/JLR-Guangzhou-e1575448284375.jpg\" alt=\"JLR \u00e0 Guangzhou\" width=\"400\" height=\"341\" \/><figcaption id=\"caption-attachment-20348\" class=\"wp-caption-text\">JLR \u00e0 Guangzhou<\/figcaption><\/figure>\n<p>Le romantique \u00e9tait Ratan Tata, alors \u00e2g\u00e9 de 70 ans, pr\u00e9sident de l'extraordinaire et incroyablement diversifi\u00e9e entreprise familiale de 150 ans qui emploie 420 000 personnes et qui couvre tout, du th\u00e9 \u00e0 l'informatique.<\/p>\n<p>Il avait d\u00e9j\u00e0 supervis\u00e9 l'acquisition de Tetley et Corus, anciennement British Steel.<\/p>\n<p>T\u00eate de p\u00e9trole et architecte de formation avec un \u0153il pour le design, il avait fait de Tata un constructeur automobile en 1991 et conduit le d\u00e9veloppement de la Tata Nano, la voiture r\u00e9volutionnaire \u00e0 tr\u00e8s bas prix de 1800 \u00a3 avec laquelle il esp\u00e8re faire sortir des millions de familles indiennes de cyclomoteurs surcharg\u00e9s et r\u00e9duire le nombre effroyable de morts sur les routes du pays.<\/p>\n<p>Il vit seul dans un modeste appartement \u00e0 Mumbai avec ses deux alsaciens, Tito et Tango, et dit que son but principal en affaires est de pouvoir poser sa t\u00eate sur son oreiller la nuit en sachant qu'il n'a fait aucun mal.<\/p>\n<p>Le Ratan a \u00e9t\u00e9 un succ\u00e8s instantan\u00e9 chez Jaguar.<\/p>\n<p>Il a une pr\u00e9sence incroyablement noble et un vrai charisme \", dit un ancien initi\u00e9 de Jaguar.<\/p>\n<p>Il adore \u00eatre dans le studio de design, \u00e0 la recherche d'\u00e9tudes pour les futurs mod\u00e8les, et en particulier la nouvelle voiture de sport.<\/p>\n<p>Je me souviens d'avoir assist\u00e9 \u00e0 une r\u00e9union au cours de laquelle nous avons convenu d'un investissement de 100 millions de livres sterling sur place, sans avoir \u00e0 aller en Am\u00e9rique ou ailleurs pour approbation. C'\u00e9tait incroyablement lib\u00e9rateur.<\/p>\n<p>Mais l'achat romantique de 1,1 milliard de livres sterling de JLR par Ratan s'est vite av\u00e9r\u00e9 spectaculairement inopportun.<\/p>\n<p>Avec l'effondrement des march\u00e9s, des banques et de pays entiers, les ventes de voitures ont chut\u00e9 et de nombreux fabricants de produits haut de gamme ont \u00e9t\u00e9 les plus durement touch\u00e9s. Les ventes de JLR ont chut\u00e9 d'un tiers et ont co\u00fbt\u00e9 \u00e0 Tata environ 300 millions de livres sterling en pertes la premi\u00e8re ann\u00e9e.<\/p>\n<p>Elle a \u00e9t\u00e9 forc\u00e9e de n\u00e9gocier avec le secr\u00e9taire d'entreprise Peter Mandelson pour avoir acc\u00e8s aux pr\u00eats et aux garanties de pr\u00eats du gouvernement.<\/p>\n<p>Nous sommes pass\u00e9s de gagnants \u00e0 perdants du jour au lendemain \", dit un ancien cadre sup\u00e9rieur de JLR.<\/p>\n<p>Les choses commen\u00e7aient \u00e0 peine \u00e0 se pr\u00e9senter lorsque la crise a \u00e9clat\u00e9. C'\u00e9tait aussi serr\u00e9 qu'on peut l'\u00eatre chez un constructeur automobile. Nous jouions pour gagner du temps, nous faisions tout ce que nous pouvions l\u00e9gitimement faire pour r\u00e9duire la tr\u00e9sorerie, et nous avions du mal \u00e0 respecter la masse salariale\".<\/p>\n<p>JLR a \u00e9t\u00e9 contrainte de licencier plus de 2 000 travailleurs et pr\u00e9voyait de fermer une de ses usines.<\/p>\n<p>Les n\u00e9gociations avec le gouvernement ont dur\u00e9 si longtemps que les march\u00e9s du cr\u00e9dit se sont lib\u00e9r\u00e9s avant d'\u00eatre achev\u00e9s et, en ao\u00fbt 2009, Tata a pu lever plus de 500 millions de livres sterling pour son achat en difficult\u00e9, aupr\u00e8s de fonds priv\u00e9s et de la Banque europ\u00e9enne d'investissement.<\/p>\n<h2>Et puis, soudain, JLR n'\u00e9tait plus malade.<\/h2>\n<p>L'exposition Land Rover au Salon international de l'auto de Guiyang<\/p>\n<p>Apr\u00e8s une perte de 76 millions de livres sterling au premier trimestre de l'exercice 2009-2010, le graphique des b\u00e9n\u00e9fices amorce une progression implacable vers le haut ; les pertes passent \u00e0 28 millions de livres sterling le trimestre suivant, un b\u00e9n\u00e9fice de 50 millions de livres le trimestre suivant et six fois celui du m\u00eame trimestre un an plus tard.<\/p>\n<p>En 2010-11, JLR a r\u00e9alis\u00e9 autant de b\u00e9n\u00e9fices - 1,1 milliard de livres sterling - qu'il en a co\u00fbt\u00e9 \u00e0 Tata d'acheter seulement trois ans auparavant, et environ 400 millions de livres sterling de plus au cours de l'ann\u00e9e \u00e9coul\u00e9e. Qu'a donc fait Tata pour rentabiliser JLR dans des conditions aussi improbables ?<\/p>\n<p>Pas grand-chose, semble-t-il.<\/p>\n<p>Tata s'est impitoyablement concentr\u00e9e sur la r\u00e9duction des co\u00fbts \", d\u00e9clare le professeur Bailey.<\/p>\n<p>Et ils ont \u00e9t\u00e9 tr\u00e8s d\u00e9cisifs dans le choix de la direction. Mais une fois qu'ils sont en place, ils les laissent faire, contrairement \u00e0 Ford. Ce sont des propri\u00e9taires de patients engag\u00e9s et \u00e0 long terme. \"Tout ce que tu veux.<\/p>\n<p>Lorsque Tata a achet\u00e9 JLR, le pipeline de nouveaux produits a \u00e9t\u00e9 rempli de voitures neuves de renomm\u00e9e mondiale d\u00e9velopp\u00e9es par JLR mais pay\u00e9es par Ford.<\/p>\n<p>La berline Jaguar XF, belle et maniable, lanc\u00e9e en 2007, a sauv\u00e9 les ventes de Jag de la chute libre pendant la crise financi\u00e8re.<\/p>\n<p>Le nouveau Range Rover, Evoque, a \u00e9t\u00e9 mis en vente l'an dernier et a connu un succ\u00e8s colossal, vendant plus de voitures au cours de ses neuf premiers mois que Jaguar vendu toute l'ann\u00e9e.<\/p>\n<p>L'am\u00e9lioration des taux de change a \u00e9galement aid\u00e9 JLR, qui exporte 80 % de sa production.<\/p>\n<p>Mais la plus grande influence sur le succ\u00e8s r\u00e9cent de JLR a \u00e9t\u00e9 la demande insatiable de voitures de luxe britanniques en Chine.<\/p>\n<p>Si l'on exclut la Chine, les chiffres du JLR seraient tr\u00e8s diff\u00e9rents \", explique M. Warburton.<\/p>\n<p>\"Ils seraient probablement encore rentables, mais ils n'auraient pas l'air aussi excitants.<\/p>\n<p>Les ventes dans d'autres march\u00e9s \u00e9mergents comme le Br\u00e9sil, la Russie et l'Inde sont en hausse de 39 %.<\/p>\n<p>Malgr\u00e9 la crise de la zone euro, les ventes y ont augment\u00e9 de 27 % et les ventes aux \u00c9tats-Unis ont augment\u00e9 de 15 % \u00e0 mesure que ce march\u00e9 se redresse lentement. Mais d'ici la fin de l'ann\u00e9e, il est presque certain que la Chine d\u00e9passera les \u00c9tats-Unis et le Royaume-Uni en tant que premier march\u00e9 de JLR.<\/p>\n<p>L'argent que JLR gagne \u00e0 l'\u00e9tranger est d\u00e9pens\u00e9 ici : il pr\u00e9voit d'ouvrir une nouvelle usine de moteurs \u00e0 Wolverhampton, qui co\u00fbtera 355 millions de livres sterling et cr\u00e9era 750 emplois ; 10 000 emplois ont \u00e9t\u00e9 cr\u00e9\u00e9s dans ses trois usines au cours des deux derni\u00e8res ann\u00e9es ; et quand il a annonc\u00e9 1 000 nouveaux travailleurs pour satisfaire la demande de l'usine Evoque \u00e0 Halewood, Merseyside, 35 000 personnes ont postul\u00e9.<\/p>\n<p>Ce mois-ci, l'usine est entr\u00e9e en production 24 heures sur 24 pour r\u00e9pondre \u00e0 la demande. JLR investit 2 milliards de livres chaque ann\u00e9e pour cr\u00e9er 40 produits nouveaux ou r\u00e9vis\u00e9s au cours des cinq prochaines ann\u00e9es.<\/p>\n<p>Bien que Tata ait b\u00e9n\u00e9fici\u00e9 de la R&amp;D de Ford, de nombreux autres projets - tels que le biplace <a href=\"http:\/\/www.carideal.com\/blog\/2012\/11\/27\/jaguar-f-type-2\/\">F-Type<\/a>, qui sera d\u00e9voil\u00e9 au salon de l'automobile de Paris le mois prochain - ont \u00e9t\u00e9 initi\u00e9s sous Tata.<\/p>\n<p>Jaguar et Land Rover ont-ils enfin \u00e9t\u00e9 d\u00e9barrass\u00e9s de leur apparence permanente de danger financier ?<\/p>\n<p>Pas tout \u00e0 fait. Une modification des taux de change ou un nouveau resserrement de la l\u00e9gislation sur les \u00e9missions pourraient frapper durement JLR.<\/p>\n<p>Et m\u00eame un coup d'\u0153il rapide aux comptes montre que c'est Land Rover qui fait toute la course : Les ventes de Jaguar ont en fait baiss\u00e9 au Royaume-Uni, en Europe et en Am\u00e9rique du Nord au cours de l'ann\u00e9e se terminant fin mars.<\/p>\n<p>Seule la Chine lui a permis d'afficher un gain de cinq pour cent \u00e0 54.000 voitures, encore loin de son sommet de 126.000 sous Ford, ou les 100.000 la plupart des analystes pensent qu'il doit travailler sans le soutien de Land Rover.<\/p>\n<p>Mais de nouvelles voitures sont en route : la F-Type, la <a href=\"http:\/\/www.carideal.com\/blog\/2012\/03\/27\/jaguar-xf-sportbrake\/\">XF Sportbrake<\/a> estate et un nouveau mod\u00e8le plus petit, encore secret, qui devrait devenir le plus gros vendeur de la Jag.<\/p>\n<p>Qui plus est, dit un membre du conseil d'administration de JLR, sous Tata, nous avons une agilit\u00e9 qui nous manquait sous Ford. On peut r\u00e9agir plus vite.<\/p>\n<p>Il y a seulement trois ans, Ratan Tata aurait \u00e9t\u00e9 heureux de voir JLR toujours en activit\u00e9. Au lieu de cela, il trouve sa nouvelle entreprise \u00e0 la pointe de la technologie, construisant m\u00eame une supervoiture hybride radicale de 700 000 \u00a3 pour c\u00e9l\u00e9brer un b\u00e9n\u00e9fice stup\u00e9fiant de 1,5 milliard \u00a3 sur un chiffre d'affaires de 13,5 milliards \u00a3.<\/p>\n<p>Tata a fait un travail exceptionnel avec JLR jusqu'\u00e0 pr\u00e9sent \", d\u00e9clare Max Warburton.<\/p>\n<p>Il y a quelques ann\u00e9es, de nombreux constructeurs automobiles occidentaux ont d\u00e9cid\u00e9 que ce n'\u00e9tait pas une bonne affaire, alors que l'entreprise \u00e9tait \u00e0 vendre.<\/p>\n<p>\"Ils doivent \u00eatre en train de se donner des coups de pied.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ratan Tata PDG du groupe Tata la Chine est le plus gros march\u00e9 pour JLR Ratan Tata \u00ab\u00a0Aujourd&rsquo;hui, la Chine est le plus gros march\u00e9 pour Jaguar-Land Rover. Bien plus que les Etats-Unis, l&rsquo;Europe et l&rsquo;Angleterre&#8230;\u00a0\u00bb En 2010-11, JLR a r\u00e9alis\u00e9 autant de b\u00e9n\u00e9fices &#8211; 1,1 milliard de livres sterling que l&rsquo;achat de Tata trois &#8230; <a title=\"Ratan Tata PDG du groupe Tata la Chine est le plus gros march\u00e9 pour JLR\" class=\"read-more\" href=\"https:\/\/www.carideal.com\/blog\/2013\/01\/30\/declaration-ratan-tata-p-dg-du-groupe-tata\/\" aria-label=\"En savoir plus sur Ratan Tata PDG du groupe Tata la Chine est le plus gros march\u00e9 pour JLR\">Lire plus<\/a><\/p>\n","protected":false},"author":3,"featured_media":20346,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[6095],"tags":[],"class_list":["post-5112","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-land-rover"],"wppr_data":{"cwp_meta_box_check":"No"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ratan Tata PDG du groupe Tata la Chine est le plus gros march\u00e9 pour JLR - Blog auto Carid\u00e9al<\/title>\n<meta name=\"description\" content=\"Ratan Tata PDG du groupe Tata la Chine est le plus gros march\u00e9 pour JLR &quot;Aujourd&#039;hui, la Chine est le plus gros march\u00e9 pour Jaguar-Land Rover. Bien plus que les Etats-Unis, l&#039;Europe et l&#039;Angleterre...&quot;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.carideal.com\/blog\/2013\/01\/30\/declaration-ratan-tata-p-dg-du-groupe-tata\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ratan Tata PDG du groupe Tata la Chine est le plus gros march\u00e9 pour JLR - Blog auto Carid\u00e9al\" \/>\n<meta property=\"og:description\" content=\"Ratan Tata PDG du groupe Tata la Chine est le plus gros march\u00e9 pour JLR &quot;Aujourd&#039;hui, la Chine est le plus gros march\u00e9 pour Jaguar-Land Rover. Bien plus que les Etats-Unis, l&#039;Europe et l&#039;Angleterre...&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.carideal.com\/blog\/2013\/01\/30\/declaration-ratan-tata-p-dg-du-groupe-tata\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog auto Carid\u00e9al\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Carideal.mandataire.automobile\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/nicolas.schiavon.39\" \/>\n<meta property=\"article:published_time\" content=\"2013-01-30T23:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-12-04T09:02:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2013\/01\/ratantata-1359621344.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"335\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nicolas SCHIAVON\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@caridealauto\" \/>\n<meta name=\"twitter:site\" content=\"@caridealauto\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nicolas SCHIAVON\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"13 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.carideal.com\/blog\/2013\/01\/30\/declaration-ratan-tata-p-dg-du-groupe-tata\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/2013\/01\/30\/declaration-ratan-tata-p-dg-du-groupe-tata\/\"},\"author\":{\"name\":\"Nicolas SCHIAVON\",\"@id\":\"https:\/\/www.carideal.com\/blog\/#\/schema\/person\/cd95dc7919660de90d31b366f85be1ec\"},\"headline\":\"Ratan Tata PDG du groupe Tata la Chine est le plus gros march\u00e9 pour JLR\",\"datePublished\":\"2013-01-30T23:00:00+00:00\",\"dateModified\":\"2019-12-04T09:02:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/2013\/01\/30\/declaration-ratan-tata-p-dg-du-groupe-tata\/\"},\"wordCount\":2619,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/2013\/01\/30\/declaration-ratan-tata-p-dg-du-groupe-tata\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2013\/01\/ratantata-1359621344.jpg\",\"articleSection\":[\"Actualit\u00e9 Land Rover\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.carideal.com\/blog\/2013\/01\/30\/declaration-ratan-tata-p-dg-du-groupe-tata\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.carideal.com\/blog\/2013\/01\/30\/declaration-ratan-tata-p-dg-du-groupe-tata\/\",\"url\":\"https:\/\/www.carideal.com\/blog\/2013\/01\/30\/declaration-ratan-tata-p-dg-du-groupe-tata\/\",\"name\":\"Ratan Tata PDG du groupe Tata la Chine est le plus gros march\u00e9 pour JLR - Blog auto Carid\u00e9al\",\"isPartOf\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/2013\/01\/30\/declaration-ratan-tata-p-dg-du-groupe-tata\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/2013\/01\/30\/declaration-ratan-tata-p-dg-du-groupe-tata\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2013\/01\/ratantata-1359621344.jpg\",\"datePublished\":\"2013-01-30T23:00:00+00:00\",\"dateModified\":\"2019-12-04T09:02:45+00:00\",\"description\":\"Ratan Tata PDG du groupe Tata la Chine est le plus gros march\u00e9 pour JLR \\\"Aujourd'hui, la Chine est le plus gros march\u00e9 pour Jaguar-Land Rover. Bien plus que les Etats-Unis, l'Europe et l'Angleterre...\\\"\",\"breadcrumb\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/2013\/01\/30\/declaration-ratan-tata-p-dg-du-groupe-tata\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.carideal.com\/blog\/2013\/01\/30\/declaration-ratan-tata-p-dg-du-groupe-tata\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.carideal.com\/blog\/2013\/01\/30\/declaration-ratan-tata-p-dg-du-groupe-tata\/#primaryimage\",\"url\":\"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2013\/01\/ratantata-1359621344.jpg\",\"contentUrl\":\"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2013\/01\/ratantata-1359621344.jpg\",\"width\":480,\"height\":335,\"caption\":\"Ratan Tata PDG du groupe Tata la Chine est le plus gros march\u00e9 pour JLR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.carideal.com\/blog\/2013\/01\/30\/declaration-ratan-tata-p-dg-du-groupe-tata\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog Carid\u00e9al\",\"item\":\"https:\/\/www.carideal.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Actualit\u00e9 constructeur automobile\",\"item\":\"https:\/\/www.carideal.com\/blog\/constructeur\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Actualit\u00e9 Land Rover\",\"item\":\"https:\/\/www.carideal.com\/blog\/constructeur\/land-rover\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Ratan Tata PDG du groupe Tata la Chine est le plus gros march\u00e9 pour JLR\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.carideal.com\/blog\/#website\",\"url\":\"https:\/\/www.carideal.com\/blog\/\",\"name\":\"Blog auto Carid\u00e9al\",\"description\":\"Actualit\u00e9 auto par des passionn\u00e9s\",\"publisher\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.carideal.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.carideal.com\/blog\/#organization\",\"name\":\"Carideal\",\"url\":\"https:\/\/www.carideal.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.carideal.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2016\/03\/logo-carideal-mandataire-automobile.png\",\"contentUrl\":\"http:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2016\/03\/logo-carideal-mandataire-automobile.png\",\"width\":300,\"height\":300,\"caption\":\"Carideal\"},\"image\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Carideal.mandataire.automobile\",\"https:\/\/x.com\/caridealauto\",\"https:\/\/www.instagram.com\/carideal1\/\",\"https:\/\/www.linkedin.com\/company\/carideal.com\",\"https:\/\/fr.pinterest.com\/schiavonsas\/\",\"https:\/\/www.youtube.com\/user\/caridealsas\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.carideal.com\/blog\/#\/schema\/person\/cd95dc7919660de90d31b366f85be1ec\",\"name\":\"Nicolas SCHIAVON\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.carideal.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c17e55009e671d92cc7f5dc837dc418a?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c17e55009e671d92cc7f5dc837dc418a?s=96&r=g\",\"caption\":\"Nicolas SCHIAVON\"},\"description\":\"Nicolas Schiavon est tomb\u00e9 tout petit dans la marmite automobile. Ayant eu un garage de marque automobile, mandataire automobile de la premi\u00e8re heure d\u00e8s 1999. Nicolas a cr\u00e9\u00e9 ces premiers sites de vente de voiture et blog automobile d\u00e8s 1994. Carideal est n\u00e9 le 15 d\u00e9cembre 2000 de la volont\u00e9 de vendre des voitures d'occasions en ligne puis des voitures neuves. Il a pu essayer beaucoup de voitures tr\u00e8s diff\u00e9rentes et ayant eu personnellement quelques belles autos, Subaru Impreza, Mitsubishi Lancer Evo 7, Porsche 911, Ferrari Testarrossa, Audi RS3, RS4 et j'en passe...\",\"sameAs\":[\"http:\/\/www.carideal.com\",\"https:\/\/www.facebook.com\/nicolas.schiavon.39\",\"https:\/\/www.instagram.com\/carideal1\/\",\"https:\/\/www.linkedin.com\/in\/nschiavon\/\",\"https:\/\/x.com\/caridealauto\",\"https:\/\/www.youtube.com\/user\/caridealsas\/\"],\"url\":\"https:\/\/www.carideal.com\/blog\/author\/nschiavon\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ratan Tata PDG du groupe Tata la Chine est le plus gros march\u00e9 pour JLR - Blog auto Carid\u00e9al","description":"Ratan Tata PDG du groupe Tata la Chine est le plus gros march\u00e9 pour JLR \"Aujourd'hui, la Chine est le plus gros march\u00e9 pour Jaguar-Land Rover. Bien plus que les Etats-Unis, l'Europe et l'Angleterre...\"","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.carideal.com\/blog\/2013\/01\/30\/declaration-ratan-tata-p-dg-du-groupe-tata\/","og_locale":"fr_FR","og_type":"article","og_title":"Ratan Tata PDG du groupe Tata la Chine est le plus gros march\u00e9 pour JLR - Blog auto Carid\u00e9al","og_description":"Ratan Tata PDG du groupe Tata la Chine est le plus gros march\u00e9 pour JLR \"Aujourd'hui, la Chine est le plus gros march\u00e9 pour Jaguar-Land Rover. Bien plus que les Etats-Unis, l'Europe et l'Angleterre...\"","og_url":"https:\/\/www.carideal.com\/blog\/2013\/01\/30\/declaration-ratan-tata-p-dg-du-groupe-tata\/","og_site_name":"Blog auto Carid\u00e9al","article_publisher":"https:\/\/www.facebook.com\/Carideal.mandataire.automobile","article_author":"https:\/\/www.facebook.com\/nicolas.schiavon.39","article_published_time":"2013-01-30T23:00:00+00:00","article_modified_time":"2019-12-04T09:02:45+00:00","og_image":[{"width":480,"height":335,"url":"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2013\/01\/ratantata-1359621344.jpg","type":"image\/jpeg"}],"author":"Nicolas SCHIAVON","twitter_card":"summary_large_image","twitter_creator":"@caridealauto","twitter_site":"@caridealauto","twitter_misc":{"\u00c9crit par":"Nicolas SCHIAVON","Dur\u00e9e de lecture estim\u00e9e":"13 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.carideal.com\/blog\/2013\/01\/30\/declaration-ratan-tata-p-dg-du-groupe-tata\/#article","isPartOf":{"@id":"https:\/\/www.carideal.com\/blog\/2013\/01\/30\/declaration-ratan-tata-p-dg-du-groupe-tata\/"},"author":{"name":"Nicolas SCHIAVON","@id":"https:\/\/www.carideal.com\/blog\/#\/schema\/person\/cd95dc7919660de90d31b366f85be1ec"},"headline":"Ratan Tata PDG du groupe Tata la Chine est le plus gros march\u00e9 pour JLR","datePublished":"2013-01-30T23:00:00+00:00","dateModified":"2019-12-04T09:02:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.carideal.com\/blog\/2013\/01\/30\/declaration-ratan-tata-p-dg-du-groupe-tata\/"},"wordCount":2619,"commentCount":0,"publisher":{"@id":"https:\/\/www.carideal.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.carideal.com\/blog\/2013\/01\/30\/declaration-ratan-tata-p-dg-du-groupe-tata\/#primaryimage"},"thumbnailUrl":"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2013\/01\/ratantata-1359621344.jpg","articleSection":["Actualit\u00e9 Land Rover"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.carideal.com\/blog\/2013\/01\/30\/declaration-ratan-tata-p-dg-du-groupe-tata\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.carideal.com\/blog\/2013\/01\/30\/declaration-ratan-tata-p-dg-du-groupe-tata\/","url":"https:\/\/www.carideal.com\/blog\/2013\/01\/30\/declaration-ratan-tata-p-dg-du-groupe-tata\/","name":"Ratan Tata PDG du groupe Tata la Chine est le plus gros march\u00e9 pour JLR - Blog auto Carid\u00e9al","isPartOf":{"@id":"https:\/\/www.carideal.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.carideal.com\/blog\/2013\/01\/30\/declaration-ratan-tata-p-dg-du-groupe-tata\/#primaryimage"},"image":{"@id":"https:\/\/www.carideal.com\/blog\/2013\/01\/30\/declaration-ratan-tata-p-dg-du-groupe-tata\/#primaryimage"},"thumbnailUrl":"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2013\/01\/ratantata-1359621344.jpg","datePublished":"2013-01-30T23:00:00+00:00","dateModified":"2019-12-04T09:02:45+00:00","description":"Ratan Tata PDG du groupe Tata la Chine est le plus gros march\u00e9 pour JLR \"Aujourd'hui, la Chine est le plus gros march\u00e9 pour Jaguar-Land Rover. Bien plus que les Etats-Unis, l'Europe et l'Angleterre...\"","breadcrumb":{"@id":"https:\/\/www.carideal.com\/blog\/2013\/01\/30\/declaration-ratan-tata-p-dg-du-groupe-tata\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.carideal.com\/blog\/2013\/01\/30\/declaration-ratan-tata-p-dg-du-groupe-tata\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.carideal.com\/blog\/2013\/01\/30\/declaration-ratan-tata-p-dg-du-groupe-tata\/#primaryimage","url":"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2013\/01\/ratantata-1359621344.jpg","contentUrl":"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2013\/01\/ratantata-1359621344.jpg","width":480,"height":335,"caption":"Ratan Tata PDG du groupe Tata la Chine est le plus gros march\u00e9 pour JLR"},{"@type":"BreadcrumbList","@id":"https:\/\/www.carideal.com\/blog\/2013\/01\/30\/declaration-ratan-tata-p-dg-du-groupe-tata\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog Carid\u00e9al","item":"https:\/\/www.carideal.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Actualit\u00e9 constructeur automobile","item":"https:\/\/www.carideal.com\/blog\/constructeur\/"},{"@type":"ListItem","position":3,"name":"Actualit\u00e9 Land Rover","item":"https:\/\/www.carideal.com\/blog\/constructeur\/land-rover\/"},{"@type":"ListItem","position":4,"name":"Ratan Tata PDG du groupe Tata la Chine est le plus gros march\u00e9 pour JLR"}]},{"@type":"WebSite","@id":"https:\/\/www.carideal.com\/blog\/#website","url":"https:\/\/www.carideal.com\/blog\/","name":"Blog auto Carid\u00e9al","description":"Actualit\u00e9 auto par des passionn\u00e9s","publisher":{"@id":"https:\/\/www.carideal.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.carideal.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.carideal.com\/blog\/#organization","name":"Carideal","url":"https:\/\/www.carideal.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.carideal.com\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2016\/03\/logo-carideal-mandataire-automobile.png","contentUrl":"http:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2016\/03\/logo-carideal-mandataire-automobile.png","width":300,"height":300,"caption":"Carideal"},"image":{"@id":"https:\/\/www.carideal.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Carideal.mandataire.automobile","https:\/\/x.com\/caridealauto","https:\/\/www.instagram.com\/carideal1\/","https:\/\/www.linkedin.com\/company\/carideal.com","https:\/\/fr.pinterest.com\/schiavonsas\/","https:\/\/www.youtube.com\/user\/caridealsas"]},{"@type":"Person","@id":"https:\/\/www.carideal.com\/blog\/#\/schema\/person\/cd95dc7919660de90d31b366f85be1ec","name":"Nicolas SCHIAVON","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.carideal.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c17e55009e671d92cc7f5dc837dc418a?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c17e55009e671d92cc7f5dc837dc418a?s=96&r=g","caption":"Nicolas SCHIAVON"},"description":"Nicolas Schiavon est tomb\u00e9 tout petit dans la marmite automobile. Ayant eu un garage de marque automobile, mandataire automobile de la premi\u00e8re heure d\u00e8s 1999. Nicolas a cr\u00e9\u00e9 ces premiers sites de vente de voiture et blog automobile d\u00e8s 1994. Carideal est n\u00e9 le 15 d\u00e9cembre 2000 de la volont\u00e9 de vendre des voitures d'occasions en ligne puis des voitures neuves. Il a pu essayer beaucoup de voitures tr\u00e8s diff\u00e9rentes et ayant eu personnellement quelques belles autos, Subaru Impreza, Mitsubishi Lancer Evo 7, Porsche 911, Ferrari Testarrossa, Audi RS3, RS4 et j'en passe...","sameAs":["http:\/\/www.carideal.com","https:\/\/www.facebook.com\/nicolas.schiavon.39","https:\/\/www.instagram.com\/carideal1\/","https:\/\/www.linkedin.com\/in\/nschiavon\/","https:\/\/x.com\/caridealauto","https:\/\/www.youtube.com\/user\/caridealsas\/"],"url":"https:\/\/www.carideal.com\/blog\/author\/nschiavon\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2013\/01\/ratantata-1359621344.jpg",480,335,false],"thumbnail":["https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2013\/01\/ratantata-1359621344-150x150.jpg",150,150,true],"medium":["https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2013\/01\/ratantata-1359621344-300x209.jpg",300,209,true],"medium_large":["https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2013\/01\/ratantata-1359621344.jpg",480,335,false],"large":["https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2013\/01\/ratantata-1359621344.jpg",480,335,false],"1536x1536":["https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2013\/01\/ratantata-1359621344.jpg",480,335,false],"2048x2048":["https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2013\/01\/ratantata-1359621344.jpg",480,335,false],"wppr-widget":["https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2013\/01\/ratantata-1359621344-50x35.jpg",50,35,true]},"uagb_author_info":{"display_name":"Nicolas SCHIAVON","author_link":"https:\/\/www.carideal.com\/blog\/author\/nschiavon\/"},"uagb_comment_info":0,"uagb_excerpt":"Ratan Tata PDG du groupe Tata la Chine est le plus gros march\u00e9 pour JLR Ratan Tata \"Aujourd'hui, la Chine est le plus gros march\u00e9 pour Jaguar-Land Rover. Bien plus que les Etats-Unis, l'Europe et l'Angleterre...\" En 2010-11, JLR a r\u00e9alis\u00e9 autant de b\u00e9n\u00e9fices - 1,1 milliard de livres sterling que l'achat de Tata trois\u2026","_links":{"self":[{"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/posts\/5112"}],"collection":[{"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/comments?post=5112"}],"version-history":[{"count":0,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/posts\/5112\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/media\/20346"}],"wp:attachment":[{"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/media?parent=5112"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/categories?post=5112"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/tags?post=5112"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}