{"id":5106,"date":"2013-01-22T23:00:00","date_gmt":"2013-01-22T23:00:00","guid":{"rendered":"http:\/\/www.carideal.com\/blog\/2013\/01\/22\/stopstart-7\/"},"modified":"2020-02-14T13:05:21","modified_gmt":"2020-02-14T12:05:21","slug":"stopstart-7","status":"publish","type":"post","link":"https:\/\/www.carideal.com\/blog\/2013\/01\/22\/stopstart-7\/","title":{"rendered":"Le lancement de la Renault Zoe est retard\u00e9"},"content":{"rendered":"<h2>Le lancement de la Renault Zoe est retard\u00e9<\/h2>\n<p>Annonc\u00e9 au printemps 2012, puis en d\u00e9cembre 2012, le lancement de la <a href=\"http:\/\/www.carideal.com\/blog\/2018\/02\/09\/meilleures-citadines-2018\/\">citadine<\/a> \u00e9lectrique ZOE de <a href=\"http:\/\/www.carideal.com\/blog\/marque-de-voiture-actualites-essais\/renault\/\">Renault<\/a> est d\u00e9sormais officiellement repouss\u00e9 au mois de mars 2013 et pourrait m\u00eame, selon certaines sources internes \u00e0 Renault, \u00eatre report\u00e9 \u00e0 l'automne 2013.<\/p>\n<figure id=\"attachment_19224\" aria-describedby=\"caption-attachment-19224\" style=\"width: 595px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-19224\" src=\"http:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2013\/01\/renaultzoe-1358948714.jpg\" alt=\"Le lancement de la Renault Zoe est retard\u00e9\" width=\"605\" height=\"325\" srcset=\"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2013\/01\/renaultzoe-1358948714.jpg 605w, https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2013\/01\/renaultzoe-1358948714-300x161.jpg 300w, https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2013\/01\/renaultzoe-1358948714-50x27.jpg 50w, https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2013\/01\/renaultzoe-1358948714-110x59.jpg 110w, https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2013\/01\/renaultzoe-1358948714-420x226.jpg 420w\" sizes=\"(max-width: 605px) 100vw, 605px\" \/><figcaption id=\"caption-attachment-19224\" class=\"wp-caption-text\">Le lancement de la Renault Zoe est retard\u00e9<\/figcaption><\/figure>\n<ul>\n<li><a href=\"http:\/\/www.carideal.com\/blog\/2018\/11\/26\/meilleures-voitures-electriques-en-vente-2018\/\">Les meilleures voitures \u00e9lectriques<\/a><\/li>\n<\/ul>\n<p>En cause, selon la version officielle, un probl\u00e8me de mise au point du syst\u00e8me d'info divertissement mais, d'autres informations \u00e9voquent un souci avec le syst\u00e8me de charge novateur de la voiture.<\/p>\n<ul>\n<li>Toutes nos offres de Renault<\/li>\n<\/ul>\n<p>En fait, peu importe la raison exacte de ce retard, mais il risque fort de faire retomber le \"souffl\u00e9\" de l'int\u00e9r\u00eat pour la <a href=\"http:\/\/www.carideal.com\/blog\/2018\/11\/26\/meilleures-voitures-electriques-en-vente-2018\/\">voiture \u00e9lectrique<\/a>. D\u00e9j\u00e0, au mois de novembre 2012, les ventes de v\u00e9hicules \u00e9lectriques particuliers se sont effondr\u00e9es malgr\u00e9 le gros bonus de 7000\u20ac.<\/p>\n<ul>\n<li>Carideal mandataire Renault<\/li>\n<\/ul>\n<p>Apr\u00e8s l'embellie du mois d'ao\u00fbt ( 960 voitures ), due aux \"braderies\" organis\u00e9es par <a href=\"http:\/\/www.carideal.com\/blog\/2015\/09\/17\/psa-va-developper-ses-futures-voitures-electriques-en-2020-avec-dongfeng\/\">PSA<\/a>, le march\u00e9 est retomb\u00e9 \u00e0 330 v\u00e9hicules en novembre.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le lancement de la Renault Zoe est retard\u00e9 Annonc\u00e9 au printemps 2012, puis en d\u00e9cembre 2012, le lancement de la citadine \u00e9lectrique ZOE de Renault est d\u00e9sormais officiellement repouss\u00e9 au mois de mars 2013 et pourrait m\u00eame, selon certaines sources internes \u00e0 Renault, \u00eatre report\u00e9 \u00e0 l&rsquo;automne 2013. Les meilleures voitures \u00e9lectriques En cause, selon &#8230; <a title=\"Le lancement de la Renault Zoe est retard\u00e9\" class=\"read-more\" href=\"https:\/\/www.carideal.com\/blog\/2013\/01\/22\/stopstart-7\/\" aria-label=\"En savoir plus sur Le lancement de la Renault Zoe est retard\u00e9\">Lire plus<\/a><\/p>\n","protected":false},"author":3,"featured_media":19224,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[5963,5970],"tags":[],"class_list":["post-5106","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-renault","category-electrique-technologie-2"],"wppr_data":{"cwp_meta_box_check":"No"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Le lancement de la Renault Zoe est retard\u00e9 - Blog auto Carid\u00e9al<\/title>\n<meta name=\"description\" content=\"Le lancement de la Renault Zoe est retard\u00e9. Diff\u00e9rentes raisons sont avanc\u00e9es, mais peu importe, cela ne joue pas en faveur de la voiture \u00e9lectrique\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.carideal.com\/blog\/2013\/01\/22\/stopstart-7\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le lancement de la Renault Zoe est retard\u00e9 - Blog auto Carid\u00e9al\" \/>\n<meta property=\"og:description\" content=\"Le lancement de la Renault Zoe est retard\u00e9. Diff\u00e9rentes raisons sont avanc\u00e9es, mais peu importe, cela ne joue pas en faveur de la voiture \u00e9lectrique\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.carideal.com\/blog\/2013\/01\/22\/stopstart-7\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog auto Carid\u00e9al\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Carideal.mandataire.automobile\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/nicolas.schiavon.39\" \/>\n<meta property=\"article:published_time\" content=\"2013-01-22T23:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-14T12:05:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2013\/01\/renaultzoe-1358948714.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"605\" \/>\n\t<meta property=\"og:image:height\" content=\"325\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nicolas SCHIAVON\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@caridealauto\" \/>\n<meta name=\"twitter:site\" content=\"@caridealauto\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nicolas SCHIAVON\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.carideal.com\/blog\/2013\/01\/22\/stopstart-7\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/2013\/01\/22\/stopstart-7\/\"},\"author\":{\"name\":\"Nicolas SCHIAVON\",\"@id\":\"https:\/\/www.carideal.com\/blog\/#\/schema\/person\/cd95dc7919660de90d31b366f85be1ec\"},\"headline\":\"Le lancement de la Renault Zoe est retard\u00e9\",\"datePublished\":\"2013-01-22T23:00:00+00:00\",\"dateModified\":\"2020-02-14T12:05:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/2013\/01\/22\/stopstart-7\/\"},\"wordCount\":186,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/2013\/01\/22\/stopstart-7\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2013\/01\/renaultzoe-1358948714.jpg\",\"articleSection\":[\"Actualit\u00e9 Renault\",\"Voiture \u00e9lectrique\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.carideal.com\/blog\/2013\/01\/22\/stopstart-7\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.carideal.com\/blog\/2013\/01\/22\/stopstart-7\/\",\"url\":\"https:\/\/www.carideal.com\/blog\/2013\/01\/22\/stopstart-7\/\",\"name\":\"Le lancement de la Renault Zoe est retard\u00e9 - Blog auto Carid\u00e9al\",\"isPartOf\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/2013\/01\/22\/stopstart-7\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/2013\/01\/22\/stopstart-7\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2013\/01\/renaultzoe-1358948714.jpg\",\"datePublished\":\"2013-01-22T23:00:00+00:00\",\"dateModified\":\"2020-02-14T12:05:21+00:00\",\"description\":\"Le lancement de la Renault Zoe est retard\u00e9. Diff\u00e9rentes raisons sont avanc\u00e9es, mais peu importe, cela ne joue pas en faveur de la voiture \u00e9lectrique\",\"breadcrumb\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/2013\/01\/22\/stopstart-7\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.carideal.com\/blog\/2013\/01\/22\/stopstart-7\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.carideal.com\/blog\/2013\/01\/22\/stopstart-7\/#primaryimage\",\"url\":\"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2013\/01\/renaultzoe-1358948714.jpg\",\"contentUrl\":\"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2013\/01\/renaultzoe-1358948714.jpg\",\"width\":605,\"height\":325,\"caption\":\"Le lancement de la Renault Zoe est retard\u00e9\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.carideal.com\/blog\/2013\/01\/22\/stopstart-7\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog Carid\u00e9al\",\"item\":\"https:\/\/www.carideal.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Actualit\u00e9 constructeur automobile\",\"item\":\"https:\/\/www.carideal.com\/blog\/constructeur\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Actualit\u00e9 Renault\",\"item\":\"https:\/\/www.carideal.com\/blog\/constructeur\/renault\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Le lancement de la Renault Zoe est retard\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.carideal.com\/blog\/#website\",\"url\":\"https:\/\/www.carideal.com\/blog\/\",\"name\":\"Blog auto Carid\u00e9al\",\"description\":\"Actualit\u00e9 auto par des passionn\u00e9s\",\"publisher\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.carideal.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.carideal.com\/blog\/#organization\",\"name\":\"Carideal\",\"url\":\"https:\/\/www.carideal.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.carideal.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2016\/03\/logo-carideal-mandataire-automobile.png\",\"contentUrl\":\"http:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2016\/03\/logo-carideal-mandataire-automobile.png\",\"width\":300,\"height\":300,\"caption\":\"Carideal\"},\"image\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Carideal.mandataire.automobile\",\"https:\/\/x.com\/caridealauto\",\"https:\/\/www.instagram.com\/carideal1\/\",\"https:\/\/www.linkedin.com\/company\/carideal.com\",\"https:\/\/fr.pinterest.com\/schiavonsas\/\",\"https:\/\/www.youtube.com\/user\/caridealsas\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.carideal.com\/blog\/#\/schema\/person\/cd95dc7919660de90d31b366f85be1ec\",\"name\":\"Nicolas SCHIAVON\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.carideal.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c17e55009e671d92cc7f5dc837dc418a?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c17e55009e671d92cc7f5dc837dc418a?s=96&r=g\",\"caption\":\"Nicolas SCHIAVON\"},\"description\":\"Nicolas Schiavon est tomb\u00e9 tout petit dans la marmite automobile. Ayant eu un garage de marque automobile, mandataire automobile de la premi\u00e8re heure d\u00e8s 1999. Nicolas a cr\u00e9\u00e9 ces premiers sites de vente de voiture et blog automobile d\u00e8s 1994. Carideal est n\u00e9 le 15 d\u00e9cembre 2000 de la volont\u00e9 de vendre des voitures d'occasions en ligne puis des voitures neuves. Il a pu essayer beaucoup de voitures tr\u00e8s diff\u00e9rentes et ayant eu personnellement quelques belles autos, Subaru Impreza, Mitsubishi Lancer Evo 7, Porsche 911, Ferrari Testarrossa, Audi RS3, RS4 et j'en passe...\",\"sameAs\":[\"http:\/\/www.carideal.com\",\"https:\/\/www.facebook.com\/nicolas.schiavon.39\",\"https:\/\/www.instagram.com\/carideal1\/\",\"https:\/\/www.linkedin.com\/in\/nschiavon\/\",\"https:\/\/x.com\/caridealauto\",\"https:\/\/www.youtube.com\/user\/caridealsas\/\"],\"url\":\"https:\/\/www.carideal.com\/blog\/author\/nschiavon\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le lancement de la Renault Zoe est retard\u00e9 - Blog auto Carid\u00e9al","description":"Le lancement de la Renault Zoe est retard\u00e9. Diff\u00e9rentes raisons sont avanc\u00e9es, mais peu importe, cela ne joue pas en faveur de la voiture \u00e9lectrique","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.carideal.com\/blog\/2013\/01\/22\/stopstart-7\/","og_locale":"fr_FR","og_type":"article","og_title":"Le lancement de la Renault Zoe est retard\u00e9 - Blog auto Carid\u00e9al","og_description":"Le lancement de la Renault Zoe est retard\u00e9. Diff\u00e9rentes raisons sont avanc\u00e9es, mais peu importe, cela ne joue pas en faveur de la voiture \u00e9lectrique","og_url":"https:\/\/www.carideal.com\/blog\/2013\/01\/22\/stopstart-7\/","og_site_name":"Blog auto Carid\u00e9al","article_publisher":"https:\/\/www.facebook.com\/Carideal.mandataire.automobile","article_author":"https:\/\/www.facebook.com\/nicolas.schiavon.39","article_published_time":"2013-01-22T23:00:00+00:00","article_modified_time":"2020-02-14T12:05:21+00:00","og_image":[{"width":605,"height":325,"url":"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2013\/01\/renaultzoe-1358948714.jpg","type":"image\/jpeg"}],"author":"Nicolas SCHIAVON","twitter_card":"summary_large_image","twitter_creator":"@caridealauto","twitter_site":"@caridealauto","twitter_misc":{"\u00c9crit par":"Nicolas SCHIAVON","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.carideal.com\/blog\/2013\/01\/22\/stopstart-7\/#article","isPartOf":{"@id":"https:\/\/www.carideal.com\/blog\/2013\/01\/22\/stopstart-7\/"},"author":{"name":"Nicolas SCHIAVON","@id":"https:\/\/www.carideal.com\/blog\/#\/schema\/person\/cd95dc7919660de90d31b366f85be1ec"},"headline":"Le lancement de la Renault Zoe est retard\u00e9","datePublished":"2013-01-22T23:00:00+00:00","dateModified":"2020-02-14T12:05:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.carideal.com\/blog\/2013\/01\/22\/stopstart-7\/"},"wordCount":186,"commentCount":0,"publisher":{"@id":"https:\/\/www.carideal.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.carideal.com\/blog\/2013\/01\/22\/stopstart-7\/#primaryimage"},"thumbnailUrl":"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2013\/01\/renaultzoe-1358948714.jpg","articleSection":["Actualit\u00e9 Renault","Voiture \u00e9lectrique"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.carideal.com\/blog\/2013\/01\/22\/stopstart-7\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.carideal.com\/blog\/2013\/01\/22\/stopstart-7\/","url":"https:\/\/www.carideal.com\/blog\/2013\/01\/22\/stopstart-7\/","name":"Le lancement de la Renault Zoe est retard\u00e9 - Blog auto Carid\u00e9al","isPartOf":{"@id":"https:\/\/www.carideal.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.carideal.com\/blog\/2013\/01\/22\/stopstart-7\/#primaryimage"},"image":{"@id":"https:\/\/www.carideal.com\/blog\/2013\/01\/22\/stopstart-7\/#primaryimage"},"thumbnailUrl":"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2013\/01\/renaultzoe-1358948714.jpg","datePublished":"2013-01-22T23:00:00+00:00","dateModified":"2020-02-14T12:05:21+00:00","description":"Le lancement de la Renault Zoe est retard\u00e9. Diff\u00e9rentes raisons sont avanc\u00e9es, mais peu importe, cela ne joue pas en faveur de la voiture \u00e9lectrique","breadcrumb":{"@id":"https:\/\/www.carideal.com\/blog\/2013\/01\/22\/stopstart-7\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.carideal.com\/blog\/2013\/01\/22\/stopstart-7\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.carideal.com\/blog\/2013\/01\/22\/stopstart-7\/#primaryimage","url":"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2013\/01\/renaultzoe-1358948714.jpg","contentUrl":"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2013\/01\/renaultzoe-1358948714.jpg","width":605,"height":325,"caption":"Le lancement de la Renault Zoe est retard\u00e9"},{"@type":"BreadcrumbList","@id":"https:\/\/www.carideal.com\/blog\/2013\/01\/22\/stopstart-7\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog Carid\u00e9al","item":"https:\/\/www.carideal.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Actualit\u00e9 constructeur automobile","item":"https:\/\/www.carideal.com\/blog\/constructeur\/"},{"@type":"ListItem","position":3,"name":"Actualit\u00e9 Renault","item":"https:\/\/www.carideal.com\/blog\/constructeur\/renault\/"},{"@type":"ListItem","position":4,"name":"Le lancement de la Renault Zoe est retard\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/www.carideal.com\/blog\/#website","url":"https:\/\/www.carideal.com\/blog\/","name":"Blog auto Carid\u00e9al","description":"Actualit\u00e9 auto par des passionn\u00e9s","publisher":{"@id":"https:\/\/www.carideal.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.carideal.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.carideal.com\/blog\/#organization","name":"Carideal","url":"https:\/\/www.carideal.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.carideal.com\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2016\/03\/logo-carideal-mandataire-automobile.png","contentUrl":"http:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2016\/03\/logo-carideal-mandataire-automobile.png","width":300,"height":300,"caption":"Carideal"},"image":{"@id":"https:\/\/www.carideal.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Carideal.mandataire.automobile","https:\/\/x.com\/caridealauto","https:\/\/www.instagram.com\/carideal1\/","https:\/\/www.linkedin.com\/company\/carideal.com","https:\/\/fr.pinterest.com\/schiavonsas\/","https:\/\/www.youtube.com\/user\/caridealsas"]},{"@type":"Person","@id":"https:\/\/www.carideal.com\/blog\/#\/schema\/person\/cd95dc7919660de90d31b366f85be1ec","name":"Nicolas SCHIAVON","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.carideal.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c17e55009e671d92cc7f5dc837dc418a?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c17e55009e671d92cc7f5dc837dc418a?s=96&r=g","caption":"Nicolas SCHIAVON"},"description":"Nicolas Schiavon est tomb\u00e9 tout petit dans la marmite automobile. Ayant eu un garage de marque automobile, mandataire automobile de la premi\u00e8re heure d\u00e8s 1999. Nicolas a cr\u00e9\u00e9 ces premiers sites de vente de voiture et blog automobile d\u00e8s 1994. Carideal est n\u00e9 le 15 d\u00e9cembre 2000 de la volont\u00e9 de vendre des voitures d'occasions en ligne puis des voitures neuves. Il a pu essayer beaucoup de voitures tr\u00e8s diff\u00e9rentes et ayant eu personnellement quelques belles autos, Subaru Impreza, Mitsubishi Lancer Evo 7, Porsche 911, Ferrari Testarrossa, Audi RS3, RS4 et j'en passe...","sameAs":["http:\/\/www.carideal.com","https:\/\/www.facebook.com\/nicolas.schiavon.39","https:\/\/www.instagram.com\/carideal1\/","https:\/\/www.linkedin.com\/in\/nschiavon\/","https:\/\/x.com\/caridealauto","https:\/\/www.youtube.com\/user\/caridealsas\/"],"url":"https:\/\/www.carideal.com\/blog\/author\/nschiavon\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2013\/01\/renaultzoe-1358948714.jpg",605,325,false],"thumbnail":["https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2013\/01\/renaultzoe-1358948714-150x150.jpg",150,150,true],"medium":["https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2013\/01\/renaultzoe-1358948714-300x161.jpg",300,161,true],"medium_large":["https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2013\/01\/renaultzoe-1358948714.jpg",605,325,false],"large":["https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2013\/01\/renaultzoe-1358948714.jpg",605,325,false],"1536x1536":["https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2013\/01\/renaultzoe-1358948714.jpg",605,325,false],"2048x2048":["https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2013\/01\/renaultzoe-1358948714.jpg",605,325,false],"wppr-widget":["https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2013\/01\/renaultzoe-1358948714-50x27.jpg",50,27,true]},"uagb_author_info":{"display_name":"Nicolas SCHIAVON","author_link":"https:\/\/www.carideal.com\/blog\/author\/nschiavon\/"},"uagb_comment_info":0,"uagb_excerpt":"Le lancement de la Renault Zoe est retard\u00e9 Annonc\u00e9 au printemps 2012, puis en d\u00e9cembre 2012, le lancement de la citadine \u00e9lectrique ZOE de Renault est d\u00e9sormais officiellement repouss\u00e9 au mois de mars 2013 et pourrait m\u00eame, selon certaines sources internes \u00e0 Renault, \u00eatre report\u00e9 \u00e0 l'automne 2013. Les meilleures voitures \u00e9lectriques En cause, selon\u2026","_links":{"self":[{"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/posts\/5106"}],"collection":[{"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/comments?post=5106"}],"version-history":[{"count":0,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/posts\/5106\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/media\/19224"}],"wp:attachment":[{"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/media?parent=5106"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/categories?post=5106"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/tags?post=5106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}