{"id":498,"date":"2012-01-05T09:49:00","date_gmt":"2012-01-05T09:49:00","guid":{"rendered":"http:\/\/carideal.com\/blog\/?p=498"},"modified":"2020-03-07T16:51:16","modified_gmt":"2020-03-07T15:51:16","slug":"evo-8-evite-carambollage-sur-autoroute-verglacee-avec-brouillard","status":"publish","type":"post","link":"https:\/\/www.carideal.com\/blog\/2012\/01\/05\/evo-8-evite-carambollage-sur-autoroute-verglacee-avec-brouillard\/","title":{"rendered":"Evo 8 evite carambollage sur autoroute verglacee avec brouillard"},"content":{"rendered":"<p><img decoding=\"async\" title=\"Accident-neige-glace-carideal-achat-pneu-hiver-carideal.jpg, janv. 2012\" src=\"\/blog\/public\/.Accident-neige-glace-carideal-achat-pneu-hiver-carideal_m.jpg\" alt=\"Accident-neige-glace-carideal-achat-pneu-hiver-carideal.jpg\" \/><\/p>\n<blockquote><p>Le conducteur \u00e9vite la mort et presque l'accident...<\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" src=\"http:\/\/www.youtube.com\/embed\/FhVGeIgLdlI\" width=\"640\" height=\"360\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>Glace noire...soudain brouillard..une bourre entre une Evo 8 et une mini puis ....le mur de carambolage, la mini qui percute un monospace, l'\u00e9vo qui passe dans l'herbe....et le semi remorque lanc\u00e9 \u00e0 fond....qui passe dans l'herbe....dieu \u00e9tait l\u00e0 !<br \/>\nLa traduction\u00a0:<br \/>\n\" Cette temp\u00eate est sorti de nulle part. Le temps \u00e9tait clair 15 secondes avant que la vid\u00e9o ai commenc\u00e9. Je laisse aller les gaz pour ralentir au lieu de freiner au d\u00e9but de la vid\u00e9o. je savais que je roulais trop vite et que de freiner n'aurait pas \u00e9t\u00e9 une bonne id\u00e9e. Le film commence lorsque j'ai prss\u00e9 le bouton d'enregistrement sur \u200b\u200bl'appareil. Vous pouvez m'entendre \u00e9teindre la radio. Mes essuie-glaces ne sont m\u00eame pas sur encore.<\/p>\n<p>J'ai frein\u00e9 \u00e0 la seconde 0:04 quand j'ai vu l'accident, pour r\u00e9aliser que c'\u00e9tait inutile donc je laisse aller compl\u00e8tement et reprend le contr\u00f4le.<\/p>\n<p>Je suis sorti de la voiture pour v\u00e9rifier les d\u00e9g\u00e2ts apr\u00e8s que j'ai pass\u00e9 devant la zone de l'accident. environ un mile sur la route. Je dois avoir vu au moins 15 voitures endommag\u00e9es gauche et \u00e0 droite.<\/p>\n<p>Film\u00e9 sur l'autoroute 77 Nord.<\/p>\n<p>Je ne suis PAS sur les pneus \u00e9t\u00e9.<\/p>\n<p>Cette Evo est une voiture en Caroline du Nord. Il n'ya aucune raison pour moi d'\u00eatre sur les pneus d'hiver.<br \/>\n(....) Malgr\u00e9 les \"petits\" d\u00e9g\u00e2ts qui a \u00e9t\u00e9 fait pour la voiture, je suis tr\u00e8s heureux de ne pas avoir heurt\u00e9 quelqu'un ou que la semi remorque ne nous ai pas emboutie. Ma voiture aurait \u00e9t\u00e9 d\u00e9truite et je ne serait probablement plus l\u00e0 pour mettre en ligne cette vid\u00e9o.<\/p>\n<p>Conduisez prudemment! \"<\/p>\n<p>\/ <a href=\"http:\/\/www.facebook.com\/pourrendreobligatoirelespneusneigesenhiver\" hreflang=\"fr\">L'HIVER IL FAUT METTRE DES PNEUS HIVER !!!<\/a><br \/>\n\/ Achat pneus neige carideal pneus discount<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le conducteur \u00e9vite la mort et presque l&rsquo;accident&#8230; &nbsp; Glace noire&#8230;soudain brouillard..une bourre entre une Evo 8 et une mini puis &#8230;.le mur de carambolage, la mini qui percute un monospace, l&rsquo;\u00e9vo qui passe dans l&rsquo;herbe&#8230;.et le semi remorque lanc\u00e9 \u00e0 fond&#8230;.qui passe dans l&rsquo;herbe&#8230;.dieu \u00e9tait l\u00e0 ! La traduction\u00a0: \u00a0\u00bb Cette temp\u00eate est sorti &#8230; <a title=\"Evo 8 evite carambollage sur autoroute verglacee avec brouillard\" class=\"read-more\" href=\"https:\/\/www.carideal.com\/blog\/2012\/01\/05\/evo-8-evite-carambollage-sur-autoroute-verglacee-avec-brouillard\/\" aria-label=\"En savoir plus sur Evo 8 evite carambollage sur autoroute verglacee avec brouillard\">Lire plus<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[13],"tags":[1233,1644,5190],"class_list":["post-498","post","type-post","status-publish","format-standard","hentry","category-pneumatique","tag-accident","tag-neige","tag-pneu-neige"],"wppr_data":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Evo 8 evite carambollage sur autoroute verglacee avec brouillard - Blog auto Carid\u00e9al<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.carideal.com\/blog\/2012\/01\/05\/evo-8-evite-carambollage-sur-autoroute-verglacee-avec-brouillard\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Evo 8 evite carambollage sur autoroute verglacee avec brouillard - Blog auto Carid\u00e9al\" \/>\n<meta property=\"og:description\" content=\"Le conducteur \u00e9vite la mort et presque l&#039;accident... &nbsp; Glace noire...soudain brouillard..une bourre entre une Evo 8 et une mini puis ....le mur de carambolage, la mini qui percute un monospace, l&#039;\u00e9vo qui passe dans l&#039;herbe....et le semi remorque lanc\u00e9 \u00e0 fond....qui passe dans l&#039;herbe....dieu \u00e9tait l\u00e0 ! La traduction\u00a0: &quot; Cette temp\u00eate est sorti ... Lire plus\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.carideal.com\/blog\/2012\/01\/05\/evo-8-evite-carambollage-sur-autoroute-verglacee-avec-brouillard\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog auto Carid\u00e9al\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Carideal.mandataire.automobile\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Carideal.mandataire.automobile\/\" \/>\n<meta property=\"article:published_time\" content=\"2012-01-05T09:49:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-07T15:51:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2016\/03\/logo-carideal-mandataire-automobile.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"N.S Carideal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@caridealauto\" \/>\n<meta name=\"twitter:site\" content=\"@caridealauto\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"N.S Carideal\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.carideal.com\/blog\/2012\/01\/05\/evo-8-evite-carambollage-sur-autoroute-verglacee-avec-brouillard\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/2012\/01\/05\/evo-8-evite-carambollage-sur-autoroute-verglacee-avec-brouillard\/\"},\"author\":{\"name\":\"N.S Carideal\",\"@id\":\"https:\/\/www.carideal.com\/blog\/#\/schema\/person\/985c7e757d1042d647f21bfaf8d41ebc\"},\"headline\":\"Evo 8 evite carambollage sur autoroute verglacee avec brouillard\",\"datePublished\":\"2012-01-05T09:49:00+00:00\",\"dateModified\":\"2020-03-07T15:51:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/2012\/01\/05\/evo-8-evite-carambollage-sur-autoroute-verglacee-avec-brouillard\/\"},\"wordCount\":312,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/#organization\"},\"keywords\":[\"Accident de Voiture\",\"neige\",\"Pneu neige\"],\"articleSection\":[\"Pneumatique\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.carideal.com\/blog\/2012\/01\/05\/evo-8-evite-carambollage-sur-autoroute-verglacee-avec-brouillard\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.carideal.com\/blog\/2012\/01\/05\/evo-8-evite-carambollage-sur-autoroute-verglacee-avec-brouillard\/\",\"url\":\"https:\/\/www.carideal.com\/blog\/2012\/01\/05\/evo-8-evite-carambollage-sur-autoroute-verglacee-avec-brouillard\/\",\"name\":\"Evo 8 evite carambollage sur autoroute verglacee avec brouillard - Blog auto Carid\u00e9al\",\"isPartOf\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/#website\"},\"datePublished\":\"2012-01-05T09:49:00+00:00\",\"dateModified\":\"2020-03-07T15:51:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/2012\/01\/05\/evo-8-evite-carambollage-sur-autoroute-verglacee-avec-brouillard\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.carideal.com\/blog\/2012\/01\/05\/evo-8-evite-carambollage-sur-autoroute-verglacee-avec-brouillard\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.carideal.com\/blog\/2012\/01\/05\/evo-8-evite-carambollage-sur-autoroute-verglacee-avec-brouillard\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog Carid\u00e9al\",\"item\":\"https:\/\/www.carideal.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pneumatique\",\"item\":\"https:\/\/www.carideal.com\/blog\/pneumatique\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Evo 8 evite carambollage sur autoroute verglacee avec brouillard\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.carideal.com\/blog\/#website\",\"url\":\"https:\/\/www.carideal.com\/blog\/\",\"name\":\"Blog auto Carid\u00e9al\",\"description\":\"Actualit\u00e9 auto par des passionn\u00e9s\",\"publisher\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.carideal.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.carideal.com\/blog\/#organization\",\"name\":\"Carideal\",\"url\":\"https:\/\/www.carideal.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.carideal.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2016\/03\/logo-carideal-mandataire-automobile.png\",\"contentUrl\":\"http:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2016\/03\/logo-carideal-mandataire-automobile.png\",\"width\":300,\"height\":300,\"caption\":\"Carideal\"},\"image\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Carideal.mandataire.automobile\",\"https:\/\/x.com\/caridealauto\",\"https:\/\/www.instagram.com\/carideal1\/\",\"https:\/\/www.linkedin.com\/company\/carideal.com\",\"https:\/\/fr.pinterest.com\/schiavonsas\/\",\"https:\/\/www.youtube.com\/user\/caridealsas\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.carideal.com\/blog\/#\/schema\/person\/985c7e757d1042d647f21bfaf8d41ebc\",\"name\":\"N.S Carideal\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.carideal.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/edb7ccdf1a4e3d14aef967760d354d0e?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/edb7ccdf1a4e3d14aef967760d354d0e?s=96&r=g\",\"caption\":\"N.S Carideal\"},\"description\":\"Depuis tout petit fan d'automobile. Il est question d'essayer et de comparer toutes ces voitures qui nous ont fait r\u00e9ver, avant que celles-ci ne devient uniquement des voitures de collection.\",\"sameAs\":[\"http:\/\/www.carideal.com\/blog\",\"https:\/\/www.facebook.com\/Carideal.mandataire.automobile\/\",\"https:\/\/www.linkedin.com\/in\/nschiavon\/\",\"https:\/\/www.youtube.com\/user\/caridealsas\/\"],\"url\":\"https:\/\/www.carideal.com\/blog\/author\/admin_carideal\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Evo 8 evite carambollage sur autoroute verglacee avec brouillard - Blog auto Carid\u00e9al","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.carideal.com\/blog\/2012\/01\/05\/evo-8-evite-carambollage-sur-autoroute-verglacee-avec-brouillard\/","og_locale":"fr_FR","og_type":"article","og_title":"Evo 8 evite carambollage sur autoroute verglacee avec brouillard - Blog auto Carid\u00e9al","og_description":"Le conducteur \u00e9vite la mort et presque l'accident... &nbsp; Glace noire...soudain brouillard..une bourre entre une Evo 8 et une mini puis ....le mur de carambolage, la mini qui percute un monospace, l'\u00e9vo qui passe dans l'herbe....et le semi remorque lanc\u00e9 \u00e0 fond....qui passe dans l'herbe....dieu \u00e9tait l\u00e0 ! La traduction\u00a0: \" Cette temp\u00eate est sorti ... Lire plus","og_url":"https:\/\/www.carideal.com\/blog\/2012\/01\/05\/evo-8-evite-carambollage-sur-autoroute-verglacee-avec-brouillard\/","og_site_name":"Blog auto Carid\u00e9al","article_publisher":"https:\/\/www.facebook.com\/Carideal.mandataire.automobile","article_author":"https:\/\/www.facebook.com\/Carideal.mandataire.automobile\/","article_published_time":"2012-01-05T09:49:00+00:00","article_modified_time":"2020-03-07T15:51:16+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2016\/03\/logo-carideal-mandataire-automobile.png","type":"image\/png"}],"author":"N.S Carideal","twitter_card":"summary_large_image","twitter_creator":"@caridealauto","twitter_site":"@caridealauto","twitter_misc":{"\u00c9crit par":"N.S Carideal","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.carideal.com\/blog\/2012\/01\/05\/evo-8-evite-carambollage-sur-autoroute-verglacee-avec-brouillard\/#article","isPartOf":{"@id":"https:\/\/www.carideal.com\/blog\/2012\/01\/05\/evo-8-evite-carambollage-sur-autoroute-verglacee-avec-brouillard\/"},"author":{"name":"N.S Carideal","@id":"https:\/\/www.carideal.com\/blog\/#\/schema\/person\/985c7e757d1042d647f21bfaf8d41ebc"},"headline":"Evo 8 evite carambollage sur autoroute verglacee avec brouillard","datePublished":"2012-01-05T09:49:00+00:00","dateModified":"2020-03-07T15:51:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.carideal.com\/blog\/2012\/01\/05\/evo-8-evite-carambollage-sur-autoroute-verglacee-avec-brouillard\/"},"wordCount":312,"commentCount":0,"publisher":{"@id":"https:\/\/www.carideal.com\/blog\/#organization"},"keywords":["Accident de Voiture","neige","Pneu neige"],"articleSection":["Pneumatique"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.carideal.com\/blog\/2012\/01\/05\/evo-8-evite-carambollage-sur-autoroute-verglacee-avec-brouillard\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.carideal.com\/blog\/2012\/01\/05\/evo-8-evite-carambollage-sur-autoroute-verglacee-avec-brouillard\/","url":"https:\/\/www.carideal.com\/blog\/2012\/01\/05\/evo-8-evite-carambollage-sur-autoroute-verglacee-avec-brouillard\/","name":"Evo 8 evite carambollage sur autoroute verglacee avec brouillard - Blog auto Carid\u00e9al","isPartOf":{"@id":"https:\/\/www.carideal.com\/blog\/#website"},"datePublished":"2012-01-05T09:49:00+00:00","dateModified":"2020-03-07T15:51:16+00:00","breadcrumb":{"@id":"https:\/\/www.carideal.com\/blog\/2012\/01\/05\/evo-8-evite-carambollage-sur-autoroute-verglacee-avec-brouillard\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.carideal.com\/blog\/2012\/01\/05\/evo-8-evite-carambollage-sur-autoroute-verglacee-avec-brouillard\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.carideal.com\/blog\/2012\/01\/05\/evo-8-evite-carambollage-sur-autoroute-verglacee-avec-brouillard\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog Carid\u00e9al","item":"https:\/\/www.carideal.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Pneumatique","item":"https:\/\/www.carideal.com\/blog\/pneumatique\/"},{"@type":"ListItem","position":3,"name":"Evo 8 evite carambollage sur autoroute verglacee avec brouillard"}]},{"@type":"WebSite","@id":"https:\/\/www.carideal.com\/blog\/#website","url":"https:\/\/www.carideal.com\/blog\/","name":"Blog auto Carid\u00e9al","description":"Actualit\u00e9 auto par des passionn\u00e9s","publisher":{"@id":"https:\/\/www.carideal.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.carideal.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.carideal.com\/blog\/#organization","name":"Carideal","url":"https:\/\/www.carideal.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.carideal.com\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2016\/03\/logo-carideal-mandataire-automobile.png","contentUrl":"http:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2016\/03\/logo-carideal-mandataire-automobile.png","width":300,"height":300,"caption":"Carideal"},"image":{"@id":"https:\/\/www.carideal.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Carideal.mandataire.automobile","https:\/\/x.com\/caridealauto","https:\/\/www.instagram.com\/carideal1\/","https:\/\/www.linkedin.com\/company\/carideal.com","https:\/\/fr.pinterest.com\/schiavonsas\/","https:\/\/www.youtube.com\/user\/caridealsas"]},{"@type":"Person","@id":"https:\/\/www.carideal.com\/blog\/#\/schema\/person\/985c7e757d1042d647f21bfaf8d41ebc","name":"N.S Carideal","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.carideal.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/edb7ccdf1a4e3d14aef967760d354d0e?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/edb7ccdf1a4e3d14aef967760d354d0e?s=96&r=g","caption":"N.S Carideal"},"description":"Depuis tout petit fan d'automobile. Il est question d'essayer et de comparer toutes ces voitures qui nous ont fait r\u00e9ver, avant que celles-ci ne devient uniquement des voitures de collection.","sameAs":["http:\/\/www.carideal.com\/blog","https:\/\/www.facebook.com\/Carideal.mandataire.automobile\/","https:\/\/www.linkedin.com\/in\/nschiavon\/","https:\/\/www.youtube.com\/user\/caridealsas\/"],"url":"https:\/\/www.carideal.com\/blog\/author\/admin_carideal\/"}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"wppr-widget":false},"uagb_author_info":{"display_name":"N.S Carideal","author_link":"https:\/\/www.carideal.com\/blog\/author\/admin_carideal\/"},"uagb_comment_info":0,"uagb_excerpt":"Le conducteur \u00e9vite la mort et presque l'accident... &nbsp; Glace noire...soudain brouillard..une bourre entre une Evo 8 et une mini puis ....le mur de carambolage, la mini qui percute un monospace, l'\u00e9vo qui passe dans l'herbe....et le semi remorque lanc\u00e9 \u00e0 fond....qui passe dans l'herbe....dieu \u00e9tait l\u00e0 ! La traduction\u00a0: \" Cette temp\u00eate est sorti\u2026","_links":{"self":[{"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/posts\/498"}],"collection":[{"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/comments?post=498"}],"version-history":[{"count":0,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/posts\/498\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/media?parent=498"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/categories?post=498"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/tags?post=498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}