{"id":478,"date":"2011-09-14T17:08:00","date_gmt":"2011-09-14T17:08:00","guid":{"rendered":"http:\/\/carideal.com\/blog\/?p=478"},"modified":"2011-09-14T17:08:00","modified_gmt":"2011-09-14T17:08:00","slug":"le-nouveau-tube-de-citroen-le-tubik","status":"publish","type":"post","link":"https:\/\/www.carideal.com\/blog\/2011\/09\/14\/le-nouveau-tube-de-citroen-le-tubik\/","title":{"rendered":"Le nouveau tube de Citroen : le TUBIK"},"content":{"rendered":"<p><img decoding=\"async\" src=\"\/blog\/public\/.citroen_tubik_carideal-mandataire-automobile_m.jpg\" alt=\"citroen_tubik_carideal-mandataire-automobile.jpg\" title=\"citroen_tubik_carideal-mandataire-automobile.jpg, sept. 2011\" \/><\/p>\n<blockquote>\n<p>Le Citroen Tubik<\/p>\n<\/blockquote>\n<p>Une \u00e9tude de style de Citroen qui surfe sur la vague nostalgique en nous rapellant, pour ceux qui l'on connu , LOL le vieux tube <a href=\"\/blog\/index.php?tag\/HY\">HY<\/a>&nbsp;: <img decoding=\"async\" src=\"\/blog\/public\/.citroen-tube-hy-carideal-mandataire_automobile_t.jpg\" alt=\"citroen-tube-hy-carideal-mandataire_automobile.jpg\" title=\"citroen-tube-hy-carideal-mandataire_automobile.jpg, sept. 2011\" \/><\/p>\n<blockquote>\n<p>L'anc\u00eatre le Tube Citroen HY en t\u00f4le ondul\u00e9e<\/p>\n<\/blockquote>\n<p>Ce concept car a sans doute diff\u00e9rentes inspirations, mais le r\u00e9sultat est l\u00e0 un m\u00e9lange des ann\u00e9es 50 et 60 avec sa bouille en nez de cochon caract\u00e9ristique. Pour m\u00e9moire le HY fut commercialis\u00e9 de 1948 \u00e0 1981. Ce concept reprend la calandre de l'\u00e9tude Citroen R\u00e9volt et qui pourrait bien \u00eatre repris par les futures mod\u00e8les de la marque \u00e0 commencer par le Citroen C4 Picasso de 2014.<br \/>\n<img decoding=\"async\" src=\"\/blog\/public\/.citroen_tubik_carideal-mandataire-automobile-1_m.jpg\" alt=\"citroen_tubik_carideal-mandataire-automobile-1.jpg\" title=\"citroen_tubik_carideal-mandataire-automobile-1.jpg, sept. 2011\" \/><\/p>\n<blockquote>\n<p>Le Citroen Tubik au salon de Francfort<\/p>\n<\/blockquote>\n<p>Citroen nous pr\u00e9sente l\u00e0 un montre beaucoup plus gros que le C8, avec 4.85m de long, soit 10 cm de plus et surtout 2m de large par 2 m\u00e8tres de haut&nbsp;! <br \/>\n<img decoding=\"async\" src=\"\/blog\/public\/.citroen_tubik_carideal-mandataire-automobile-4_m.jpg\" alt=\"citroen_tubik_carideal-mandataire-automobile-4.jpg\" title=\"citroen_tubik_carideal-mandataire-automobile-4.jpg, sept. 2011\" \/><\/p>\n<blockquote>\n<p>La face avant du Citroen Tubik impressionante<\/p>\n<\/blockquote>\n<p>Les designers se sont inspir\u00e9 du fuselage d'avion pour dessiner et lisser les cot\u00e9s ce qui all\u00e8ge quelque peu la silhouette.<br \/>\n<img decoding=\"async\" src=\"\/blog\/public\/.citroen_tubik_carideal-mandataire-automobile-3_m.jpg\" alt=\"citroen_tubik_carideal-mandataire-automobile-3.jpg\" title=\"citroen_tubik_carideal-mandataire-automobile-3.jpg, sept. 2011\" \/><\/p>\n<blockquote>\n<p>le profil en forme de fuselage<\/p>\n<\/blockquote>\n<p>Le Tubik transporte 9 personnes et leurs bagages dans un coffre sous le plancher. A l'int\u00e9rieur les passagers trouveront de la place beaucoup de place dans une ambiance \"lounge\" voir m\u00eame discotheque....avec lumi\u00e8res tamis\u00e9es et velours violet.<br \/>\n<img decoding=\"async\" src=\"\/blog\/public\/.citroen_tubik_carideal-mandataire-automobile-5_m.jpg\" alt=\"citroen_tubik_carideal-mandataire-automobile-5.jpg\" title=\"citroen_tubik_carideal-mandataire-automobile-5.jpg, sept. 2011\" \/><\/p>\n<blockquote>\n<p>L'invitation au voyage en Tubik<\/p>\n<\/blockquote>\n<p>La banquette avant peut se retourner pour faire face aux passager arri\u00e8res. Le Tubik est \u00e9quip\u00e9 de la technologie Hybrid4, avec un moteur diesel sur les roues avants, et un \u00e9lectromoteur pour les roues arri\u00e8res.<\/p>\n<p>\/ <a href=\"\/blog\/index.php?post\/2011\/09\/08\/Nouvelle-Peugeot-3008-Hybrid4\">Peugeot 3008 hybrid4<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Citroen Tubik Une \u00e9tude de style de Citroen qui surfe sur la vague nostalgique en nous rapellant, pour ceux qui l&rsquo;on connu , LOL le vieux tube HY&nbsp;: L&rsquo;anc\u00eatre le Tube Citroen HY en t\u00f4le ondul\u00e9e Ce concept car a sans doute diff\u00e9rentes inspirations, mais le r\u00e9sultat est l\u00e0 un m\u00e9lange des ann\u00e9es 50 &#8230; <a title=\"Le nouveau tube de Citroen : le TUBIK\" class=\"read-more\" href=\"https:\/\/www.carideal.com\/blog\/2011\/09\/14\/le-nouveau-tube-de-citroen-le-tubik\/\" aria-label=\"En savoir plus sur Le nouveau tube de Citroen : le TUBIK\">Lire plus<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[9],"tags":[],"class_list":["post-478","post","type-post","status-publish","format-standard","hentry","category-divers"],"wppr_data":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le nouveau tube de Citroen : le TUBIK - Blog auto Carid\u00e9al<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.carideal.com\/blog\/2011\/09\/14\/le-nouveau-tube-de-citroen-le-tubik\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le nouveau tube de Citroen : le TUBIK - Blog auto Carid\u00e9al\" \/>\n<meta property=\"og:description\" content=\"Le Citroen Tubik Une \u00e9tude de style de Citroen qui surfe sur la vague nostalgique en nous rapellant, pour ceux qui l&#039;on connu , LOL le vieux tube HY&nbsp;: L&#039;anc\u00eatre le Tube Citroen HY en t\u00f4le ondul\u00e9e Ce concept car a sans doute diff\u00e9rentes inspirations, mais le r\u00e9sultat est l\u00e0 un m\u00e9lange des ann\u00e9es 50 ... Lire plus\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.carideal.com\/blog\/2011\/09\/14\/le-nouveau-tube-de-citroen-le-tubik\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog auto Carid\u00e9al\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Carideal.mandataire.automobile\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Carideal.mandataire.automobile\/\" \/>\n<meta property=\"article:published_time\" content=\"2011-09-14T17:08:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2016\/03\/logo-carideal-mandataire-automobile.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"N.S Carideal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@caridealauto\" \/>\n<meta name=\"twitter:site\" content=\"@caridealauto\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"N.S Carideal\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.carideal.com\\\/blog\\\/2011\\\/09\\\/14\\\/le-nouveau-tube-de-citroen-le-tubik\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.carideal.com\\\/blog\\\/2011\\\/09\\\/14\\\/le-nouveau-tube-de-citroen-le-tubik\\\/\"},\"author\":{\"name\":\"N.S Carideal\",\"@id\":\"https:\\\/\\\/www.carideal.com\\\/blog\\\/#\\\/schema\\\/person\\\/985c7e757d1042d647f21bfaf8d41ebc\"},\"headline\":\"Le nouveau tube de Citroen : le TUBIK\",\"datePublished\":\"2011-09-14T17:08:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.carideal.com\\\/blog\\\/2011\\\/09\\\/14\\\/le-nouveau-tube-de-citroen-le-tubik\\\/\"},\"wordCount\":278,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.carideal.com\\\/blog\\\/#organization\"},\"articleSection\":[\"Divers\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.carideal.com\\\/blog\\\/2011\\\/09\\\/14\\\/le-nouveau-tube-de-citroen-le-tubik\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.carideal.com\\\/blog\\\/2011\\\/09\\\/14\\\/le-nouveau-tube-de-citroen-le-tubik\\\/\",\"url\":\"https:\\\/\\\/www.carideal.com\\\/blog\\\/2011\\\/09\\\/14\\\/le-nouveau-tube-de-citroen-le-tubik\\\/\",\"name\":\"Le nouveau tube de Citroen : le TUBIK - Blog auto Carid\u00e9al\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.carideal.com\\\/blog\\\/#website\"},\"datePublished\":\"2011-09-14T17:08:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.carideal.com\\\/blog\\\/2011\\\/09\\\/14\\\/le-nouveau-tube-de-citroen-le-tubik\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.carideal.com\\\/blog\\\/2011\\\/09\\\/14\\\/le-nouveau-tube-de-citroen-le-tubik\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.carideal.com\\\/blog\\\/2011\\\/09\\\/14\\\/le-nouveau-tube-de-citroen-le-tubik\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog Carid\u00e9al\",\"item\":\"https:\\\/\\\/www.carideal.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Divers\",\"item\":\"https:\\\/\\\/www.carideal.com\\\/blog\\\/divers\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Le nouveau tube de Citroen : le TUBIK\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.carideal.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.carideal.com\\\/blog\\\/\",\"name\":\"Blog auto Carid\u00e9al\",\"description\":\"Actualit\u00e9 auto par des passionn\u00e9s\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.carideal.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.carideal.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.carideal.com\\\/blog\\\/#organization\",\"name\":\"Carideal\",\"url\":\"https:\\\/\\\/www.carideal.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.carideal.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.carideal.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/03\\\/logo-carideal-mandataire-automobile.png\",\"contentUrl\":\"http:\\\/\\\/www.carideal.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/03\\\/logo-carideal-mandataire-automobile.png\",\"width\":300,\"height\":300,\"caption\":\"Carideal\"},\"image\":{\"@id\":\"https:\\\/\\\/www.carideal.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Carideal.mandataire.automobile\",\"https:\\\/\\\/x.com\\\/caridealauto\",\"https:\\\/\\\/www.instagram.com\\\/carideal1\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/carideal.com\",\"https:\\\/\\\/fr.pinterest.com\\\/schiavonsas\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/caridealsas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.carideal.com\\\/blog\\\/#\\\/schema\\\/person\\\/985c7e757d1042d647f21bfaf8d41ebc\",\"name\":\"N.S Carideal\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6f5ba979b007ea5262e0fe9d7c158f488589e92229a20c2c59e0c4e9de7177df?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6f5ba979b007ea5262e0fe9d7c158f488589e92229a20c2c59e0c4e9de7177df?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6f5ba979b007ea5262e0fe9d7c158f488589e92229a20c2c59e0c4e9de7177df?s=96&r=g\",\"caption\":\"N.S Carideal\"},\"description\":\"Depuis tout petit fan d'automobile. Il est question d'essayer et de comparer toutes ces voitures qui nous ont fait r\u00e9ver, avant que celles-ci ne devient uniquement des voitures de collection.\",\"sameAs\":[\"http:\\\/\\\/www.carideal.com\\\/blog\",\"https:\\\/\\\/www.facebook.com\\\/Carideal.mandataire.automobile\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/nschiavon\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/caridealsas\\\/\"],\"url\":\"https:\\\/\\\/www.carideal.com\\\/blog\\\/author\\\/admin_carideal\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le nouveau tube de Citroen : le TUBIK - Blog auto Carid\u00e9al","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.carideal.com\/blog\/2011\/09\/14\/le-nouveau-tube-de-citroen-le-tubik\/","og_locale":"fr_FR","og_type":"article","og_title":"Le nouveau tube de Citroen : le TUBIK - Blog auto Carid\u00e9al","og_description":"Le Citroen Tubik Une \u00e9tude de style de Citroen qui surfe sur la vague nostalgique en nous rapellant, pour ceux qui l'on connu , LOL le vieux tube HY&nbsp;: L'anc\u00eatre le Tube Citroen HY en t\u00f4le ondul\u00e9e Ce concept car a sans doute diff\u00e9rentes inspirations, mais le r\u00e9sultat est l\u00e0 un m\u00e9lange des ann\u00e9es 50 ... Lire plus","og_url":"https:\/\/www.carideal.com\/blog\/2011\/09\/14\/le-nouveau-tube-de-citroen-le-tubik\/","og_site_name":"Blog auto Carid\u00e9al","article_publisher":"https:\/\/www.facebook.com\/Carideal.mandataire.automobile","article_author":"https:\/\/www.facebook.com\/Carideal.mandataire.automobile\/","article_published_time":"2011-09-14T17:08:00+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2016\/03\/logo-carideal-mandataire-automobile.png","type":"image\/png"}],"author":"N.S Carideal","twitter_card":"summary_large_image","twitter_creator":"@caridealauto","twitter_site":"@caridealauto","twitter_misc":{"\u00c9crit par":"N.S Carideal","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.carideal.com\/blog\/2011\/09\/14\/le-nouveau-tube-de-citroen-le-tubik\/#article","isPartOf":{"@id":"https:\/\/www.carideal.com\/blog\/2011\/09\/14\/le-nouveau-tube-de-citroen-le-tubik\/"},"author":{"name":"N.S Carideal","@id":"https:\/\/www.carideal.com\/blog\/#\/schema\/person\/985c7e757d1042d647f21bfaf8d41ebc"},"headline":"Le nouveau tube de Citroen : le TUBIK","datePublished":"2011-09-14T17:08:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.carideal.com\/blog\/2011\/09\/14\/le-nouveau-tube-de-citroen-le-tubik\/"},"wordCount":278,"commentCount":0,"publisher":{"@id":"https:\/\/www.carideal.com\/blog\/#organization"},"articleSection":["Divers"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.carideal.com\/blog\/2011\/09\/14\/le-nouveau-tube-de-citroen-le-tubik\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.carideal.com\/blog\/2011\/09\/14\/le-nouveau-tube-de-citroen-le-tubik\/","url":"https:\/\/www.carideal.com\/blog\/2011\/09\/14\/le-nouveau-tube-de-citroen-le-tubik\/","name":"Le nouveau tube de Citroen : le TUBIK - Blog auto Carid\u00e9al","isPartOf":{"@id":"https:\/\/www.carideal.com\/blog\/#website"},"datePublished":"2011-09-14T17:08:00+00:00","breadcrumb":{"@id":"https:\/\/www.carideal.com\/blog\/2011\/09\/14\/le-nouveau-tube-de-citroen-le-tubik\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.carideal.com\/blog\/2011\/09\/14\/le-nouveau-tube-de-citroen-le-tubik\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.carideal.com\/blog\/2011\/09\/14\/le-nouveau-tube-de-citroen-le-tubik\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog Carid\u00e9al","item":"https:\/\/www.carideal.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Divers","item":"https:\/\/www.carideal.com\/blog\/divers\/"},{"@type":"ListItem","position":3,"name":"Le nouveau tube de Citroen : le TUBIK"}]},{"@type":"WebSite","@id":"https:\/\/www.carideal.com\/blog\/#website","url":"https:\/\/www.carideal.com\/blog\/","name":"Blog auto Carid\u00e9al","description":"Actualit\u00e9 auto par des passionn\u00e9s","publisher":{"@id":"https:\/\/www.carideal.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.carideal.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.carideal.com\/blog\/#organization","name":"Carideal","url":"https:\/\/www.carideal.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.carideal.com\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2016\/03\/logo-carideal-mandataire-automobile.png","contentUrl":"http:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2016\/03\/logo-carideal-mandataire-automobile.png","width":300,"height":300,"caption":"Carideal"},"image":{"@id":"https:\/\/www.carideal.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Carideal.mandataire.automobile","https:\/\/x.com\/caridealauto","https:\/\/www.instagram.com\/carideal1\/","https:\/\/www.linkedin.com\/company\/carideal.com","https:\/\/fr.pinterest.com\/schiavonsas\/","https:\/\/www.youtube.com\/user\/caridealsas"]},{"@type":"Person","@id":"https:\/\/www.carideal.com\/blog\/#\/schema\/person\/985c7e757d1042d647f21bfaf8d41ebc","name":"N.S Carideal","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/6f5ba979b007ea5262e0fe9d7c158f488589e92229a20c2c59e0c4e9de7177df?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6f5ba979b007ea5262e0fe9d7c158f488589e92229a20c2c59e0c4e9de7177df?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6f5ba979b007ea5262e0fe9d7c158f488589e92229a20c2c59e0c4e9de7177df?s=96&r=g","caption":"N.S Carideal"},"description":"Depuis tout petit fan d'automobile. Il est question d'essayer et de comparer toutes ces voitures qui nous ont fait r\u00e9ver, avant que celles-ci ne devient uniquement des voitures de collection.","sameAs":["http:\/\/www.carideal.com\/blog","https:\/\/www.facebook.com\/Carideal.mandataire.automobile\/","https:\/\/www.linkedin.com\/in\/nschiavon\/","https:\/\/www.youtube.com\/user\/caridealsas\/"],"url":"https:\/\/www.carideal.com\/blog\/author\/admin_carideal\/"}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"wppr-widget":false},"uagb_author_info":{"display_name":"N.S Carideal","author_link":"https:\/\/www.carideal.com\/blog\/author\/admin_carideal\/"},"uagb_comment_info":0,"uagb_excerpt":"Le Citroen Tubik Une \u00e9tude de style de Citroen qui surfe sur la vague nostalgique en nous rapellant, pour ceux qui l'on connu , LOL le vieux tube HY&nbsp;: L'anc\u00eatre le Tube Citroen HY en t\u00f4le ondul\u00e9e Ce concept car a sans doute diff\u00e9rentes inspirations, mais le r\u00e9sultat est l\u00e0 un m\u00e9lange des ann\u00e9es 50\u2026","_links":{"self":[{"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/posts\/478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/comments?post=478"}],"version-history":[{"count":0,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/posts\/478\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/media?parent=478"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/categories?post=478"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/tags?post=478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}