{"id":4581,"date":"2007-12-10T00:00:00","date_gmt":"2007-12-10T00:00:00","guid":{"rendered":"http:\/\/www.carideal.com\/blog\/2007\/12\/10\/une-bourse-a-suresne-pour-passer-le-permis-de-conduire\/"},"modified":"2015-07-06T12:40:17","modified_gmt":"2015-07-06T10:40:17","slug":"une-bourse-a-suresne-pour-passer-le-permis-de-conduire","status":"publish","type":"post","link":"https:\/\/www.carideal.com\/blog\/2007\/12\/10\/une-bourse-a-suresne-pour-passer-le-permis-de-conduire\/","title":{"rendered":"Une bourse \u00e0 Suresne pour aider \u00e0 passer le permis de conduire"},"content":{"rendered":"<div><img decoding=\"async\" src=\"http:\/\/www.carideal.com\/images_actualite\/permisconduirecarideal-1194849529.jpg\" alt=\"\" \/>Tout le monde a droit au permis<\/p>\n<\/div>\n<div><img decoding=\"async\" src=\"http:\/\/www.carideal.com\/images_actualite\/bussereaupermisdeconduirecarideal-1197271093.jpg\" alt=\"\" \/>L'initiative de M Bussereau pour le permis de conduire<\/p>\n<\/div>\n<p>M Bussereau le secretaire d'etat aux transport, s'est rendu \u00e0 Suresne dans le 92 afin de promouvoir un nouveau dispositif pour le permis de conduire. Il souhaite en effet que chaque ville propose une bourse pour passer le permis de conduire en \u00e9change d'heure de travail d'int\u00e9ret general. Ce syst\u00e8me a \u00e9t\u00e9 mis en place en 2005 a Suresne, et 74 jeunes entre 18 et 25 ans en ont profit\u00e9s. L'aide est plafonn\u00e9e \u00e0 1200 \u20ac\u00a0par\u00a0 permis et couvre jusque 80% des frais. En contrepartie les jeunes signent une charte ou ils s'engagent a travailler jusque 40 heures pour le compte de la mairie. M Bussereau a demand\u00e9 a ses services d'elaborer d'un dossier type qu'il pourrait soumettre \u00e0 l'ensemble des communes avant la fin 2007.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tout le monde a droit au permis L&rsquo;initiative de M Bussereau pour le permis de conduire M Bussereau le secretaire d&rsquo;etat aux transport, s&rsquo;est rendu \u00e0 Suresne dans le 92 afin de promouvoir un nouveau dispositif pour le permis de conduire. Il souhaite en effet que chaque ville propose une bourse pour passer le permis &#8230; <a title=\"Une bourse \u00e0 Suresne pour aider \u00e0 passer le permis de conduire\" class=\"read-more\" href=\"https:\/\/www.carideal.com\/blog\/2007\/12\/10\/une-bourse-a-suresne-pour-passer-le-permis-de-conduire\/\" aria-label=\"En savoir plus sur Une bourse \u00e0 Suresne pour aider \u00e0 passer le permis de conduire\">Lire plus<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[21],"tags":[2500],"class_list":["post-4581","post","type-post","status-publish","format-standard","hentry","category-actualites-auto","tag-permis-de-conduire"],"wppr_data":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Une bourse \u00e0 Suresne pour aider \u00e0 passer le permis de conduire - Blog auto Carid\u00e9al<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.carideal.com\/blog\/2007\/12\/10\/une-bourse-a-suresne-pour-passer-le-permis-de-conduire\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Une bourse \u00e0 Suresne pour aider \u00e0 passer le permis de conduire - Blog auto Carid\u00e9al\" \/>\n<meta property=\"og:description\" content=\"Tout le monde a droit au permis L&#039;initiative de M Bussereau pour le permis de conduire M Bussereau le secretaire d&#039;etat aux transport, s&#039;est rendu \u00e0 Suresne dans le 92 afin de promouvoir un nouveau dispositif pour le permis de conduire. Il souhaite en effet que chaque ville propose une bourse pour passer le permis ... Lire plus\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.carideal.com\/blog\/2007\/12\/10\/une-bourse-a-suresne-pour-passer-le-permis-de-conduire\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog auto Carid\u00e9al\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Carideal.mandataire.automobile\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/nicolas.schiavon.39\" \/>\n<meta property=\"article:published_time\" content=\"2007-12-10T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-07-06T10:40:17+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.carideal.com\/images_actualite\/permisconduirecarideal-1194849529.jpg\" \/>\n<meta name=\"author\" content=\"Nicolas SCHIAVON\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@caridealauto\" \/>\n<meta name=\"twitter:site\" content=\"@caridealauto\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nicolas SCHIAVON\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.carideal.com\/blog\/2007\/12\/10\/une-bourse-a-suresne-pour-passer-le-permis-de-conduire\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/2007\/12\/10\/une-bourse-a-suresne-pour-passer-le-permis-de-conduire\/\"},\"author\":{\"name\":\"Nicolas SCHIAVON\",\"@id\":\"https:\/\/www.carideal.com\/blog\/#\/schema\/person\/cd95dc7919660de90d31b366f85be1ec\"},\"headline\":\"Une bourse \u00e0 Suresne pour aider \u00e0 passer le permis de conduire\",\"datePublished\":\"2007-12-10T00:00:00+00:00\",\"dateModified\":\"2015-07-06T10:40:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/2007\/12\/10\/une-bourse-a-suresne-pour-passer-le-permis-de-conduire\/\"},\"wordCount\":144,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/2007\/12\/10\/une-bourse-a-suresne-pour-passer-le-permis-de-conduire\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/www.carideal.com\/images_actualite\/permisconduirecarideal-1194849529.jpg\",\"keywords\":[\"Permis de conduire\"],\"articleSection\":[\"Actualit\u00e9 automobile\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.carideal.com\/blog\/2007\/12\/10\/une-bourse-a-suresne-pour-passer-le-permis-de-conduire\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.carideal.com\/blog\/2007\/12\/10\/une-bourse-a-suresne-pour-passer-le-permis-de-conduire\/\",\"url\":\"https:\/\/www.carideal.com\/blog\/2007\/12\/10\/une-bourse-a-suresne-pour-passer-le-permis-de-conduire\/\",\"name\":\"Une bourse \u00e0 Suresne pour aider \u00e0 passer le permis de conduire - Blog auto Carid\u00e9al\",\"isPartOf\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/2007\/12\/10\/une-bourse-a-suresne-pour-passer-le-permis-de-conduire\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/2007\/12\/10\/une-bourse-a-suresne-pour-passer-le-permis-de-conduire\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/www.carideal.com\/images_actualite\/permisconduirecarideal-1194849529.jpg\",\"datePublished\":\"2007-12-10T00:00:00+00:00\",\"dateModified\":\"2015-07-06T10:40:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/2007\/12\/10\/une-bourse-a-suresne-pour-passer-le-permis-de-conduire\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.carideal.com\/blog\/2007\/12\/10\/une-bourse-a-suresne-pour-passer-le-permis-de-conduire\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.carideal.com\/blog\/2007\/12\/10\/une-bourse-a-suresne-pour-passer-le-permis-de-conduire\/#primaryimage\",\"url\":\"http:\/\/www.carideal.com\/images_actualite\/permisconduirecarideal-1194849529.jpg\",\"contentUrl\":\"http:\/\/www.carideal.com\/images_actualite\/permisconduirecarideal-1194849529.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.carideal.com\/blog\/2007\/12\/10\/une-bourse-a-suresne-pour-passer-le-permis-de-conduire\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog Carid\u00e9al\",\"item\":\"https:\/\/www.carideal.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Actualit\u00e9 automobile\",\"item\":\"https:\/\/www.carideal.com\/blog\/actualites-auto\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Une bourse \u00e0 Suresne pour aider \u00e0 passer le permis de conduire\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.carideal.com\/blog\/#website\",\"url\":\"https:\/\/www.carideal.com\/blog\/\",\"name\":\"Blog auto Carid\u00e9al\",\"description\":\"Actualit\u00e9 auto par des passionn\u00e9s\",\"publisher\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.carideal.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.carideal.com\/blog\/#organization\",\"name\":\"Carideal\",\"url\":\"https:\/\/www.carideal.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.carideal.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2016\/03\/logo-carideal-mandataire-automobile.png\",\"contentUrl\":\"http:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2016\/03\/logo-carideal-mandataire-automobile.png\",\"width\":300,\"height\":300,\"caption\":\"Carideal\"},\"image\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Carideal.mandataire.automobile\",\"https:\/\/x.com\/caridealauto\",\"https:\/\/www.instagram.com\/carideal1\/\",\"https:\/\/www.linkedin.com\/company\/carideal.com\",\"https:\/\/fr.pinterest.com\/schiavonsas\/\",\"https:\/\/www.youtube.com\/user\/caridealsas\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.carideal.com\/blog\/#\/schema\/person\/cd95dc7919660de90d31b366f85be1ec\",\"name\":\"Nicolas SCHIAVON\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.carideal.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c17e55009e671d92cc7f5dc837dc418a?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c17e55009e671d92cc7f5dc837dc418a?s=96&r=g\",\"caption\":\"Nicolas SCHIAVON\"},\"description\":\"Nicolas Schiavon est tomb\u00e9 tout petit dans la marmite automobile. Ayant eu un garage de marque automobile, mandataire automobile de la premi\u00e8re heure d\u00e8s 1999. Nicolas a cr\u00e9\u00e9 ces premiers sites de vente de voiture et blog automobile d\u00e8s 1994. Carideal est n\u00e9 le 15 d\u00e9cembre 2000 de la volont\u00e9 de vendre des voitures d'occasions en ligne puis des voitures neuves. Il a pu essayer beaucoup de voitures tr\u00e8s diff\u00e9rentes et ayant eu personnellement quelques belles autos, Subaru Impreza, Mitsubishi Lancer Evo 7, Porsche 911, Ferrari Testarrossa, Audi RS3, RS4 et j'en passe...\",\"sameAs\":[\"http:\/\/www.carideal.com\",\"https:\/\/www.facebook.com\/nicolas.schiavon.39\",\"https:\/\/www.instagram.com\/carideal1\/\",\"https:\/\/www.linkedin.com\/in\/nschiavon\/\",\"https:\/\/x.com\/caridealauto\",\"https:\/\/www.youtube.com\/user\/caridealsas\/\"],\"url\":\"https:\/\/www.carideal.com\/blog\/author\/nschiavon\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Une bourse \u00e0 Suresne pour aider \u00e0 passer le permis de conduire - Blog auto Carid\u00e9al","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.carideal.com\/blog\/2007\/12\/10\/une-bourse-a-suresne-pour-passer-le-permis-de-conduire\/","og_locale":"fr_FR","og_type":"article","og_title":"Une bourse \u00e0 Suresne pour aider \u00e0 passer le permis de conduire - Blog auto Carid\u00e9al","og_description":"Tout le monde a droit au permis L'initiative de M Bussereau pour le permis de conduire M Bussereau le secretaire d'etat aux transport, s'est rendu \u00e0 Suresne dans le 92 afin de promouvoir un nouveau dispositif pour le permis de conduire. Il souhaite en effet que chaque ville propose une bourse pour passer le permis ... Lire plus","og_url":"https:\/\/www.carideal.com\/blog\/2007\/12\/10\/une-bourse-a-suresne-pour-passer-le-permis-de-conduire\/","og_site_name":"Blog auto Carid\u00e9al","article_publisher":"https:\/\/www.facebook.com\/Carideal.mandataire.automobile","article_author":"https:\/\/www.facebook.com\/nicolas.schiavon.39","article_published_time":"2007-12-10T00:00:00+00:00","article_modified_time":"2015-07-06T10:40:17+00:00","og_image":[{"url":"http:\/\/www.carideal.com\/images_actualite\/permisconduirecarideal-1194849529.jpg","type":"","width":"","height":""}],"author":"Nicolas SCHIAVON","twitter_card":"summary_large_image","twitter_creator":"@caridealauto","twitter_site":"@caridealauto","twitter_misc":{"\u00c9crit par":"Nicolas SCHIAVON","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.carideal.com\/blog\/2007\/12\/10\/une-bourse-a-suresne-pour-passer-le-permis-de-conduire\/#article","isPartOf":{"@id":"https:\/\/www.carideal.com\/blog\/2007\/12\/10\/une-bourse-a-suresne-pour-passer-le-permis-de-conduire\/"},"author":{"name":"Nicolas SCHIAVON","@id":"https:\/\/www.carideal.com\/blog\/#\/schema\/person\/cd95dc7919660de90d31b366f85be1ec"},"headline":"Une bourse \u00e0 Suresne pour aider \u00e0 passer le permis de conduire","datePublished":"2007-12-10T00:00:00+00:00","dateModified":"2015-07-06T10:40:17+00:00","mainEntityOfPage":{"@id":"https:\/\/www.carideal.com\/blog\/2007\/12\/10\/une-bourse-a-suresne-pour-passer-le-permis-de-conduire\/"},"wordCount":144,"commentCount":0,"publisher":{"@id":"https:\/\/www.carideal.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.carideal.com\/blog\/2007\/12\/10\/une-bourse-a-suresne-pour-passer-le-permis-de-conduire\/#primaryimage"},"thumbnailUrl":"http:\/\/www.carideal.com\/images_actualite\/permisconduirecarideal-1194849529.jpg","keywords":["Permis de conduire"],"articleSection":["Actualit\u00e9 automobile"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.carideal.com\/blog\/2007\/12\/10\/une-bourse-a-suresne-pour-passer-le-permis-de-conduire\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.carideal.com\/blog\/2007\/12\/10\/une-bourse-a-suresne-pour-passer-le-permis-de-conduire\/","url":"https:\/\/www.carideal.com\/blog\/2007\/12\/10\/une-bourse-a-suresne-pour-passer-le-permis-de-conduire\/","name":"Une bourse \u00e0 Suresne pour aider \u00e0 passer le permis de conduire - Blog auto Carid\u00e9al","isPartOf":{"@id":"https:\/\/www.carideal.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.carideal.com\/blog\/2007\/12\/10\/une-bourse-a-suresne-pour-passer-le-permis-de-conduire\/#primaryimage"},"image":{"@id":"https:\/\/www.carideal.com\/blog\/2007\/12\/10\/une-bourse-a-suresne-pour-passer-le-permis-de-conduire\/#primaryimage"},"thumbnailUrl":"http:\/\/www.carideal.com\/images_actualite\/permisconduirecarideal-1194849529.jpg","datePublished":"2007-12-10T00:00:00+00:00","dateModified":"2015-07-06T10:40:17+00:00","breadcrumb":{"@id":"https:\/\/www.carideal.com\/blog\/2007\/12\/10\/une-bourse-a-suresne-pour-passer-le-permis-de-conduire\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.carideal.com\/blog\/2007\/12\/10\/une-bourse-a-suresne-pour-passer-le-permis-de-conduire\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.carideal.com\/blog\/2007\/12\/10\/une-bourse-a-suresne-pour-passer-le-permis-de-conduire\/#primaryimage","url":"http:\/\/www.carideal.com\/images_actualite\/permisconduirecarideal-1194849529.jpg","contentUrl":"http:\/\/www.carideal.com\/images_actualite\/permisconduirecarideal-1194849529.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.carideal.com\/blog\/2007\/12\/10\/une-bourse-a-suresne-pour-passer-le-permis-de-conduire\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog Carid\u00e9al","item":"https:\/\/www.carideal.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Actualit\u00e9 automobile","item":"https:\/\/www.carideal.com\/blog\/actualites-auto\/"},{"@type":"ListItem","position":3,"name":"Une bourse \u00e0 Suresne pour aider \u00e0 passer le permis de conduire"}]},{"@type":"WebSite","@id":"https:\/\/www.carideal.com\/blog\/#website","url":"https:\/\/www.carideal.com\/blog\/","name":"Blog auto Carid\u00e9al","description":"Actualit\u00e9 auto par des passionn\u00e9s","publisher":{"@id":"https:\/\/www.carideal.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.carideal.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.carideal.com\/blog\/#organization","name":"Carideal","url":"https:\/\/www.carideal.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.carideal.com\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2016\/03\/logo-carideal-mandataire-automobile.png","contentUrl":"http:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2016\/03\/logo-carideal-mandataire-automobile.png","width":300,"height":300,"caption":"Carideal"},"image":{"@id":"https:\/\/www.carideal.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Carideal.mandataire.automobile","https:\/\/x.com\/caridealauto","https:\/\/www.instagram.com\/carideal1\/","https:\/\/www.linkedin.com\/company\/carideal.com","https:\/\/fr.pinterest.com\/schiavonsas\/","https:\/\/www.youtube.com\/user\/caridealsas"]},{"@type":"Person","@id":"https:\/\/www.carideal.com\/blog\/#\/schema\/person\/cd95dc7919660de90d31b366f85be1ec","name":"Nicolas SCHIAVON","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.carideal.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c17e55009e671d92cc7f5dc837dc418a?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c17e55009e671d92cc7f5dc837dc418a?s=96&r=g","caption":"Nicolas SCHIAVON"},"description":"Nicolas Schiavon est tomb\u00e9 tout petit dans la marmite automobile. Ayant eu un garage de marque automobile, mandataire automobile de la premi\u00e8re heure d\u00e8s 1999. Nicolas a cr\u00e9\u00e9 ces premiers sites de vente de voiture et blog automobile d\u00e8s 1994. Carideal est n\u00e9 le 15 d\u00e9cembre 2000 de la volont\u00e9 de vendre des voitures d'occasions en ligne puis des voitures neuves. Il a pu essayer beaucoup de voitures tr\u00e8s diff\u00e9rentes et ayant eu personnellement quelques belles autos, Subaru Impreza, Mitsubishi Lancer Evo 7, Porsche 911, Ferrari Testarrossa, Audi RS3, RS4 et j'en passe...","sameAs":["http:\/\/www.carideal.com","https:\/\/www.facebook.com\/nicolas.schiavon.39","https:\/\/www.instagram.com\/carideal1\/","https:\/\/www.linkedin.com\/in\/nschiavon\/","https:\/\/x.com\/caridealauto","https:\/\/www.youtube.com\/user\/caridealsas\/"],"url":"https:\/\/www.carideal.com\/blog\/author\/nschiavon\/"}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"wppr-widget":false},"uagb_author_info":{"display_name":"Nicolas SCHIAVON","author_link":"https:\/\/www.carideal.com\/blog\/author\/nschiavon\/"},"uagb_comment_info":0,"uagb_excerpt":"Tout le monde a droit au permis L'initiative de M Bussereau pour le permis de conduire M Bussereau le secretaire d'etat aux transport, s'est rendu \u00e0 Suresne dans le 92 afin de promouvoir un nouveau dispositif pour le permis de conduire. Il souhaite en effet que chaque ville propose une bourse pour passer le permis\u2026","_links":{"self":[{"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/posts\/4581"}],"collection":[{"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/comments?post=4581"}],"version-history":[{"count":0,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/posts\/4581\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/media?parent=4581"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/categories?post=4581"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/tags?post=4581"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}