{"id":196,"date":"2011-02-09T22:10:00","date_gmt":"2011-02-09T22:10:00","guid":{"rendered":"http:\/\/carideal.com\/blog\/?p=196"},"modified":"2011-02-09T22:10:00","modified_gmt":"2011-02-09T22:10:00","slug":"mercedes-sls-amg-e-cell","status":"publish","type":"post","link":"https:\/\/www.carideal.com\/blog\/2011\/02\/09\/mercedes-sls-amg-e-cell\/","title":{"rendered":"Mercedes SLS AMG E-CELL"},"content":{"rendered":"<p><img decoding=\"async\" src=\"\/blog\/public\/.Mercedes-Benz-SLS-AMG-E-Cell-carideal_m.jpg\" alt=\"mercedes sls amg e-cell\" title=\"mercedes sls amg e-cell, f\u00e9v. 2011\" \/><\/p>\n<blockquote>\n<p>La Mercedes SLS AMG E-CELL \u00e0 l'\u00e9tude pour 2015<\/p>\n<\/blockquote>\n<p>Sa couleur jaune fluo mat intrigue, serait ce un clin d'oeil \u00e0 son aieule la C111 qui dans les ann\u00e9es 70 pr\u00f4nait, \u00e0 sa fa\u00e7on un autre type de propulsion, un moteur rotatif de type wankel. Quoi qu'il en soit, la Mercedes SLS AMG E-CELL troque le moteur V8 \u00e0 essence pour quatre \u00e9lectromoteurs d\u00e9veloppant une puissance de 392 kw, soit l'\u00e9quivalent de 525 ch (571 ch pour sa version \u00e0 essence). En revanche, avec une valeur de couple de 880Nm, elle surclasse sa soeur thermique, laquelle ne dispose que de 650 Nm, d'autan que cette capacit\u00e9 d'acc\u00e9l\u00e9ration est imm\u00e9diatement disponible. <br \/>\n<img decoding=\"async\" src=\"\/blog\/public\/.Mercedes-Benz-SLS-AMG-E-Cell_carideal_m.jpg\" alt=\"mercedes sls amg e-cell\" title=\"mercedes sls amg e-cell, f\u00e9v. 2011\" \/><\/p>\n<blockquote>\n<p>La Mercedes SLS en jaune Fluo<\/p>\n<\/blockquote>\n<p>N\u00e9anmoins, le poids cons\u00e9quent des batteries de type lithium-ion de 48 kwh, d'une capacit\u00e9 de 40Ah, gr\u00e8ve un peu l'exercice du passage de 0 \u00e0 100 km\/h, 3.9 sec contre 3.7 sec pour la version 6.3 V8. En revanche, l'\u00e9quilibre du ch\u00e2ssis n'est pas mis en p\u00e9ril puisque ces batteries prennent place sous l'habitacle.<br \/>\n<img decoding=\"async\" src=\"\/blog\/public\/.Mercedes-Benz-SLS-AMG-E-Cell_carideal-1_m.jpg\" alt=\"mercedes sls amg e-cell\" title=\"mercedes sls amg e-cell, f\u00e9v. 2011\" \/><\/p>\n<blockquote>\n<p>L'alimentation de la SLS<\/p>\n<\/blockquote>\n<p>A bord, le passage au tout \u00e9lectrique se traduit par l'implantation d'une nouvelle console centrale, laquelle rec\u00e8le un vaste \u00e9cran tactile. Aujourd'hui, le projet est suffisamment avanc\u00e9 pour que Mercedes puisse envisager une \u00e9ventuelle commercialisation en petite s\u00e9rie de la SLS AMG E-CELL, l'Audi e-tron l'attend d\u00e9j\u00e0 de pied ferme.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Mercedes SLS AMG E-CELL \u00e0 l&rsquo;\u00e9tude pour 2015 Sa couleur jaune fluo mat intrigue, serait ce un clin d&rsquo;oeil \u00e0 son aieule la C111 qui dans les ann\u00e9es 70 pr\u00f4nait, \u00e0 sa fa\u00e7on un autre type de propulsion, un moteur rotatif de type wankel. Quoi qu&rsquo;il en soit, la Mercedes SLS AMG E-CELL troque &#8230; <a title=\"Mercedes SLS AMG E-CELL\" class=\"read-more\" href=\"https:\/\/www.carideal.com\/blog\/2011\/02\/09\/mercedes-sls-amg-e-cell\/\" aria-label=\"En savoir plus sur Mercedes SLS AMG E-CELL\">Lire plus<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[6],"tags":[622,568],"class_list":["post-196","post","type-post","status-publish","format-standard","hentry","category-ecologie","tag-amg","tag-r8"],"wppr_data":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mercedes SLS AMG E-CELL - Blog auto Carid\u00e9al<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.carideal.com\/blog\/2011\/02\/09\/mercedes-sls-amg-e-cell\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mercedes SLS AMG E-CELL - Blog auto Carid\u00e9al\" \/>\n<meta property=\"og:description\" content=\"La Mercedes SLS AMG E-CELL \u00e0 l&#039;\u00e9tude pour 2015 Sa couleur jaune fluo mat intrigue, serait ce un clin d&#039;oeil \u00e0 son aieule la C111 qui dans les ann\u00e9es 70 pr\u00f4nait, \u00e0 sa fa\u00e7on un autre type de propulsion, un moteur rotatif de type wankel. Quoi qu&#039;il en soit, la Mercedes SLS AMG E-CELL troque ... Lire plus\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.carideal.com\/blog\/2011\/02\/09\/mercedes-sls-amg-e-cell\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog auto Carid\u00e9al\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Carideal.mandataire.automobile\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Carideal.mandataire.automobile\/\" \/>\n<meta property=\"article:published_time\" content=\"2011-02-09T22:10:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2016\/03\/logo-carideal-mandataire-automobile.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"N.S Carideal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@caridealauto\" \/>\n<meta name=\"twitter:site\" content=\"@caridealauto\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"N.S Carideal\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.carideal.com\\\/blog\\\/2011\\\/02\\\/09\\\/mercedes-sls-amg-e-cell\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.carideal.com\\\/blog\\\/2011\\\/02\\\/09\\\/mercedes-sls-amg-e-cell\\\/\"},\"author\":{\"name\":\"N.S Carideal\",\"@id\":\"https:\\\/\\\/www.carideal.com\\\/blog\\\/#\\\/schema\\\/person\\\/985c7e757d1042d647f21bfaf8d41ebc\"},\"headline\":\"Mercedes SLS AMG E-CELL\",\"datePublished\":\"2011-02-09T22:10:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.carideal.com\\\/blog\\\/2011\\\/02\\\/09\\\/mercedes-sls-amg-e-cell\\\/\"},\"wordCount\":229,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.carideal.com\\\/blog\\\/#organization\"},\"keywords\":[\"AMG\",\"R8\"],\"articleSection\":[\"Ecologie\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.carideal.com\\\/blog\\\/2011\\\/02\\\/09\\\/mercedes-sls-amg-e-cell\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.carideal.com\\\/blog\\\/2011\\\/02\\\/09\\\/mercedes-sls-amg-e-cell\\\/\",\"url\":\"https:\\\/\\\/www.carideal.com\\\/blog\\\/2011\\\/02\\\/09\\\/mercedes-sls-amg-e-cell\\\/\",\"name\":\"Mercedes SLS AMG E-CELL - Blog auto Carid\u00e9al\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.carideal.com\\\/blog\\\/#website\"},\"datePublished\":\"2011-02-09T22:10:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.carideal.com\\\/blog\\\/2011\\\/02\\\/09\\\/mercedes-sls-amg-e-cell\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.carideal.com\\\/blog\\\/2011\\\/02\\\/09\\\/mercedes-sls-amg-e-cell\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.carideal.com\\\/blog\\\/2011\\\/02\\\/09\\\/mercedes-sls-amg-e-cell\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog Carid\u00e9al\",\"item\":\"https:\\\/\\\/www.carideal.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ecologie\",\"item\":\"https:\\\/\\\/www.carideal.com\\\/blog\\\/ecologie\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mercedes SLS AMG E-CELL\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.carideal.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.carideal.com\\\/blog\\\/\",\"name\":\"Blog auto Carid\u00e9al\",\"description\":\"Actualit\u00e9 auto par des passionn\u00e9s\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.carideal.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.carideal.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.carideal.com\\\/blog\\\/#organization\",\"name\":\"Carideal\",\"url\":\"https:\\\/\\\/www.carideal.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.carideal.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.carideal.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/03\\\/logo-carideal-mandataire-automobile.png\",\"contentUrl\":\"http:\\\/\\\/www.carideal.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/03\\\/logo-carideal-mandataire-automobile.png\",\"width\":300,\"height\":300,\"caption\":\"Carideal\"},\"image\":{\"@id\":\"https:\\\/\\\/www.carideal.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Carideal.mandataire.automobile\",\"https:\\\/\\\/x.com\\\/caridealauto\",\"https:\\\/\\\/www.instagram.com\\\/carideal1\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/carideal.com\",\"https:\\\/\\\/fr.pinterest.com\\\/schiavonsas\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/caridealsas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.carideal.com\\\/blog\\\/#\\\/schema\\\/person\\\/985c7e757d1042d647f21bfaf8d41ebc\",\"name\":\"N.S Carideal\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6f5ba979b007ea5262e0fe9d7c158f488589e92229a20c2c59e0c4e9de7177df?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6f5ba979b007ea5262e0fe9d7c158f488589e92229a20c2c59e0c4e9de7177df?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6f5ba979b007ea5262e0fe9d7c158f488589e92229a20c2c59e0c4e9de7177df?s=96&r=g\",\"caption\":\"N.S Carideal\"},\"description\":\"Depuis tout petit fan d'automobile. Il est question d'essayer et de comparer toutes ces voitures qui nous ont fait r\u00e9ver, avant que celles-ci ne devient uniquement des voitures de collection.\",\"sameAs\":[\"http:\\\/\\\/www.carideal.com\\\/blog\",\"https:\\\/\\\/www.facebook.com\\\/Carideal.mandataire.automobile\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/nschiavon\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/caridealsas\\\/\"],\"url\":\"https:\\\/\\\/www.carideal.com\\\/blog\\\/author\\\/admin_carideal\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mercedes SLS AMG E-CELL - Blog auto Carid\u00e9al","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.carideal.com\/blog\/2011\/02\/09\/mercedes-sls-amg-e-cell\/","og_locale":"fr_FR","og_type":"article","og_title":"Mercedes SLS AMG E-CELL - Blog auto Carid\u00e9al","og_description":"La Mercedes SLS AMG E-CELL \u00e0 l'\u00e9tude pour 2015 Sa couleur jaune fluo mat intrigue, serait ce un clin d'oeil \u00e0 son aieule la C111 qui dans les ann\u00e9es 70 pr\u00f4nait, \u00e0 sa fa\u00e7on un autre type de propulsion, un moteur rotatif de type wankel. Quoi qu'il en soit, la Mercedes SLS AMG E-CELL troque ... Lire plus","og_url":"https:\/\/www.carideal.com\/blog\/2011\/02\/09\/mercedes-sls-amg-e-cell\/","og_site_name":"Blog auto Carid\u00e9al","article_publisher":"https:\/\/www.facebook.com\/Carideal.mandataire.automobile","article_author":"https:\/\/www.facebook.com\/Carideal.mandataire.automobile\/","article_published_time":"2011-02-09T22:10:00+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2016\/03\/logo-carideal-mandataire-automobile.png","type":"image\/png"}],"author":"N.S Carideal","twitter_card":"summary_large_image","twitter_creator":"@caridealauto","twitter_site":"@caridealauto","twitter_misc":{"\u00c9crit par":"N.S Carideal","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.carideal.com\/blog\/2011\/02\/09\/mercedes-sls-amg-e-cell\/#article","isPartOf":{"@id":"https:\/\/www.carideal.com\/blog\/2011\/02\/09\/mercedes-sls-amg-e-cell\/"},"author":{"name":"N.S Carideal","@id":"https:\/\/www.carideal.com\/blog\/#\/schema\/person\/985c7e757d1042d647f21bfaf8d41ebc"},"headline":"Mercedes SLS AMG E-CELL","datePublished":"2011-02-09T22:10:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.carideal.com\/blog\/2011\/02\/09\/mercedes-sls-amg-e-cell\/"},"wordCount":229,"commentCount":0,"publisher":{"@id":"https:\/\/www.carideal.com\/blog\/#organization"},"keywords":["AMG","R8"],"articleSection":["Ecologie"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.carideal.com\/blog\/2011\/02\/09\/mercedes-sls-amg-e-cell\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.carideal.com\/blog\/2011\/02\/09\/mercedes-sls-amg-e-cell\/","url":"https:\/\/www.carideal.com\/blog\/2011\/02\/09\/mercedes-sls-amg-e-cell\/","name":"Mercedes SLS AMG E-CELL - Blog auto Carid\u00e9al","isPartOf":{"@id":"https:\/\/www.carideal.com\/blog\/#website"},"datePublished":"2011-02-09T22:10:00+00:00","breadcrumb":{"@id":"https:\/\/www.carideal.com\/blog\/2011\/02\/09\/mercedes-sls-amg-e-cell\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.carideal.com\/blog\/2011\/02\/09\/mercedes-sls-amg-e-cell\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.carideal.com\/blog\/2011\/02\/09\/mercedes-sls-amg-e-cell\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog Carid\u00e9al","item":"https:\/\/www.carideal.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Ecologie","item":"https:\/\/www.carideal.com\/blog\/ecologie\/"},{"@type":"ListItem","position":3,"name":"Mercedes SLS AMG E-CELL"}]},{"@type":"WebSite","@id":"https:\/\/www.carideal.com\/blog\/#website","url":"https:\/\/www.carideal.com\/blog\/","name":"Blog auto Carid\u00e9al","description":"Actualit\u00e9 auto par des passionn\u00e9s","publisher":{"@id":"https:\/\/www.carideal.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.carideal.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.carideal.com\/blog\/#organization","name":"Carideal","url":"https:\/\/www.carideal.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.carideal.com\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2016\/03\/logo-carideal-mandataire-automobile.png","contentUrl":"http:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2016\/03\/logo-carideal-mandataire-automobile.png","width":300,"height":300,"caption":"Carideal"},"image":{"@id":"https:\/\/www.carideal.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Carideal.mandataire.automobile","https:\/\/x.com\/caridealauto","https:\/\/www.instagram.com\/carideal1\/","https:\/\/www.linkedin.com\/company\/carideal.com","https:\/\/fr.pinterest.com\/schiavonsas\/","https:\/\/www.youtube.com\/user\/caridealsas"]},{"@type":"Person","@id":"https:\/\/www.carideal.com\/blog\/#\/schema\/person\/985c7e757d1042d647f21bfaf8d41ebc","name":"N.S Carideal","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/6f5ba979b007ea5262e0fe9d7c158f488589e92229a20c2c59e0c4e9de7177df?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6f5ba979b007ea5262e0fe9d7c158f488589e92229a20c2c59e0c4e9de7177df?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6f5ba979b007ea5262e0fe9d7c158f488589e92229a20c2c59e0c4e9de7177df?s=96&r=g","caption":"N.S Carideal"},"description":"Depuis tout petit fan d'automobile. Il est question d'essayer et de comparer toutes ces voitures qui nous ont fait r\u00e9ver, avant que celles-ci ne devient uniquement des voitures de collection.","sameAs":["http:\/\/www.carideal.com\/blog","https:\/\/www.facebook.com\/Carideal.mandataire.automobile\/","https:\/\/www.linkedin.com\/in\/nschiavon\/","https:\/\/www.youtube.com\/user\/caridealsas\/"],"url":"https:\/\/www.carideal.com\/blog\/author\/admin_carideal\/"}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"wppr-widget":false},"uagb_author_info":{"display_name":"N.S Carideal","author_link":"https:\/\/www.carideal.com\/blog\/author\/admin_carideal\/"},"uagb_comment_info":0,"uagb_excerpt":"La Mercedes SLS AMG E-CELL \u00e0 l'\u00e9tude pour 2015 Sa couleur jaune fluo mat intrigue, serait ce un clin d'oeil \u00e0 son aieule la C111 qui dans les ann\u00e9es 70 pr\u00f4nait, \u00e0 sa fa\u00e7on un autre type de propulsion, un moteur rotatif de type wankel. Quoi qu'il en soit, la Mercedes SLS AMG E-CELL troque\u2026","_links":{"self":[{"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/posts\/196","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/comments?post=196"}],"version-history":[{"count":0,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/posts\/196\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/media?parent=196"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/categories?post=196"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/tags?post=196"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}