{"id":1818,"date":"2012-11-23T07:31:00","date_gmt":"2012-11-23T07:31:00","guid":{"rendered":"http:\/\/carideal.com\/blog\/?p=1818"},"modified":"2020-03-08T07:34:03","modified_gmt":"2020-03-08T06:34:03","slug":"peugeot-rcz-racing-cup-le-castellet-en-video","status":"publish","type":"post","link":"https:\/\/www.carideal.com\/blog\/2012\/11\/23\/peugeot-rcz-racing-cup-le-castellet-en-video\/","title":{"rendered":"Peugeot RCZ Racing Cup @ Le Castellet en vid\u00e9o"},"content":{"rendered":"<h2><strong>Peugeot RCZ Racing Cup au Mans<\/strong><\/h2>\n<figure id=\"attachment_13147\" aria-describedby=\"caption-attachment-13147\" style=\"width: 630px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2012\/11\/peugeot_rcz_racing_cup-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-13147\" title=\"Peugeot RCZ Racing Cup\" src=\"http:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2012\/11\/peugeot_rcz_racing_cup-2.jpg\" alt=\"Peugeot RCZ Racing Cup\" width=\"640\" height=\"378\" srcset=\"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2012\/11\/peugeot_rcz_racing_cup-2.jpg 920w, https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2012\/11\/peugeot_rcz_racing_cup-2-300x177.jpg 300w, https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2012\/11\/peugeot_rcz_racing_cup-2-768x454.jpg 768w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/a><figcaption id=\"caption-attachment-13147\" class=\"wp-caption-text\">Peugeot RCZ Racing Cup<\/figcaption><\/figure>\n<p><strong>Peugeot RCZ Racing Cup :<\/strong> Si vous pensez quelques peu que Peugeot n'\u00e9tait pas s\u00e9rieux au sujet de la promotion appropri\u00e9e de son <a href=\"http:\/\/www.carideal.com\/blog\/2014\/01\/09\/peugeot-rcz-r-essai\/\">coup\u00e9 RCZ<\/a> en tant que \u00a0voiture de sport, son nouveau troph\u00e9e\u00a0\"Peugeot RCZ Racing Cup\" devrait supprimer tout doute.<\/p>\n<p>La s\u00e9rie RCZ Racing Cup d\u00e9butera en 2012 avec une version sp\u00e9cialement adapt\u00e9e pour concurrencer l'<a href=\"http:\/\/www.carideal.com\/blog\/2015\/11\/08\/la-nouvelle-audi-tt-au-top-de-la-technologie\/\">Audi TT<\/a>, cette RCZ Racing cup a \u00e9t\u00e9 sp\u00e9cialement d\u00e9velopp\u00e9e par Magneti Marelli sur la base de son moteur THP turbo de 1,6 litres.<\/p>\n<p>La puissance passe de \u00a0200 ch \u00e0 252 ch, et le couple monte\u00a0\u00e0 290 Nm au lieu de 275 Nm. Il n'y a qu'une bo\u00eete automatique s\u00e9quentielle six vitesses \u00a0avec des palettes au volant de propos\u00e9e, aucune boite manuelle en vue.<\/p>\n<p>Les chiffres des performances de la belle Peogeot RCZ Racing Cup n'ont pas \u00e9t\u00e9 publi\u00e9s, mais avec beaucoup plus de puissance et une baisse de poids de 1372 kg \u00e0 1267 kg, il est juste de supposer que ce Pitbull\u00a0sera un peu plus rapide que votre RCZ de tous les jours.<\/p>\n<figure id=\"attachment_13145\" aria-describedby=\"caption-attachment-13145\" style=\"width: 630px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2012\/11\/peugeot_rcz_cup.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-13145\" title=\"Peugeot RCZ Cup au Castelt et au Mans\" src=\"http:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2012\/11\/peugeot_rcz_cup.jpg\" alt=\"Peugeot RCZ Cup au Castelt et au Mans\" width=\"640\" height=\"378\" srcset=\"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2012\/11\/peugeot_rcz_cup.jpg 920w, https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2012\/11\/peugeot_rcz_cup-300x177.jpg 300w, https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2012\/11\/peugeot_rcz_cup-768x454.jpg 768w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/a><figcaption id=\"caption-attachment-13145\" class=\"wp-caption-text\">Peugeot RCZ Cup au Castelt et au Mans<\/figcaption><\/figure>\n<p>\u00c0 l'int\u00e9rieur, il ya des si\u00e8ges de course l\u00e9gers et un arceau a \u00e9t\u00e9 rajout\u00e9 pour la s\u00e9curit\u00e9, tandis que les amortisseurs de suspension sont am\u00e9lior\u00e9s et les freins AP Racing vont prendre soin de la conduite\u00a0et \u00e9viter les collisions.<\/p>\n<p>Pour participer \u00e0 la s\u00e9rie Peugeot RCZ Racing Cup, les \u00e9quipes auront besoin d'environ 56000\u00a0\u20ac, soit un peu plus que le co\u00fbt du de la version homologu\u00e9e de la RCZ 200 e anniversaire , mais vous ne pouvez pas conduire celle-ci sur la route.<\/p>\n<h2>Vid\u00e9os Peugeot RCZ Racing Cup<\/h2>\n<p><iframe loading=\"lazy\" src=\"http:\/\/www.youtube.com\/embed\/J9l-rU-wYSk\" width=\"640\" height=\"360\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p><iframe loading=\"lazy\" src=\"http:\/\/www.youtube.com\/embed\/cUAK4L4SJXc\" width=\"640\" height=\"360\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<h2>Peugeot Australia va engager des Peugeot RCZ Racing cup \u00e0 la course d'endurance des 12H de Bathurst\u00a02013<\/h2>\n<figure id=\"attachment_13148\" aria-describedby=\"caption-attachment-13148\" style=\"width: 630px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2012\/11\/peugeot_rcz_bathurst_12hr_australia.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-13148\" title=\"Peugeot RCZ Racing Cup aux 12H d'endurance de Bathurst 2013 en Australie\" src=\"http:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2012\/11\/peugeot_rcz_bathurst_12hr_australia.jpg\" alt=\"Peugeot RCZ Racing Cup aux 12H d'endurance de Bathurst 2013 en Australie\" width=\"640\" height=\"378\" \/><\/a><figcaption id=\"caption-attachment-13148\" class=\"wp-caption-text\">Peugeot RCZ Racing Cup aux 12H d'endurance de Bathurst 2013 en Australie<\/figcaption><\/figure>\n<p>Deux coup\u00e9s Peugeot RCZ Racing Cup seront parmi plus de 50 voitures en comp\u00e9tition dans la course d'endurance des 12H de Bathurst 2013\u00a0en F\u00e9vrier.<\/p>\n<p>L'\u00e9quipe fran\u00e7aise de Peugeot Sport sera la seule usine\u00a0sur la piste et s'inscrira dans la classe L1 en tant qu'invit\u00e9e pour les v\u00e9hicules jusqu'\u00e0 1600 cc.<\/p>\n<p>Ces RCZ Racing Cup pr\u00e9par\u00e9es pour la course\u00a0utiliseront\u00a0le m\u00eame moteur 1.6 THP essence que celui des s\u00e9rie Racing Cup fran\u00e7aise, (voir plus haut) soit 252 ch et 290 Nm. Ces m\u00eame caract\u00e9ristiques incluent le poids revu \u00e0 la baisse.<\/p>\n<p>Peugeot Automobiles Australia soutient \u00e9galement l'\u00e9quipe des 12 heures de Bathurst, laissant entrevoir potentiellement une plus grande participation dans la comp\u00e9tition pour le distributeur local.<\/p>\n<blockquote><p>\u00abUn \u00e9v\u00e9nement comme la course des 12H de Bathurst est un beau coup de pied dans la mare\u00a0en Australie car il montre la capacit\u00e9 de la RCZ \u00e0 courrir, mais renforce \u00e9galement l'image de fiabilit\u00e9 des voitures\u00bb, a d\u00e9clar\u00e9 Bill Gillespie de Peugeot Australie.<\/p><\/blockquote>\n<p>La Peugeot RCZ Racing Cup principale sera pilot\u00e9 par trois pilotes fran\u00e7ais : St\u00e9phane Caillet, Bruce Jouanny et Julien Rueflin.<\/p>\n<p>Tous les trois ont pr\u00e9c\u00e9demment conduit des RCZ diesel d'usine dans la course des 24 heures du Nurburgring.<\/p>\n<p>L'alignement des pilotes pour la deuxi\u00e8me voiture est encore \u00e0 finaliser, mais la l\u00e9gende moto Mick Doohan est cit\u00e9\u00a0pour \u00eatre parmi le trio de pilotes local.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Peugeot RCZ Racing Cup au Mans Peugeot RCZ Racing Cup : Si vous pensez quelques peu que Peugeot n&rsquo;\u00e9tait pas s\u00e9rieux au sujet de la promotion appropri\u00e9e de son coup\u00e9 RCZ en tant que \u00a0voiture de sport, son nouveau troph\u00e9e\u00a0\u00ab\u00a0Peugeot RCZ Racing Cup\u00a0\u00bb devrait supprimer tout doute. La s\u00e9rie RCZ Racing Cup d\u00e9butera en 2012 &#8230; <a title=\"Peugeot RCZ Racing Cup @ Le Castellet en vid\u00e9o\" class=\"read-more\" href=\"https:\/\/www.carideal.com\/blog\/2012\/11\/23\/peugeot-rcz-racing-cup-le-castellet-en-video\/\" aria-label=\"En savoir plus sur Peugeot RCZ Racing Cup @ Le Castellet en vid\u00e9o\">Lire plus<\/a><\/p>\n","protected":false},"author":1,"featured_media":13145,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[5946,16,18],"tags":[],"class_list":["post-1818","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-peugeot","category-sport-auto","category-videos"],"wppr_data":{"cwp_meta_box_check":"No"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Peugeot RCZ Racing Cup @ Le Castellet en vid\u00e9o - Blog auto Carid\u00e9al<\/title>\n<meta name=\"description\" content=\"Peugeot lance la promotion de son coup\u00e9 RCZ en tant que voiture de sport, avec son nouveau troph\u00e9e Peugeot RCZ Racing Cup\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.carideal.com\/blog\/2012\/11\/23\/peugeot-rcz-racing-cup-le-castellet-en-video\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Peugeot RCZ Racing Cup @ Le Castellet en vid\u00e9o - Blog auto Carid\u00e9al\" \/>\n<meta property=\"og:description\" content=\"Peugeot lance la promotion de son coup\u00e9 RCZ en tant que voiture de sport, avec son nouveau troph\u00e9e Peugeot RCZ Racing Cup\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.carideal.com\/blog\/2012\/11\/23\/peugeot-rcz-racing-cup-le-castellet-en-video\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog auto Carid\u00e9al\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Carideal.mandataire.automobile\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Carideal.mandataire.automobile\/\" \/>\n<meta property=\"article:published_time\" content=\"2012-11-23T07:31:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-08T06:34:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2012\/11\/peugeot_rcz_cup.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"920\" \/>\n\t<meta property=\"og:image:height\" content=\"544\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"N.S Carideal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@caridealauto\" \/>\n<meta name=\"twitter:site\" content=\"@caridealauto\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"N.S Carideal\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.carideal.com\/blog\/2012\/11\/23\/peugeot-rcz-racing-cup-le-castellet-en-video\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/2012\/11\/23\/peugeot-rcz-racing-cup-le-castellet-en-video\/\"},\"author\":{\"name\":\"N.S Carideal\",\"@id\":\"https:\/\/www.carideal.com\/blog\/#\/schema\/person\/985c7e757d1042d647f21bfaf8d41ebc\"},\"headline\":\"Peugeot RCZ Racing Cup @ Le Castellet en vid\u00e9o\",\"datePublished\":\"2012-11-23T07:31:00+00:00\",\"dateModified\":\"2020-03-08T06:34:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/2012\/11\/23\/peugeot-rcz-racing-cup-le-castellet-en-video\/\"},\"wordCount\":588,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/2012\/11\/23\/peugeot-rcz-racing-cup-le-castellet-en-video\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2012\/11\/peugeot_rcz_cup.jpg\",\"articleSection\":[\"Actualit\u00e9 Peugeot\",\"Sport Automobile\",\"Vid\u00e9o voiture : vid\u00e9o automobile\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.carideal.com\/blog\/2012\/11\/23\/peugeot-rcz-racing-cup-le-castellet-en-video\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.carideal.com\/blog\/2012\/11\/23\/peugeot-rcz-racing-cup-le-castellet-en-video\/\",\"url\":\"https:\/\/www.carideal.com\/blog\/2012\/11\/23\/peugeot-rcz-racing-cup-le-castellet-en-video\/\",\"name\":\"Peugeot RCZ Racing Cup @ Le Castellet en vid\u00e9o - Blog auto Carid\u00e9al\",\"isPartOf\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/2012\/11\/23\/peugeot-rcz-racing-cup-le-castellet-en-video\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/2012\/11\/23\/peugeot-rcz-racing-cup-le-castellet-en-video\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2012\/11\/peugeot_rcz_cup.jpg\",\"datePublished\":\"2012-11-23T07:31:00+00:00\",\"dateModified\":\"2020-03-08T06:34:03+00:00\",\"description\":\"Peugeot lance la promotion de son coup\u00e9 RCZ en tant que voiture de sport, avec son nouveau troph\u00e9e Peugeot RCZ Racing Cup\",\"breadcrumb\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/2012\/11\/23\/peugeot-rcz-racing-cup-le-castellet-en-video\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.carideal.com\/blog\/2012\/11\/23\/peugeot-rcz-racing-cup-le-castellet-en-video\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.carideal.com\/blog\/2012\/11\/23\/peugeot-rcz-racing-cup-le-castellet-en-video\/#primaryimage\",\"url\":\"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2012\/11\/peugeot_rcz_cup.jpg\",\"contentUrl\":\"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2012\/11\/peugeot_rcz_cup.jpg\",\"width\":920,\"height\":544,\"caption\":\"Peugeot RCZ Racing Cup\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.carideal.com\/blog\/2012\/11\/23\/peugeot-rcz-racing-cup-le-castellet-en-video\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog Carid\u00e9al\",\"item\":\"https:\/\/www.carideal.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vid\u00e9o voiture : vid\u00e9o automobile\",\"item\":\"https:\/\/www.carideal.com\/blog\/videos\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Peugeot RCZ Racing Cup @ Le Castellet en vid\u00e9o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.carideal.com\/blog\/#website\",\"url\":\"https:\/\/www.carideal.com\/blog\/\",\"name\":\"Blog auto Carid\u00e9al\",\"description\":\"Actualit\u00e9 auto par des passionn\u00e9s\",\"publisher\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.carideal.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.carideal.com\/blog\/#organization\",\"name\":\"Carideal\",\"url\":\"https:\/\/www.carideal.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.carideal.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2016\/03\/logo-carideal-mandataire-automobile.png\",\"contentUrl\":\"http:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2016\/03\/logo-carideal-mandataire-automobile.png\",\"width\":300,\"height\":300,\"caption\":\"Carideal\"},\"image\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Carideal.mandataire.automobile\",\"https:\/\/x.com\/caridealauto\",\"https:\/\/www.instagram.com\/carideal1\/\",\"https:\/\/www.linkedin.com\/company\/carideal.com\",\"https:\/\/fr.pinterest.com\/schiavonsas\/\",\"https:\/\/www.youtube.com\/user\/caridealsas\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.carideal.com\/blog\/#\/schema\/person\/985c7e757d1042d647f21bfaf8d41ebc\",\"name\":\"N.S Carideal\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.carideal.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/edb7ccdf1a4e3d14aef967760d354d0e?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/edb7ccdf1a4e3d14aef967760d354d0e?s=96&r=g\",\"caption\":\"N.S Carideal\"},\"description\":\"Depuis tout petit fan d'automobile. Il est question d'essayer et de comparer toutes ces voitures qui nous ont fait r\u00e9ver, avant que celles-ci ne devient uniquement des voitures de collection.\",\"sameAs\":[\"http:\/\/www.carideal.com\/blog\",\"https:\/\/www.facebook.com\/Carideal.mandataire.automobile\/\",\"https:\/\/www.linkedin.com\/in\/nschiavon\/\",\"https:\/\/www.youtube.com\/user\/caridealsas\/\"],\"url\":\"https:\/\/www.carideal.com\/blog\/author\/admin_carideal\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Peugeot RCZ Racing Cup @ Le Castellet en vid\u00e9o - Blog auto Carid\u00e9al","description":"Peugeot lance la promotion de son coup\u00e9 RCZ en tant que voiture de sport, avec son nouveau troph\u00e9e Peugeot RCZ Racing Cup","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.carideal.com\/blog\/2012\/11\/23\/peugeot-rcz-racing-cup-le-castellet-en-video\/","og_locale":"fr_FR","og_type":"article","og_title":"Peugeot RCZ Racing Cup @ Le Castellet en vid\u00e9o - Blog auto Carid\u00e9al","og_description":"Peugeot lance la promotion de son coup\u00e9 RCZ en tant que voiture de sport, avec son nouveau troph\u00e9e Peugeot RCZ Racing Cup","og_url":"https:\/\/www.carideal.com\/blog\/2012\/11\/23\/peugeot-rcz-racing-cup-le-castellet-en-video\/","og_site_name":"Blog auto Carid\u00e9al","article_publisher":"https:\/\/www.facebook.com\/Carideal.mandataire.automobile","article_author":"https:\/\/www.facebook.com\/Carideal.mandataire.automobile\/","article_published_time":"2012-11-23T07:31:00+00:00","article_modified_time":"2020-03-08T06:34:03+00:00","og_image":[{"width":920,"height":544,"url":"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2012\/11\/peugeot_rcz_cup.jpg","type":"image\/jpeg"}],"author":"N.S Carideal","twitter_card":"summary_large_image","twitter_creator":"@caridealauto","twitter_site":"@caridealauto","twitter_misc":{"\u00c9crit par":"N.S Carideal","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.carideal.com\/blog\/2012\/11\/23\/peugeot-rcz-racing-cup-le-castellet-en-video\/#article","isPartOf":{"@id":"https:\/\/www.carideal.com\/blog\/2012\/11\/23\/peugeot-rcz-racing-cup-le-castellet-en-video\/"},"author":{"name":"N.S Carideal","@id":"https:\/\/www.carideal.com\/blog\/#\/schema\/person\/985c7e757d1042d647f21bfaf8d41ebc"},"headline":"Peugeot RCZ Racing Cup @ Le Castellet en vid\u00e9o","datePublished":"2012-11-23T07:31:00+00:00","dateModified":"2020-03-08T06:34:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.carideal.com\/blog\/2012\/11\/23\/peugeot-rcz-racing-cup-le-castellet-en-video\/"},"wordCount":588,"commentCount":0,"publisher":{"@id":"https:\/\/www.carideal.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.carideal.com\/blog\/2012\/11\/23\/peugeot-rcz-racing-cup-le-castellet-en-video\/#primaryimage"},"thumbnailUrl":"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2012\/11\/peugeot_rcz_cup.jpg","articleSection":["Actualit\u00e9 Peugeot","Sport Automobile","Vid\u00e9o voiture : vid\u00e9o automobile"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.carideal.com\/blog\/2012\/11\/23\/peugeot-rcz-racing-cup-le-castellet-en-video\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.carideal.com\/blog\/2012\/11\/23\/peugeot-rcz-racing-cup-le-castellet-en-video\/","url":"https:\/\/www.carideal.com\/blog\/2012\/11\/23\/peugeot-rcz-racing-cup-le-castellet-en-video\/","name":"Peugeot RCZ Racing Cup @ Le Castellet en vid\u00e9o - Blog auto Carid\u00e9al","isPartOf":{"@id":"https:\/\/www.carideal.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.carideal.com\/blog\/2012\/11\/23\/peugeot-rcz-racing-cup-le-castellet-en-video\/#primaryimage"},"image":{"@id":"https:\/\/www.carideal.com\/blog\/2012\/11\/23\/peugeot-rcz-racing-cup-le-castellet-en-video\/#primaryimage"},"thumbnailUrl":"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2012\/11\/peugeot_rcz_cup.jpg","datePublished":"2012-11-23T07:31:00+00:00","dateModified":"2020-03-08T06:34:03+00:00","description":"Peugeot lance la promotion de son coup\u00e9 RCZ en tant que voiture de sport, avec son nouveau troph\u00e9e Peugeot RCZ Racing Cup","breadcrumb":{"@id":"https:\/\/www.carideal.com\/blog\/2012\/11\/23\/peugeot-rcz-racing-cup-le-castellet-en-video\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.carideal.com\/blog\/2012\/11\/23\/peugeot-rcz-racing-cup-le-castellet-en-video\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.carideal.com\/blog\/2012\/11\/23\/peugeot-rcz-racing-cup-le-castellet-en-video\/#primaryimage","url":"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2012\/11\/peugeot_rcz_cup.jpg","contentUrl":"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2012\/11\/peugeot_rcz_cup.jpg","width":920,"height":544,"caption":"Peugeot RCZ Racing Cup"},{"@type":"BreadcrumbList","@id":"https:\/\/www.carideal.com\/blog\/2012\/11\/23\/peugeot-rcz-racing-cup-le-castellet-en-video\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog Carid\u00e9al","item":"https:\/\/www.carideal.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Vid\u00e9o voiture : vid\u00e9o automobile","item":"https:\/\/www.carideal.com\/blog\/videos\/"},{"@type":"ListItem","position":3,"name":"Peugeot RCZ Racing Cup @ Le Castellet en vid\u00e9o"}]},{"@type":"WebSite","@id":"https:\/\/www.carideal.com\/blog\/#website","url":"https:\/\/www.carideal.com\/blog\/","name":"Blog auto Carid\u00e9al","description":"Actualit\u00e9 auto par des passionn\u00e9s","publisher":{"@id":"https:\/\/www.carideal.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.carideal.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.carideal.com\/blog\/#organization","name":"Carideal","url":"https:\/\/www.carideal.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.carideal.com\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2016\/03\/logo-carideal-mandataire-automobile.png","contentUrl":"http:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2016\/03\/logo-carideal-mandataire-automobile.png","width":300,"height":300,"caption":"Carideal"},"image":{"@id":"https:\/\/www.carideal.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Carideal.mandataire.automobile","https:\/\/x.com\/caridealauto","https:\/\/www.instagram.com\/carideal1\/","https:\/\/www.linkedin.com\/company\/carideal.com","https:\/\/fr.pinterest.com\/schiavonsas\/","https:\/\/www.youtube.com\/user\/caridealsas"]},{"@type":"Person","@id":"https:\/\/www.carideal.com\/blog\/#\/schema\/person\/985c7e757d1042d647f21bfaf8d41ebc","name":"N.S Carideal","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.carideal.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/edb7ccdf1a4e3d14aef967760d354d0e?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/edb7ccdf1a4e3d14aef967760d354d0e?s=96&r=g","caption":"N.S Carideal"},"description":"Depuis tout petit fan d'automobile. Il est question d'essayer et de comparer toutes ces voitures qui nous ont fait r\u00e9ver, avant que celles-ci ne devient uniquement des voitures de collection.","sameAs":["http:\/\/www.carideal.com\/blog","https:\/\/www.facebook.com\/Carideal.mandataire.automobile\/","https:\/\/www.linkedin.com\/in\/nschiavon\/","https:\/\/www.youtube.com\/user\/caridealsas\/"],"url":"https:\/\/www.carideal.com\/blog\/author\/admin_carideal\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2012\/11\/peugeot_rcz_cup.jpg",920,544,false],"thumbnail":["https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2012\/11\/peugeot_rcz_cup-150x150.jpg",150,150,true],"medium":["https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2012\/11\/peugeot_rcz_cup-300x177.jpg",300,177,true],"medium_large":["https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2012\/11\/peugeot_rcz_cup-768x454.jpg",768,454,true],"large":["https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2012\/11\/peugeot_rcz_cup.jpg",920,544,false],"1536x1536":["https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2012\/11\/peugeot_rcz_cup.jpg",920,544,false],"2048x2048":["https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2012\/11\/peugeot_rcz_cup.jpg",920,544,false],"wppr-widget":["https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2012\/11\/peugeot_rcz_cup.jpg",50,30,false]},"uagb_author_info":{"display_name":"N.S Carideal","author_link":"https:\/\/www.carideal.com\/blog\/author\/admin_carideal\/"},"uagb_comment_info":0,"uagb_excerpt":"Peugeot RCZ Racing Cup au Mans Peugeot RCZ Racing Cup : Si vous pensez quelques peu que Peugeot n'\u00e9tait pas s\u00e9rieux au sujet de la promotion appropri\u00e9e de son coup\u00e9 RCZ en tant que \u00a0voiture de sport, son nouveau troph\u00e9e\u00a0\"Peugeot RCZ Racing Cup\" devrait supprimer tout doute. La s\u00e9rie RCZ Racing Cup d\u00e9butera en 2012\u2026","_links":{"self":[{"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/posts\/1818"}],"collection":[{"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/comments?post=1818"}],"version-history":[{"count":0,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/posts\/1818\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/media\/13145"}],"wp:attachment":[{"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/media?parent=1818"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/categories?post=1818"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/tags?post=1818"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}