{"id":1500,"date":"2014-03-02T10:46:00","date_gmt":"2014-03-02T10:46:00","guid":{"rendered":"http:\/\/carideal.com\/blog\/?p=1500"},"modified":"2020-03-08T07:28:52","modified_gmt":"2020-03-08T06:28:52","slug":"nouvelle-volvo-v60-d4-geartronic8","status":"publish","type":"post","link":"https:\/\/www.carideal.com\/blog\/2014\/03\/02\/nouvelle-volvo-v60-d4-geartronic8\/","title":{"rendered":"Nouvelle Volvo V60 D4 Geartronic8"},"content":{"rendered":"<\/p>\n<blockquote>\n<p>#VolvoV60 avec le nouveau moteur #D4 \u00e9quip\u00e9 de la technologie #iART<\/p>\n<\/blockquote>\n<p>Volvo se met \u00e0 la page et remplace ses moteurs V8, V6 essence et m\u00eame les cinq cylindres car trop gourmands, Volvo est aussi \u00e0 la recherche d'une plus grande productivit\u00e9 et rentabilit\u00e9. <a href=\"\/blog\/index.php?tag\/Volvo\">Volvo<\/a> appelle cette nouvelle g\u00e9n\u00e9ration de moteur <a href=\"\/blog\/index.php?tag\/Drive-E\">Drive-E<\/a> bas\u00e9 sur une m\u00eame architecture bas\u00e9 sur un quatre cylindres.<br \/>\nPar exemple en essence, le nouveau moteur d'une cylindr\u00e9e de 1969 Cm3 utilise l'injection directe d'essence avec un compresseur ET un turbo qui d\u00e9livre soit <strong>245 ch dans le T5 ou 306 ch dans le T6<\/strong>. Volvo annonce aussi une version de 140 ch<br \/>\nLe moteur diesel aura la m\u00eame cylindr\u00e9e avec deux turbo compresseurs et poss\u00e9dera la technologie <a href=\"\/blog\/index.php?post\/2014\/03\/02\/Nouvelle-g%C3%A9n%C3%A9ration-de-moteur-haute-technologie-i-Art-pour-Volvo\">i-ART<\/a> qui permettra de proposer des puissances comprises entre 120 et 230 ch.<br \/>\nCette nouvelle <a href=\"\/blog\/index.php?tag\/Volvo%20V60\">Volvo V60<\/a> est \u00e9quip\u00e9e du moteur <a href=\"\/blog\/index.php?tag\/D4\">D4<\/a> de <a href=\"\/blog\/index.php?tag\/181%20ch\">181 ch<\/a> qui remplace l'ancien moteur D4 de <a href=\"\/blog\/index.php?tag\/cinq%20cylindres\">cinq cylindres<\/a> de 163 ch qui \u00e9quipait les <a href=\"\/blog\/index.php?tag\/S60\">S60<\/a> et <a href=\"\/blog\/index.php?tag\/V60\">V60<\/a>.<br \/>\nLe nouveau moteur D4 qui \u00e9quipe la V60 propose 11% de puissance en plus pour 13% d'\u00e9mission de CO2 en moins, 181 ch et 99 g de CO2 pour la S60 la place en t\u00eate de son segment devant la reine de la cat\u00e9gorie la BMW 320d EfficientDynamic qui elle propose 163 ch pour 109 g de CO2.<br \/>\nLes puristes regretteront le bruit du cinq cylindres, mais le D4 leur fera oublier par son silence, et surtout son couple tr\u00e8s g\u00e9n\u00e9reux de 400 Nm contre 350 pour l'ancien d\u00e8s les plus bas r\u00e9gimes.<br \/>\nCette excellent moteur associ\u00e9 \u00e0 la nouvelle boite de vitesse automatique <a href=\"\/blog\/index.php?tag\/Geartronic8\">Geartronic8<\/a> du Japonais <a href=\"\/blog\/index.php?tag\/Ainsin\">Ainsin<\/a>, \u00e0 8 rapports remplace avantageusement l'ancienne \u00e0 six rapports.<br \/>\nCette nouvelle boite de vitesse reste sobre en limitant les \u00e9missions de CO2 \u00e0 112g\/km, mais aussi des performances en hausse 7.6 sec sur le 0 \u00e0 100 km\/h contre 10.4 sec pour l'ancien duo Geartronic6.<br \/>\nLa pr\u00e9sentation luxueuse et le design sobre de la planche de bord avec un affichage enti\u00e8rement digital pour les compteurs finissent de position cette Volvo comme une alternative s\u00e9rieuse dans le haut de gamme.<\/p>\n<p>\/ <a href=\"\/blog\/index.php?post\/2013\/11\/04\/S%C3%A9curit%C3%A9-%3A-on-compte-sur-l-automatisation\">S\u00e9curit\u00e9 on compte sur l'automatisation<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>#VolvoV60 avec le nouveau moteur #D4 \u00e9quip\u00e9 de la technologie #iART Volvo se met \u00e0 la page et remplace ses moteurs V8, V6 essence et m\u00eame les cinq cylindres car trop gourmands, Volvo est aussi \u00e0 la recherche d&rsquo;une plus grande productivit\u00e9 et rentabilit\u00e9. Volvo appelle cette nouvelle g\u00e9n\u00e9ration de moteur Drive-E bas\u00e9 sur une &#8230; <a title=\"Nouvelle Volvo V60 D4 Geartronic8\" class=\"read-more\" href=\"https:\/\/www.carideal.com\/blog\/2014\/03\/02\/nouvelle-volvo-v60-d4-geartronic8\/\" aria-label=\"En savoir plus sur Nouvelle Volvo V60 D4 Geartronic8\">Lire plus<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1500","post","type-post","status-publish","format-standard","hentry","category-marche-automobile-voiture-neuve-occasion-4x4-suv"],"wppr_data":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Nouvelle Volvo V60 D4 Geartronic8 - Blog auto Carid\u00e9al<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.carideal.com\/blog\/2014\/03\/02\/nouvelle-volvo-v60-d4-geartronic8\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nouvelle Volvo V60 D4 Geartronic8 - Blog auto Carid\u00e9al\" \/>\n<meta property=\"og:description\" content=\"#VolvoV60 avec le nouveau moteur #D4 \u00e9quip\u00e9 de la technologie #iART Volvo se met \u00e0 la page et remplace ses moteurs V8, V6 essence et m\u00eame les cinq cylindres car trop gourmands, Volvo est aussi \u00e0 la recherche d&#039;une plus grande productivit\u00e9 et rentabilit\u00e9. Volvo appelle cette nouvelle g\u00e9n\u00e9ration de moteur Drive-E bas\u00e9 sur une ... Lire plus\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.carideal.com\/blog\/2014\/03\/02\/nouvelle-volvo-v60-d4-geartronic8\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog auto Carid\u00e9al\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Carideal.mandataire.automobile\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Carideal.mandataire.automobile\/\" \/>\n<meta property=\"article:published_time\" content=\"2014-03-02T10:46:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-08T06:28:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2016\/03\/logo-carideal-mandataire-automobile.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"N.S Carideal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@caridealauto\" \/>\n<meta name=\"twitter:site\" content=\"@caridealauto\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"N.S Carideal\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.carideal.com\/blog\/2014\/03\/02\/nouvelle-volvo-v60-d4-geartronic8\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/2014\/03\/02\/nouvelle-volvo-v60-d4-geartronic8\/\"},\"author\":{\"name\":\"N.S Carideal\",\"@id\":\"https:\/\/www.carideal.com\/blog\/#\/schema\/person\/985c7e757d1042d647f21bfaf8d41ebc\"},\"headline\":\"Nouvelle Volvo V60 D4 Geartronic8\",\"datePublished\":\"2014-03-02T10:46:00+00:00\",\"dateModified\":\"2020-03-08T06:28:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/2014\/03\/02\/nouvelle-volvo-v60-d4-geartronic8\/\"},\"wordCount\":356,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/#organization\"},\"articleSection\":[\"March\u00e9 automobile\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.carideal.com\/blog\/2014\/03\/02\/nouvelle-volvo-v60-d4-geartronic8\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.carideal.com\/blog\/2014\/03\/02\/nouvelle-volvo-v60-d4-geartronic8\/\",\"url\":\"https:\/\/www.carideal.com\/blog\/2014\/03\/02\/nouvelle-volvo-v60-d4-geartronic8\/\",\"name\":\"Nouvelle Volvo V60 D4 Geartronic8 - Blog auto Carid\u00e9al\",\"isPartOf\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/#website\"},\"datePublished\":\"2014-03-02T10:46:00+00:00\",\"dateModified\":\"2020-03-08T06:28:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/2014\/03\/02\/nouvelle-volvo-v60-d4-geartronic8\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.carideal.com\/blog\/2014\/03\/02\/nouvelle-volvo-v60-d4-geartronic8\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.carideal.com\/blog\/2014\/03\/02\/nouvelle-volvo-v60-d4-geartronic8\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog Carid\u00e9al\",\"item\":\"https:\/\/www.carideal.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"March\u00e9 automobile\",\"item\":\"https:\/\/www.carideal.com\/blog\/marche-automobile-voiture-neuve-occasion-4x4-suv\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Nouvelle Volvo V60 D4 Geartronic8\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.carideal.com\/blog\/#website\",\"url\":\"https:\/\/www.carideal.com\/blog\/\",\"name\":\"Blog auto Carid\u00e9al\",\"description\":\"Actualit\u00e9 auto par des passionn\u00e9s\",\"publisher\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.carideal.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.carideal.com\/blog\/#organization\",\"name\":\"Carideal\",\"url\":\"https:\/\/www.carideal.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.carideal.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2016\/03\/logo-carideal-mandataire-automobile.png\",\"contentUrl\":\"http:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2016\/03\/logo-carideal-mandataire-automobile.png\",\"width\":300,\"height\":300,\"caption\":\"Carideal\"},\"image\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Carideal.mandataire.automobile\",\"https:\/\/x.com\/caridealauto\",\"https:\/\/www.instagram.com\/carideal1\/\",\"https:\/\/www.linkedin.com\/company\/carideal.com\",\"https:\/\/fr.pinterest.com\/schiavonsas\/\",\"https:\/\/www.youtube.com\/user\/caridealsas\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.carideal.com\/blog\/#\/schema\/person\/985c7e757d1042d647f21bfaf8d41ebc\",\"name\":\"N.S Carideal\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.carideal.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/edb7ccdf1a4e3d14aef967760d354d0e?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/edb7ccdf1a4e3d14aef967760d354d0e?s=96&r=g\",\"caption\":\"N.S Carideal\"},\"description\":\"Depuis tout petit fan d'automobile. Il est question d'essayer et de comparer toutes ces voitures qui nous ont fait r\u00e9ver, avant que celles-ci ne devient uniquement des voitures de collection.\",\"sameAs\":[\"http:\/\/www.carideal.com\/blog\",\"https:\/\/www.facebook.com\/Carideal.mandataire.automobile\/\",\"https:\/\/www.linkedin.com\/in\/nschiavon\/\",\"https:\/\/www.youtube.com\/user\/caridealsas\/\"],\"url\":\"https:\/\/www.carideal.com\/blog\/author\/admin_carideal\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nouvelle Volvo V60 D4 Geartronic8 - Blog auto Carid\u00e9al","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.carideal.com\/blog\/2014\/03\/02\/nouvelle-volvo-v60-d4-geartronic8\/","og_locale":"fr_FR","og_type":"article","og_title":"Nouvelle Volvo V60 D4 Geartronic8 - Blog auto Carid\u00e9al","og_description":"#VolvoV60 avec le nouveau moteur #D4 \u00e9quip\u00e9 de la technologie #iART Volvo se met \u00e0 la page et remplace ses moteurs V8, V6 essence et m\u00eame les cinq cylindres car trop gourmands, Volvo est aussi \u00e0 la recherche d'une plus grande productivit\u00e9 et rentabilit\u00e9. Volvo appelle cette nouvelle g\u00e9n\u00e9ration de moteur Drive-E bas\u00e9 sur une ... Lire plus","og_url":"https:\/\/www.carideal.com\/blog\/2014\/03\/02\/nouvelle-volvo-v60-d4-geartronic8\/","og_site_name":"Blog auto Carid\u00e9al","article_publisher":"https:\/\/www.facebook.com\/Carideal.mandataire.automobile","article_author":"https:\/\/www.facebook.com\/Carideal.mandataire.automobile\/","article_published_time":"2014-03-02T10:46:00+00:00","article_modified_time":"2020-03-08T06:28:52+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2016\/03\/logo-carideal-mandataire-automobile.png","type":"image\/png"}],"author":"N.S Carideal","twitter_card":"summary_large_image","twitter_creator":"@caridealauto","twitter_site":"@caridealauto","twitter_misc":{"\u00c9crit par":"N.S Carideal","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.carideal.com\/blog\/2014\/03\/02\/nouvelle-volvo-v60-d4-geartronic8\/#article","isPartOf":{"@id":"https:\/\/www.carideal.com\/blog\/2014\/03\/02\/nouvelle-volvo-v60-d4-geartronic8\/"},"author":{"name":"N.S Carideal","@id":"https:\/\/www.carideal.com\/blog\/#\/schema\/person\/985c7e757d1042d647f21bfaf8d41ebc"},"headline":"Nouvelle Volvo V60 D4 Geartronic8","datePublished":"2014-03-02T10:46:00+00:00","dateModified":"2020-03-08T06:28:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.carideal.com\/blog\/2014\/03\/02\/nouvelle-volvo-v60-d4-geartronic8\/"},"wordCount":356,"commentCount":0,"publisher":{"@id":"https:\/\/www.carideal.com\/blog\/#organization"},"articleSection":["March\u00e9 automobile"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.carideal.com\/blog\/2014\/03\/02\/nouvelle-volvo-v60-d4-geartronic8\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.carideal.com\/blog\/2014\/03\/02\/nouvelle-volvo-v60-d4-geartronic8\/","url":"https:\/\/www.carideal.com\/blog\/2014\/03\/02\/nouvelle-volvo-v60-d4-geartronic8\/","name":"Nouvelle Volvo V60 D4 Geartronic8 - Blog auto Carid\u00e9al","isPartOf":{"@id":"https:\/\/www.carideal.com\/blog\/#website"},"datePublished":"2014-03-02T10:46:00+00:00","dateModified":"2020-03-08T06:28:52+00:00","breadcrumb":{"@id":"https:\/\/www.carideal.com\/blog\/2014\/03\/02\/nouvelle-volvo-v60-d4-geartronic8\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.carideal.com\/blog\/2014\/03\/02\/nouvelle-volvo-v60-d4-geartronic8\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.carideal.com\/blog\/2014\/03\/02\/nouvelle-volvo-v60-d4-geartronic8\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog Carid\u00e9al","item":"https:\/\/www.carideal.com\/blog\/"},{"@type":"ListItem","position":2,"name":"March\u00e9 automobile","item":"https:\/\/www.carideal.com\/blog\/marche-automobile-voiture-neuve-occasion-4x4-suv\/"},{"@type":"ListItem","position":3,"name":"Nouvelle Volvo V60 D4 Geartronic8"}]},{"@type":"WebSite","@id":"https:\/\/www.carideal.com\/blog\/#website","url":"https:\/\/www.carideal.com\/blog\/","name":"Blog auto Carid\u00e9al","description":"Actualit\u00e9 auto par des passionn\u00e9s","publisher":{"@id":"https:\/\/www.carideal.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.carideal.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.carideal.com\/blog\/#organization","name":"Carideal","url":"https:\/\/www.carideal.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.carideal.com\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2016\/03\/logo-carideal-mandataire-automobile.png","contentUrl":"http:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2016\/03\/logo-carideal-mandataire-automobile.png","width":300,"height":300,"caption":"Carideal"},"image":{"@id":"https:\/\/www.carideal.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Carideal.mandataire.automobile","https:\/\/x.com\/caridealauto","https:\/\/www.instagram.com\/carideal1\/","https:\/\/www.linkedin.com\/company\/carideal.com","https:\/\/fr.pinterest.com\/schiavonsas\/","https:\/\/www.youtube.com\/user\/caridealsas"]},{"@type":"Person","@id":"https:\/\/www.carideal.com\/blog\/#\/schema\/person\/985c7e757d1042d647f21bfaf8d41ebc","name":"N.S Carideal","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.carideal.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/edb7ccdf1a4e3d14aef967760d354d0e?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/edb7ccdf1a4e3d14aef967760d354d0e?s=96&r=g","caption":"N.S Carideal"},"description":"Depuis tout petit fan d'automobile. Il est question d'essayer et de comparer toutes ces voitures qui nous ont fait r\u00e9ver, avant que celles-ci ne devient uniquement des voitures de collection.","sameAs":["http:\/\/www.carideal.com\/blog","https:\/\/www.facebook.com\/Carideal.mandataire.automobile\/","https:\/\/www.linkedin.com\/in\/nschiavon\/","https:\/\/www.youtube.com\/user\/caridealsas\/"],"url":"https:\/\/www.carideal.com\/blog\/author\/admin_carideal\/"}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"wppr-widget":false},"uagb_author_info":{"display_name":"N.S Carideal","author_link":"https:\/\/www.carideal.com\/blog\/author\/admin_carideal\/"},"uagb_comment_info":0,"uagb_excerpt":"#VolvoV60 avec le nouveau moteur #D4 \u00e9quip\u00e9 de la technologie #iART Volvo se met \u00e0 la page et remplace ses moteurs V8, V6 essence et m\u00eame les cinq cylindres car trop gourmands, Volvo est aussi \u00e0 la recherche d'une plus grande productivit\u00e9 et rentabilit\u00e9. Volvo appelle cette nouvelle g\u00e9n\u00e9ration de moteur Drive-E bas\u00e9 sur une\u2026","_links":{"self":[{"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/posts\/1500"}],"collection":[{"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/comments?post=1500"}],"version-history":[{"count":0,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/posts\/1500\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/media?parent=1500"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/categories?post=1500"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/tags?post=1500"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}