{"id":14789,"date":"2012-11-06T12:40:24","date_gmt":"2012-11-06T11:40:24","guid":{"rendered":"http:\/\/www.carideal.com\/blog\/?p=14789"},"modified":"2019-12-13T09:15:33","modified_gmt":"2019-12-13T08:15:33","slug":"etiquette-de-performance-energetique","status":"publish","type":"post","link":"https:\/\/www.carideal.com\/blog\/2012\/11\/06\/etiquette-de-performance-energetique\/","title":{"rendered":"L&rsquo;\u00e9tiquette de performance \u00e9nerg\u00e9tique des pneus"},"content":{"rendered":"<h2><strong>L'\u00e9tiquette de performance \u00e9nerg\u00e9tique des pneumatiques<\/strong><\/h2>\n<p>\u00c0 partir du 1er novembre, l\u2019\u00e9tiquetage des pneus informera l\u2019automobiliste sur les performances des pneumatiques. La comparaison sera donc enfin possible pour les consommateurs. L\u2019\u00e9tiquetage sur les pneus utilise un syst\u00e8me \u00e0 base de lettres. Le A correspond \u00e0 la meilleure performance et le G \u00e0 la moins bonne. Les brochures vont se multiplier dans les points de vente pour expliquer ce nouvel \u00e9tiquetage.<\/p>\n<figure id=\"attachment_14791\" aria-describedby=\"caption-attachment-14791\" style=\"width: 590px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-14791\" src=\"http:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2017\/01\/etiquette-performance-energetique-pneu-2-e1576224747962.jpg\" alt=\"A partir du 1er Novembre 2012, tous les pneumatiques neufs pour voitures particuli\u00e8res et utilitaires l\u00e9gers vendus sur le march\u00e9 europ\u00e9en et produits \u00e0 partir du 1er juillet 2012 devront comporter une \u00e9tiquette de performance \u00e9nerg\u00e9tique\" width=\"600\" height=\"450\" \/><figcaption id=\"caption-attachment-14791\" class=\"wp-caption-text\">A partir du 1er Novembre 2012, tous les pneumatiques neufs pour voitures particuli\u00e8res et utilitaires l\u00e9gers vendus sur le march\u00e9 europ\u00e9en et produits \u00e0 partir du 1er juillet 2012 devront comporter une \u00e9tiquette de performance \u00e9nerg\u00e9tique<\/figcaption><\/figure>\n<p>\u00c0 partir du 1er Novembre 2012, tous les pneumatiques neufs pour <a href=\"http:\/\/www.carideal.com\/blog\/type-de-vehicule\/berlines\/\">voitures particuli\u00e8res<\/a> et <a href=\"http:\/\/www.carideal.com\/blog\/type-de-vehicule\/utilitaire\/\">utilitaires l\u00e9gers<\/a> vendus sur le march\u00e9 europ\u00e9en et produits \u00e0 partir du 1er juillet 2012 devront comporter une \u00e9tiquette de performance \u00e9nerg\u00e9tique sp\u00e9cifique repr\u00e9sentant les performances de chaque pneumatique. Vous retrouvez ci-dessous les diff\u00e9rentes dispositions et informations sur le sujet. <a href=\"https:\/\/www.service-public.fr\/particuliers\/actualites\/002560\">Loi du 1\/11\/2012.<\/a><\/p>\n<ul>\n<li><a href=\"http:\/\/www.carideal.com\/blog\/garage-automobile\/pneu\/pneu-discount\/\">Achat Pneu discount\u00a0<\/a><\/li>\n<\/ul>\n<p>Les <a href=\"http:\/\/www.carideal.com\/blog\/garage-automobile\/pneu\/\">pneus<\/a> sont ainsi class\u00e9s selon 3 crit\u00e8res d\u2019\u00e9valuation pour la performance \u00e9nerg\u00e9tique, appr\u00e9ciables d\u2019un seul coup d\u2019\u0153il :<\/p>\n<p>\u2022 Efficacit\u00e9 \u00e9nerg\u00e9tique (R\u00e9sistance au roulement consommation de carburant)<br \/>\n\u2022 Adh\u00e9rence sur sol mouill\u00e9 (facteur cl\u00e9 de s\u00e9curit\u00e9)<br \/>\n\u2022 Bruit de roulement ext\u00e9rieur (bruit per\u00e7u \u00e0 l\u2019ext\u00e9rieur de la voiture)<\/p>\n<h2>La r\u00e8glementation europ\u00e9enne impose l'\u00e9tiquette de performance \u00e9nerg\u00e9tique des pneus<\/h2>\n<figure id=\"attachment_18747\" aria-describedby=\"caption-attachment-18747\" style=\"width: 390px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-18747 size-full\" src=\"http:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2012\/11\/etiquetage_pneus.png\" alt=\"etiquetage pneu\" width=\"400\" height=\"364\" srcset=\"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2012\/11\/etiquetage_pneus.png 400w, https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2012\/11\/etiquetage_pneus-300x273.png 300w, https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2012\/11\/etiquetage_pneus-50x46.png 50w, https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2012\/11\/etiquetage_pneus-110x100.png 110w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><figcaption id=\"caption-attachment-18747\" class=\"wp-caption-text\">\u00c9tiquetage pneu<\/figcaption><\/figure>\n<p>Cette nouvelle r\u00e9glementation europ\u00e9enne (R\u00e8glement (CE) n\u00b0 1222\/2009 modifi\u00e9 par le r\u00e8glement (UE) n\u00b0 1235\/2011 de la Commission) incite \u00e0 l\u2019utilisation de pneumatiques s\u00fbrs, \u00e9conomiques et \u00e9cologiques en participant \u00e0 la r\u00e9duction de leur impact sur l\u2019environnement. Le consommateur final gr\u00e2ce \u00e0 cette \u00e9tiquette de performance \u00e9nerg\u00e9tique, dispose de la sorte des informations essentielles propices \u00e0 orienter son choix lors de l\u2019achat.<\/p>\n<p>Ces trois valeurs factuelles, la r\u00e9sistance au roulement qui influe forc\u00e9ment sur la consommation, l'adh\u00e9rence du pneu sur le sol mouill\u00e9, qui est une image entre autre du rainurage du pneu et qui influe sur sa capacit\u00e9 \u00e0 \u00e9vacuer l'eau et donc \u00e0 la tenue de route sur le sol mouill\u00e9 et le troisi\u00e8me facture qui est le bruit, p\u00e9nible \u00e0 130 km\/h sur autoroute par exemple.<\/p>\n<p>En fait il faut bien comprendre que ces trois facteurs sont intimement li\u00e9s ! <strong>L'\u00e9tiquette de performance \u00e9nerg\u00e9tique des pneus est une chose, et la r\u00e9alit\u00e9 est plus compliqu\u00e9e que cela<\/strong> ! Pour faire un \"bon pneu\" selon cette directive et ainsi montrer de bonne valeurs sur cette \u00e9tiquette de performance \u00e9nerg\u00e9tique, il suffira de durcir la gomme, d'y ajouter de la silice, et d'enlever du rainurage transversal.... On aura de bons chiffres et un mauvais pneu, surtout sur le mouill\u00e9 et en courbe... Bref quand on aura besoin qu'il tienne la voiture sur la route !<\/p>\n<p>C'est pour cela qu'au <a href=\"http:\/\/www.carideal.com\/blog\/garage-automobile\/\">garage<\/a> Schiavon <a href=\"http:\/\/www.carideal.com\/blog\/2010\/01\/23\/garage-citroen-schiavon-13-av-de-turin-73000-bassens-chambery\/\">Citroen \u00e0 Chamb\u00e9ry<\/a>, nos techniciens vous conseillent, en plus de nos <a href=\"http:\/\/www.carideal.com\/blog\/garage-automobile\/pneu\/pneu-pas-cher\/\">promos pneus<\/a>, et que nous publions les <a href=\"http:\/\/www.carideal.com\/blog\/tag\/test-pneu\/\">tests pneu du TCS<\/a>, qui passent au crible deux fois par an des \u00e9chantillons de pneu repr\u00e9sentatifs.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;\u00e9tiquette de performance \u00e9nerg\u00e9tique des pneumatiques \u00c0 partir du 1er novembre, l\u2019\u00e9tiquetage des pneus informera l\u2019automobiliste sur les performances des pneumatiques. La comparaison sera donc enfin possible pour les consommateurs. L\u2019\u00e9tiquetage sur les pneus utilise un syst\u00e8me \u00e0 base de lettres. Le A correspond \u00e0 la meilleure performance et le G \u00e0 la moins bonne. &#8230; <a title=\"L&rsquo;\u00e9tiquette de performance \u00e9nerg\u00e9tique des pneus\" class=\"read-more\" href=\"https:\/\/www.carideal.com\/blog\/2012\/11\/06\/etiquette-de-performance-energetique\/\" aria-label=\"En savoir plus sur L&rsquo;\u00e9tiquette de performance \u00e9nerg\u00e9tique des pneus\">Lire plus<\/a><\/p>\n","protected":false},"author":3,"featured_media":14791,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[21,13],"tags":[],"class_list":["post-14789","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites-auto","category-pneumatique"],"wppr_data":{"cwp_meta_box_check":"No"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>L&#039;\u00e9tiquette de performance \u00e9nerg\u00e9tique des pneus - Blog auto Carid\u00e9al<\/title>\n<meta name=\"description\" content=\"A partir du 1er Novembre 2012, tous les pneumatiques neufs pour voitures et utilitaires l\u00e9gers devront comporter une \u00e9tiquette de performance \u00e9nerg\u00e9tique\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.carideal.com\/blog\/2012\/11\/06\/etiquette-de-performance-energetique\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;\u00e9tiquette de performance \u00e9nerg\u00e9tique des pneus - Blog auto Carid\u00e9al\" \/>\n<meta property=\"og:description\" content=\"A partir du 1er Novembre 2012, tous les pneumatiques neufs pour voitures et utilitaires l\u00e9gers devront comporter une \u00e9tiquette de performance \u00e9nerg\u00e9tique\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.carideal.com\/blog\/2012\/11\/06\/etiquette-de-performance-energetique\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog auto Carid\u00e9al\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Carideal.mandataire.automobile\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/nicolas.schiavon.39\" \/>\n<meta property=\"article:published_time\" content=\"2012-11-06T11:40:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-12-13T08:15:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2017\/01\/etiquette-performance-energetique-pneu-2-e1576224747962.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nicolas SCHIAVON\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@caridealauto\" \/>\n<meta name=\"twitter:site\" content=\"@caridealauto\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nicolas SCHIAVON\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.carideal.com\/blog\/2012\/11\/06\/etiquette-de-performance-energetique\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/2012\/11\/06\/etiquette-de-performance-energetique\/\"},\"author\":{\"name\":\"Nicolas SCHIAVON\",\"@id\":\"https:\/\/www.carideal.com\/blog\/#\/schema\/person\/cd95dc7919660de90d31b366f85be1ec\"},\"headline\":\"L&rsquo;\u00e9tiquette de performance \u00e9nerg\u00e9tique des pneus\",\"datePublished\":\"2012-11-06T11:40:24+00:00\",\"dateModified\":\"2019-12-13T08:15:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/2012\/11\/06\/etiquette-de-performance-energetique\/\"},\"wordCount\":545,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/2012\/11\/06\/etiquette-de-performance-energetique\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2017\/01\/etiquette-performance-energetique-pneu-2-e1576224747962.jpg\",\"articleSection\":[\"Actualit\u00e9 automobile\",\"Pneumatique\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.carideal.com\/blog\/2012\/11\/06\/etiquette-de-performance-energetique\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.carideal.com\/blog\/2012\/11\/06\/etiquette-de-performance-energetique\/\",\"url\":\"https:\/\/www.carideal.com\/blog\/2012\/11\/06\/etiquette-de-performance-energetique\/\",\"name\":\"L'\u00e9tiquette de performance \u00e9nerg\u00e9tique des pneus - Blog auto Carid\u00e9al\",\"isPartOf\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/2012\/11\/06\/etiquette-de-performance-energetique\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/2012\/11\/06\/etiquette-de-performance-energetique\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2017\/01\/etiquette-performance-energetique-pneu-2-e1576224747962.jpg\",\"datePublished\":\"2012-11-06T11:40:24+00:00\",\"dateModified\":\"2019-12-13T08:15:33+00:00\",\"description\":\"A partir du 1er Novembre 2012, tous les pneumatiques neufs pour voitures et utilitaires l\u00e9gers devront comporter une \u00e9tiquette de performance \u00e9nerg\u00e9tique\",\"breadcrumb\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/2012\/11\/06\/etiquette-de-performance-energetique\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.carideal.com\/blog\/2012\/11\/06\/etiquette-de-performance-energetique\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.carideal.com\/blog\/2012\/11\/06\/etiquette-de-performance-energetique\/#primaryimage\",\"url\":\"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2017\/01\/etiquette-performance-energetique-pneu-2-e1576224747962.jpg\",\"contentUrl\":\"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2017\/01\/etiquette-performance-energetique-pneu-2-e1576224747962.jpg\",\"width\":600,\"height\":450,\"caption\":\"A partir du 1er Novembre 2012, tous les pneumatiques neufs pour voitures particuli\u00e8res et utilitaires l\u00e9gers vendus sur le march\u00e9 europ\u00e9en et produits \u00e0 partir du 1er juillet 2012 devront comporter une \u00e9tiquette de performance \u00e9nerg\u00e9tique\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.carideal.com\/blog\/2012\/11\/06\/etiquette-de-performance-energetique\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog Carid\u00e9al\",\"item\":\"https:\/\/www.carideal.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pneumatique\",\"item\":\"https:\/\/www.carideal.com\/blog\/pneumatique\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"L&rsquo;\u00e9tiquette de performance \u00e9nerg\u00e9tique des pneus\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.carideal.com\/blog\/#website\",\"url\":\"https:\/\/www.carideal.com\/blog\/\",\"name\":\"Blog auto Carid\u00e9al\",\"description\":\"Actualit\u00e9 auto par des passionn\u00e9s\",\"publisher\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.carideal.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.carideal.com\/blog\/#organization\",\"name\":\"Carideal\",\"url\":\"https:\/\/www.carideal.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.carideal.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2016\/03\/logo-carideal-mandataire-automobile.png\",\"contentUrl\":\"http:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2016\/03\/logo-carideal-mandataire-automobile.png\",\"width\":300,\"height\":300,\"caption\":\"Carideal\"},\"image\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Carideal.mandataire.automobile\",\"https:\/\/x.com\/caridealauto\",\"https:\/\/www.instagram.com\/carideal1\/\",\"https:\/\/www.linkedin.com\/company\/carideal.com\",\"https:\/\/fr.pinterest.com\/schiavonsas\/\",\"https:\/\/www.youtube.com\/user\/caridealsas\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.carideal.com\/blog\/#\/schema\/person\/cd95dc7919660de90d31b366f85be1ec\",\"name\":\"Nicolas SCHIAVON\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.carideal.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c17e55009e671d92cc7f5dc837dc418a?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c17e55009e671d92cc7f5dc837dc418a?s=96&r=g\",\"caption\":\"Nicolas SCHIAVON\"},\"description\":\"Nicolas Schiavon est tomb\u00e9 tout petit dans la marmite automobile. Ayant eu un garage de marque automobile, mandataire automobile de la premi\u00e8re heure d\u00e8s 1999. Nicolas a cr\u00e9\u00e9 ces premiers sites de vente de voiture et blog automobile d\u00e8s 1994. Carideal est n\u00e9 le 15 d\u00e9cembre 2000 de la volont\u00e9 de vendre des voitures d'occasions en ligne puis des voitures neuves. Il a pu essayer beaucoup de voitures tr\u00e8s diff\u00e9rentes et ayant eu personnellement quelques belles autos, Subaru Impreza, Mitsubishi Lancer Evo 7, Porsche 911, Ferrari Testarrossa, Audi RS3, RS4 et j'en passe...\",\"sameAs\":[\"http:\/\/www.carideal.com\",\"https:\/\/www.facebook.com\/nicolas.schiavon.39\",\"https:\/\/www.instagram.com\/carideal1\/\",\"https:\/\/www.linkedin.com\/in\/nschiavon\/\",\"https:\/\/x.com\/caridealauto\",\"https:\/\/www.youtube.com\/user\/caridealsas\/\"],\"url\":\"https:\/\/www.carideal.com\/blog\/author\/nschiavon\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'\u00e9tiquette de performance \u00e9nerg\u00e9tique des pneus - Blog auto Carid\u00e9al","description":"A partir du 1er Novembre 2012, tous les pneumatiques neufs pour voitures et utilitaires l\u00e9gers devront comporter une \u00e9tiquette de performance \u00e9nerg\u00e9tique","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.carideal.com\/blog\/2012\/11\/06\/etiquette-de-performance-energetique\/","og_locale":"fr_FR","og_type":"article","og_title":"L'\u00e9tiquette de performance \u00e9nerg\u00e9tique des pneus - Blog auto Carid\u00e9al","og_description":"A partir du 1er Novembre 2012, tous les pneumatiques neufs pour voitures et utilitaires l\u00e9gers devront comporter une \u00e9tiquette de performance \u00e9nerg\u00e9tique","og_url":"https:\/\/www.carideal.com\/blog\/2012\/11\/06\/etiquette-de-performance-energetique\/","og_site_name":"Blog auto Carid\u00e9al","article_publisher":"https:\/\/www.facebook.com\/Carideal.mandataire.automobile","article_author":"https:\/\/www.facebook.com\/nicolas.schiavon.39","article_published_time":"2012-11-06T11:40:24+00:00","article_modified_time":"2019-12-13T08:15:33+00:00","og_image":[{"width":600,"height":450,"url":"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2017\/01\/etiquette-performance-energetique-pneu-2-e1576224747962.jpg","type":"image\/jpeg"}],"author":"Nicolas SCHIAVON","twitter_card":"summary_large_image","twitter_creator":"@caridealauto","twitter_site":"@caridealauto","twitter_misc":{"\u00c9crit par":"Nicolas SCHIAVON","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.carideal.com\/blog\/2012\/11\/06\/etiquette-de-performance-energetique\/#article","isPartOf":{"@id":"https:\/\/www.carideal.com\/blog\/2012\/11\/06\/etiquette-de-performance-energetique\/"},"author":{"name":"Nicolas SCHIAVON","@id":"https:\/\/www.carideal.com\/blog\/#\/schema\/person\/cd95dc7919660de90d31b366f85be1ec"},"headline":"L&rsquo;\u00e9tiquette de performance \u00e9nerg\u00e9tique des pneus","datePublished":"2012-11-06T11:40:24+00:00","dateModified":"2019-12-13T08:15:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.carideal.com\/blog\/2012\/11\/06\/etiquette-de-performance-energetique\/"},"wordCount":545,"commentCount":0,"publisher":{"@id":"https:\/\/www.carideal.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.carideal.com\/blog\/2012\/11\/06\/etiquette-de-performance-energetique\/#primaryimage"},"thumbnailUrl":"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2017\/01\/etiquette-performance-energetique-pneu-2-e1576224747962.jpg","articleSection":["Actualit\u00e9 automobile","Pneumatique"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.carideal.com\/blog\/2012\/11\/06\/etiquette-de-performance-energetique\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.carideal.com\/blog\/2012\/11\/06\/etiquette-de-performance-energetique\/","url":"https:\/\/www.carideal.com\/blog\/2012\/11\/06\/etiquette-de-performance-energetique\/","name":"L'\u00e9tiquette de performance \u00e9nerg\u00e9tique des pneus - Blog auto Carid\u00e9al","isPartOf":{"@id":"https:\/\/www.carideal.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.carideal.com\/blog\/2012\/11\/06\/etiquette-de-performance-energetique\/#primaryimage"},"image":{"@id":"https:\/\/www.carideal.com\/blog\/2012\/11\/06\/etiquette-de-performance-energetique\/#primaryimage"},"thumbnailUrl":"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2017\/01\/etiquette-performance-energetique-pneu-2-e1576224747962.jpg","datePublished":"2012-11-06T11:40:24+00:00","dateModified":"2019-12-13T08:15:33+00:00","description":"A partir du 1er Novembre 2012, tous les pneumatiques neufs pour voitures et utilitaires l\u00e9gers devront comporter une \u00e9tiquette de performance \u00e9nerg\u00e9tique","breadcrumb":{"@id":"https:\/\/www.carideal.com\/blog\/2012\/11\/06\/etiquette-de-performance-energetique\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.carideal.com\/blog\/2012\/11\/06\/etiquette-de-performance-energetique\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.carideal.com\/blog\/2012\/11\/06\/etiquette-de-performance-energetique\/#primaryimage","url":"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2017\/01\/etiquette-performance-energetique-pneu-2-e1576224747962.jpg","contentUrl":"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2017\/01\/etiquette-performance-energetique-pneu-2-e1576224747962.jpg","width":600,"height":450,"caption":"A partir du 1er Novembre 2012, tous les pneumatiques neufs pour voitures particuli\u00e8res et utilitaires l\u00e9gers vendus sur le march\u00e9 europ\u00e9en et produits \u00e0 partir du 1er juillet 2012 devront comporter une \u00e9tiquette de performance \u00e9nerg\u00e9tique"},{"@type":"BreadcrumbList","@id":"https:\/\/www.carideal.com\/blog\/2012\/11\/06\/etiquette-de-performance-energetique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog Carid\u00e9al","item":"https:\/\/www.carideal.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Pneumatique","item":"https:\/\/www.carideal.com\/blog\/pneumatique\/"},{"@type":"ListItem","position":3,"name":"L&rsquo;\u00e9tiquette de performance \u00e9nerg\u00e9tique des pneus"}]},{"@type":"WebSite","@id":"https:\/\/www.carideal.com\/blog\/#website","url":"https:\/\/www.carideal.com\/blog\/","name":"Blog auto Carid\u00e9al","description":"Actualit\u00e9 auto par des passionn\u00e9s","publisher":{"@id":"https:\/\/www.carideal.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.carideal.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.carideal.com\/blog\/#organization","name":"Carideal","url":"https:\/\/www.carideal.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.carideal.com\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2016\/03\/logo-carideal-mandataire-automobile.png","contentUrl":"http:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2016\/03\/logo-carideal-mandataire-automobile.png","width":300,"height":300,"caption":"Carideal"},"image":{"@id":"https:\/\/www.carideal.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Carideal.mandataire.automobile","https:\/\/x.com\/caridealauto","https:\/\/www.instagram.com\/carideal1\/","https:\/\/www.linkedin.com\/company\/carideal.com","https:\/\/fr.pinterest.com\/schiavonsas\/","https:\/\/www.youtube.com\/user\/caridealsas"]},{"@type":"Person","@id":"https:\/\/www.carideal.com\/blog\/#\/schema\/person\/cd95dc7919660de90d31b366f85be1ec","name":"Nicolas SCHIAVON","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.carideal.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c17e55009e671d92cc7f5dc837dc418a?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c17e55009e671d92cc7f5dc837dc418a?s=96&r=g","caption":"Nicolas SCHIAVON"},"description":"Nicolas Schiavon est tomb\u00e9 tout petit dans la marmite automobile. Ayant eu un garage de marque automobile, mandataire automobile de la premi\u00e8re heure d\u00e8s 1999. Nicolas a cr\u00e9\u00e9 ces premiers sites de vente de voiture et blog automobile d\u00e8s 1994. Carideal est n\u00e9 le 15 d\u00e9cembre 2000 de la volont\u00e9 de vendre des voitures d'occasions en ligne puis des voitures neuves. Il a pu essayer beaucoup de voitures tr\u00e8s diff\u00e9rentes et ayant eu personnellement quelques belles autos, Subaru Impreza, Mitsubishi Lancer Evo 7, Porsche 911, Ferrari Testarrossa, Audi RS3, RS4 et j'en passe...","sameAs":["http:\/\/www.carideal.com","https:\/\/www.facebook.com\/nicolas.schiavon.39","https:\/\/www.instagram.com\/carideal1\/","https:\/\/www.linkedin.com\/in\/nschiavon\/","https:\/\/x.com\/caridealauto","https:\/\/www.youtube.com\/user\/caridealsas\/"],"url":"https:\/\/www.carideal.com\/blog\/author\/nschiavon\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2017\/01\/etiquette-performance-energetique-pneu-2-e1576224747962.jpg",600,450,false],"thumbnail":["https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2017\/01\/etiquette-performance-energetique-pneu-2-150x150.jpg",150,150,true],"medium":["https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2017\/01\/etiquette-performance-energetique-pneu-2-300x225.jpg",300,225,true],"medium_large":["https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2017\/01\/etiquette-performance-energetique-pneu-2-768x576.jpg",768,576,true],"large":["https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2017\/01\/etiquette-performance-energetique-pneu-2-e1576224747962.jpg",600,450,false],"1536x1536":["https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2017\/01\/etiquette-performance-energetique-pneu-2-e1576224747962.jpg",600,450,false],"2048x2048":["https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2017\/01\/etiquette-performance-energetique-pneu-2-e1576224747962.jpg",600,450,false],"wppr-widget":["https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2017\/01\/etiquette-performance-energetique-pneu-2-e1576224747962.jpg",50,38,false]},"uagb_author_info":{"display_name":"Nicolas SCHIAVON","author_link":"https:\/\/www.carideal.com\/blog\/author\/nschiavon\/"},"uagb_comment_info":0,"uagb_excerpt":"L'\u00e9tiquette de performance \u00e9nerg\u00e9tique des pneumatiques \u00c0 partir du 1er novembre, l\u2019\u00e9tiquetage des pneus informera l\u2019automobiliste sur les performances des pneumatiques. La comparaison sera donc enfin possible pour les consommateurs. L\u2019\u00e9tiquetage sur les pneus utilise un syst\u00e8me \u00e0 base de lettres. Le A correspond \u00e0 la meilleure performance et le G \u00e0 la moins bonne.\u2026","_links":{"self":[{"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/posts\/14789"}],"collection":[{"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/comments?post=14789"}],"version-history":[{"count":0,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/posts\/14789\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/media\/14791"}],"wp:attachment":[{"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/media?parent=14789"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/categories?post=14789"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/tags?post=14789"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}