{"id":1154,"date":"2012-06-18T11:56:00","date_gmt":"2012-06-18T11:56:00","guid":{"rendered":"http:\/\/carideal.com\/blog\/?p=1154"},"modified":"2012-06-18T11:56:00","modified_gmt":"2012-06-18T11:56:00","slug":"mercedes-e-300-bluetec-hybrid","status":"publish","type":"post","link":"https:\/\/www.carideal.com\/blog\/2012\/06\/18\/mercedes-e-300-bluetec-hybrid\/","title":{"rendered":"MERCEDES E 300 Bluetec Hybrid"},"content":{"rendered":"<p><img decoding=\"async\" src=\"\/blog\/public\/.Mercedes-E300-HYBRID-Diesel-carideal_m.jpg\" alt=\"Mercedes-E300-HYBRID-Diesel-carideal.jpg\" title=\"Mercedes-E300-HYBRID-Diesel-carideal.jpg, juin 2012\" \/><\/p>\n<blockquote>\n<p>La <a href=\"\/blog\/index.php?tag\/Classe%20E%20Hybrid\">Classe E Hybrid<\/a><\/p>\n<\/blockquote>\n<p>La premi\u00e8re <a href=\"\/blog\/index.php?tag\/Hybride\">Hybride<\/a> de Mercedes sortit en 2009 sur une<a href=\"\/blog\/index.php?tag\/classe%20S\"> classe S<\/a> \u00e0 essence ne nous avait pas laisser un magnifique souvenir:moteur \u00e9lectrique faible incapable de progresser seul, gain en consommation minime, et la sensation de conduire une limousine dot\u00e9e d'un simple <a href=\"\/blog\/index.php?tag\/Stopamp%3BStart.\">Stop&amp;Start.<\/a><br \/>\nAvec la Classe E Hybrid, cette fois diesel, le bilan est plus favorable, bien que le syst\u00e8me d'hybrid reste l\u00e9ger. Avantage? La batterie, est bien tailler puisque qu'elle rentre sous le capot et sans d\u00e9t\u00e9riorer le volume de l'int\u00e9rieur. Inconv\u00e9nient? Avec juste 27 ch de puissance maximale, le module \u00e9lectrique n'aime pas jouer solo: d'apr\u00e8s Mercedes, il pousse la classe E Hybrid \u00e0 35 km\/h pendant un petit kilom\u00e8tre.Dans les faits, il est m\u00eame difficile de d\u00e9passer 20km\/h en silence. Pour autant, le syst\u00e8me s\u00e9duit. D'abord, les passages des modes \u00e9lectriques aux thermiques sont silencieux, car s\u2019effectuant \u00e0 faible charge: si l'on acc\u00e9l\u00e8re fort, le diesel vient de toute fa\u00e7on aussit\u00f4t. Une fois lanc\u00e9, il est aussi possible de maintenir son allure jusqu'\u00e0 80 km\/h sur les seules ressources de l'\u00e9lectrique. Enfin, la r\u00e9cup\u00e9ration d'\u00e9nergie ne cr\u00e9e pas trop de frein moteur et peut \u00eatre d\u00e9saccoupl\u00e9e pour conserver son \u00e9lan dans une longue descente. La consommation, en baisse de 0.7L\/100 km par rapport au 250 CDI classique (204ch), ach\u00e8ve de convaincre, comme les rejets de CO2 qui donnent droit aux 2000 \u20ac de bonus. Seul probl\u00e8me: on ne connait pas encore le vrai prix exact, et donc, le vrai surco\u00fbt par rapport au diesel.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Classe E Hybrid La premi\u00e8re Hybride de Mercedes sortit en 2009 sur une classe S \u00e0 essence ne nous avait pas laisser un magnifique souvenir:moteur \u00e9lectrique faible incapable de progresser seul, gain en consommation minime, et la sensation de conduire une limousine dot\u00e9e d&rsquo;un simple Stop&amp;Start. Avec la Classe E Hybrid, cette fois diesel, &#8230; <a title=\"MERCEDES E 300 Bluetec Hybrid\" class=\"read-more\" href=\"https:\/\/www.carideal.com\/blog\/2012\/06\/18\/mercedes-e-300-bluetec-hybrid\/\" aria-label=\"En savoir plus sur MERCEDES E 300 Bluetec Hybrid\">Lire plus<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1154","post","type-post","status-publish","format-standard","hentry","category-marche-automobile-voiture-neuve-occasion-4x4-suv"],"wppr_data":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>MERCEDES E 300 Bluetec Hybrid - Blog auto Carid\u00e9al<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.carideal.com\/blog\/2012\/06\/18\/mercedes-e-300-bluetec-hybrid\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MERCEDES E 300 Bluetec Hybrid - Blog auto Carid\u00e9al\" \/>\n<meta property=\"og:description\" content=\"La Classe E Hybrid La premi\u00e8re Hybride de Mercedes sortit en 2009 sur une classe S \u00e0 essence ne nous avait pas laisser un magnifique souvenir:moteur \u00e9lectrique faible incapable de progresser seul, gain en consommation minime, et la sensation de conduire une limousine dot\u00e9e d&#039;un simple Stop&amp;Start. Avec la Classe E Hybrid, cette fois diesel, ... Lire plus\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.carideal.com\/blog\/2012\/06\/18\/mercedes-e-300-bluetec-hybrid\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog auto Carid\u00e9al\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Carideal.mandataire.automobile\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Carideal.mandataire.automobile\/\" \/>\n<meta property=\"article:published_time\" content=\"2012-06-18T11:56:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2016\/03\/logo-carideal-mandataire-automobile.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"N.S Carideal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@caridealauto\" \/>\n<meta name=\"twitter:site\" content=\"@caridealauto\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"N.S Carideal\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.carideal.com\/blog\/2012\/06\/18\/mercedes-e-300-bluetec-hybrid\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/2012\/06\/18\/mercedes-e-300-bluetec-hybrid\/\"},\"author\":{\"name\":\"N.S Carideal\",\"@id\":\"https:\/\/www.carideal.com\/blog\/#\/schema\/person\/985c7e757d1042d647f21bfaf8d41ebc\"},\"headline\":\"MERCEDES E 300 Bluetec Hybrid\",\"datePublished\":\"2012-06-18T11:56:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/2012\/06\/18\/mercedes-e-300-bluetec-hybrid\/\"},\"wordCount\":281,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/#organization\"},\"articleSection\":[\"March\u00e9 automobile\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.carideal.com\/blog\/2012\/06\/18\/mercedes-e-300-bluetec-hybrid\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.carideal.com\/blog\/2012\/06\/18\/mercedes-e-300-bluetec-hybrid\/\",\"url\":\"https:\/\/www.carideal.com\/blog\/2012\/06\/18\/mercedes-e-300-bluetec-hybrid\/\",\"name\":\"MERCEDES E 300 Bluetec Hybrid - Blog auto Carid\u00e9al\",\"isPartOf\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/#website\"},\"datePublished\":\"2012-06-18T11:56:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/2012\/06\/18\/mercedes-e-300-bluetec-hybrid\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.carideal.com\/blog\/2012\/06\/18\/mercedes-e-300-bluetec-hybrid\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.carideal.com\/blog\/2012\/06\/18\/mercedes-e-300-bluetec-hybrid\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog Carid\u00e9al\",\"item\":\"https:\/\/www.carideal.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"March\u00e9 automobile\",\"item\":\"https:\/\/www.carideal.com\/blog\/marche-automobile-voiture-neuve-occasion-4x4-suv\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"MERCEDES E 300 Bluetec Hybrid\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.carideal.com\/blog\/#website\",\"url\":\"https:\/\/www.carideal.com\/blog\/\",\"name\":\"Blog auto Carid\u00e9al\",\"description\":\"Actualit\u00e9 auto par des passionn\u00e9s\",\"publisher\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.carideal.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.carideal.com\/blog\/#organization\",\"name\":\"Carideal\",\"url\":\"https:\/\/www.carideal.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.carideal.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2016\/03\/logo-carideal-mandataire-automobile.png\",\"contentUrl\":\"http:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2016\/03\/logo-carideal-mandataire-automobile.png\",\"width\":300,\"height\":300,\"caption\":\"Carideal\"},\"image\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Carideal.mandataire.automobile\",\"https:\/\/x.com\/caridealauto\",\"https:\/\/www.instagram.com\/carideal1\/\",\"https:\/\/www.linkedin.com\/company\/carideal.com\",\"https:\/\/fr.pinterest.com\/schiavonsas\/\",\"https:\/\/www.youtube.com\/user\/caridealsas\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.carideal.com\/blog\/#\/schema\/person\/985c7e757d1042d647f21bfaf8d41ebc\",\"name\":\"N.S Carideal\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.carideal.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/edb7ccdf1a4e3d14aef967760d354d0e?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/edb7ccdf1a4e3d14aef967760d354d0e?s=96&r=g\",\"caption\":\"N.S Carideal\"},\"description\":\"Depuis tout petit fan d'automobile. Il est question d'essayer et de comparer toutes ces voitures qui nous ont fait r\u00e9ver, avant que celles-ci ne devient uniquement des voitures de collection.\",\"sameAs\":[\"http:\/\/www.carideal.com\/blog\",\"https:\/\/www.facebook.com\/Carideal.mandataire.automobile\/\",\"https:\/\/www.linkedin.com\/in\/nschiavon\/\",\"https:\/\/www.youtube.com\/user\/caridealsas\/\"],\"url\":\"https:\/\/www.carideal.com\/blog\/author\/admin_carideal\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MERCEDES E 300 Bluetec Hybrid - Blog auto Carid\u00e9al","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.carideal.com\/blog\/2012\/06\/18\/mercedes-e-300-bluetec-hybrid\/","og_locale":"fr_FR","og_type":"article","og_title":"MERCEDES E 300 Bluetec Hybrid - Blog auto Carid\u00e9al","og_description":"La Classe E Hybrid La premi\u00e8re Hybride de Mercedes sortit en 2009 sur une classe S \u00e0 essence ne nous avait pas laisser un magnifique souvenir:moteur \u00e9lectrique faible incapable de progresser seul, gain en consommation minime, et la sensation de conduire une limousine dot\u00e9e d'un simple Stop&amp;Start. Avec la Classe E Hybrid, cette fois diesel, ... Lire plus","og_url":"https:\/\/www.carideal.com\/blog\/2012\/06\/18\/mercedes-e-300-bluetec-hybrid\/","og_site_name":"Blog auto Carid\u00e9al","article_publisher":"https:\/\/www.facebook.com\/Carideal.mandataire.automobile","article_author":"https:\/\/www.facebook.com\/Carideal.mandataire.automobile\/","article_published_time":"2012-06-18T11:56:00+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2016\/03\/logo-carideal-mandataire-automobile.png","type":"image\/png"}],"author":"N.S Carideal","twitter_card":"summary_large_image","twitter_creator":"@caridealauto","twitter_site":"@caridealauto","twitter_misc":{"\u00c9crit par":"N.S Carideal","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.carideal.com\/blog\/2012\/06\/18\/mercedes-e-300-bluetec-hybrid\/#article","isPartOf":{"@id":"https:\/\/www.carideal.com\/blog\/2012\/06\/18\/mercedes-e-300-bluetec-hybrid\/"},"author":{"name":"N.S Carideal","@id":"https:\/\/www.carideal.com\/blog\/#\/schema\/person\/985c7e757d1042d647f21bfaf8d41ebc"},"headline":"MERCEDES E 300 Bluetec Hybrid","datePublished":"2012-06-18T11:56:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.carideal.com\/blog\/2012\/06\/18\/mercedes-e-300-bluetec-hybrid\/"},"wordCount":281,"commentCount":0,"publisher":{"@id":"https:\/\/www.carideal.com\/blog\/#organization"},"articleSection":["March\u00e9 automobile"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.carideal.com\/blog\/2012\/06\/18\/mercedes-e-300-bluetec-hybrid\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.carideal.com\/blog\/2012\/06\/18\/mercedes-e-300-bluetec-hybrid\/","url":"https:\/\/www.carideal.com\/blog\/2012\/06\/18\/mercedes-e-300-bluetec-hybrid\/","name":"MERCEDES E 300 Bluetec Hybrid - Blog auto Carid\u00e9al","isPartOf":{"@id":"https:\/\/www.carideal.com\/blog\/#website"},"datePublished":"2012-06-18T11:56:00+00:00","breadcrumb":{"@id":"https:\/\/www.carideal.com\/blog\/2012\/06\/18\/mercedes-e-300-bluetec-hybrid\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.carideal.com\/blog\/2012\/06\/18\/mercedes-e-300-bluetec-hybrid\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.carideal.com\/blog\/2012\/06\/18\/mercedes-e-300-bluetec-hybrid\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog Carid\u00e9al","item":"https:\/\/www.carideal.com\/blog\/"},{"@type":"ListItem","position":2,"name":"March\u00e9 automobile","item":"https:\/\/www.carideal.com\/blog\/marche-automobile-voiture-neuve-occasion-4x4-suv\/"},{"@type":"ListItem","position":3,"name":"MERCEDES E 300 Bluetec Hybrid"}]},{"@type":"WebSite","@id":"https:\/\/www.carideal.com\/blog\/#website","url":"https:\/\/www.carideal.com\/blog\/","name":"Blog auto Carid\u00e9al","description":"Actualit\u00e9 auto par des passionn\u00e9s","publisher":{"@id":"https:\/\/www.carideal.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.carideal.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.carideal.com\/blog\/#organization","name":"Carideal","url":"https:\/\/www.carideal.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.carideal.com\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2016\/03\/logo-carideal-mandataire-automobile.png","contentUrl":"http:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2016\/03\/logo-carideal-mandataire-automobile.png","width":300,"height":300,"caption":"Carideal"},"image":{"@id":"https:\/\/www.carideal.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Carideal.mandataire.automobile","https:\/\/x.com\/caridealauto","https:\/\/www.instagram.com\/carideal1\/","https:\/\/www.linkedin.com\/company\/carideal.com","https:\/\/fr.pinterest.com\/schiavonsas\/","https:\/\/www.youtube.com\/user\/caridealsas"]},{"@type":"Person","@id":"https:\/\/www.carideal.com\/blog\/#\/schema\/person\/985c7e757d1042d647f21bfaf8d41ebc","name":"N.S Carideal","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.carideal.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/edb7ccdf1a4e3d14aef967760d354d0e?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/edb7ccdf1a4e3d14aef967760d354d0e?s=96&r=g","caption":"N.S Carideal"},"description":"Depuis tout petit fan d'automobile. Il est question d'essayer et de comparer toutes ces voitures qui nous ont fait r\u00e9ver, avant que celles-ci ne devient uniquement des voitures de collection.","sameAs":["http:\/\/www.carideal.com\/blog","https:\/\/www.facebook.com\/Carideal.mandataire.automobile\/","https:\/\/www.linkedin.com\/in\/nschiavon\/","https:\/\/www.youtube.com\/user\/caridealsas\/"],"url":"https:\/\/www.carideal.com\/blog\/author\/admin_carideal\/"}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"wppr-widget":false},"uagb_author_info":{"display_name":"N.S Carideal","author_link":"https:\/\/www.carideal.com\/blog\/author\/admin_carideal\/"},"uagb_comment_info":0,"uagb_excerpt":"La Classe E Hybrid La premi\u00e8re Hybride de Mercedes sortit en 2009 sur une classe S \u00e0 essence ne nous avait pas laisser un magnifique souvenir:moteur \u00e9lectrique faible incapable de progresser seul, gain en consommation minime, et la sensation de conduire une limousine dot\u00e9e d'un simple Stop&amp;Start. Avec la Classe E Hybrid, cette fois diesel,\u2026","_links":{"self":[{"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/posts\/1154"}],"collection":[{"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/comments?post=1154"}],"version-history":[{"count":0,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/posts\/1154\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/media?parent=1154"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/categories?post=1154"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/tags?post=1154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}