{"id":19497,"date":"2019-07-03T19:51:21","date_gmt":"2019-07-03T17:51:21","guid":{"rendered":"http:\/\/www.carideal.com\/blog\/?page_id=19497"},"modified":"2019-07-03T19:51:21","modified_gmt":"2019-07-03T17:51:21","slug":"politique-confidentialite","status":"publish","type":"page","link":"https:\/\/www.carideal.com\/blog\/politique-confidentialite\/","title":{"rendered":"Politique de confidentialit\u00e9"},"content":{"rendered":"<h2>POLITIQUE DE PROTECTION DE LA VIE PRIV\u00c9E<\/h2>\n<p>Derni\u00e8re mise \u00e0 jour : Juillet 2019.<\/p>\n<ul>\n<li>Introduction et conditions g\u00e9n\u00e9rales<\/li>\n<li>Qui nous sommes<\/li>\n<li>Quelles donn\u00e9es nous recueillons<\/li>\n<li>Comment nous utilisons vos donn\u00e9es<\/li>\n<li>Comment nous prot\u00e9geons vos donn\u00e9es personnelles<\/li>\n<li>Avec qui partageons-nous vos donn\u00e9es personnelles ?<\/li>\n<li>Combien de temps conservons-nous vos donn\u00e9es ?<\/li>\n<li>Donn\u00e9es personnelles - Vos droits<\/li>\n<li>Contactez notre \u00e9quipe de protection des donn\u00e9es<\/li>\n<li>Modifications \u00e0 cette politique de confidentialit\u00e9<\/li>\n<li>Politique de confidentialit\u00e9 des candidats<\/li>\n<\/ul>\n<h2>Introduction et conditions g\u00e9n\u00e9rales<\/h2>\n<p>Ce document (\" Politique de confidentialit\u00e9 \"), combin\u00e9 \u00e0 la Politique sur les t\u00e9moins et aux r\u00e8gles du concours, constitue notre engagement \u00e0 prot\u00e9ger les renseignements personnels que nous d\u00e9tenons sur nos clients, nos clients \u00e9ventuels, nos abonn\u00e9s au bulletin d'information, les participants au concours, les utilisateurs du site Web ou toute autre personne dont nous d\u00e9tenons des renseignements personnels. Les informations personnelles d\u00e9crites dans cette politique sont trait\u00e9es par Carideal. En cas de vente ou de mise sous s\u00e9questre d'une partie quelconque de Carideal, nous nous r\u00e9servons le droit de continuer \u00e0 partager vos donn\u00e9es avec des tiers conform\u00e9ment aux derni\u00e8res pr\u00e9f\u00e9rences que vous nous avez communiqu\u00e9es. Vous serez inform\u00e9 de tout changement de propri\u00e9taire et le nouveau propri\u00e9taire g\u00e9rera vos pr\u00e9f\u00e9rences en mati\u00e8re de renseignements personnels.<\/p>\n<h2>Notre engagement envers vous<\/h2>\n<p>Nous nous engageons \u00e0 g\u00e9rer et \u00e0 prot\u00e9ger vos renseignements personnels conform\u00e9ment \u00e0 la l\u00e9gislation en vigueur et aux meilleures pratiques. Notre objectif est d'\u00eatre responsable, pertinent et s\u00e9curis\u00e9 lors de l'utilisation de vos donn\u00e9es. Chaque fois que vous fournissez des renseignements personnels, nous traiterons ces renseignements conform\u00e9ment \u00e0 la pr\u00e9sente politique de confidentialit\u00e9. Nous traiterons les renseignements personnels que vous nous avez fournis pour mener et g\u00e9rer nos affaires afin de vous offrir le marketing, l'information, les services et les produits les plus appropri\u00e9s et de vous offrir l'exp\u00e9rience la meilleure et la plus s\u00e9curitaire. C'est ce que nous consid\u00e9rons comme nos \" int\u00e9r\u00eats l\u00e9gitimes \". Nous nous effor\u00e7ons \u00e0 tout moment de pr\u00e9server l'exactitude et la s\u00e9curit\u00e9 de vos donn\u00e9es et de respecter vos pr\u00e9f\u00e9rences en ce qui concerne la r\u00e9ception de donn\u00e9es de marketing direct, telles que les communications postales, le courrier \u00e9lectronique, la messagerie mobile et les appels t\u00e9l\u00e9phoniques.<\/p>\n<p>Nous exploitons des sites Web qui peuvent contenir des hyperliens vers des sites Web appartenant \u00e0 des tiers et exploit\u00e9s par eux. Ces sites Web tiers ont leur propre politique de confidentialit\u00e9 et sont \u00e9galement susceptibles d'utiliser des cookies, c'est pourquoi nous vous conseillons vivement de les consulter. Ils r\u00e9giront l'utilisation des renseignements personnels que vous soumettez lorsque vous visitez ces sites Web, qui peuvent \u00e9galement \u00eatre recueillis par des t\u00e9moins. Nous n'acceptons aucune responsabilit\u00e9 pour les pratiques de confidentialit\u00e9 de ces sites Web tiers et votre utilisation de ces sites Web est \u00e0 vos propres risques.<\/p>\n<p>Nous pouvons avoir recours \u00e0 des fournisseurs tiers pour vous fournir une partie de nos services. Dans certaines circonstances, ces fournisseurs peuvent \u00eatre bas\u00e9s dans des pays en dehors de l'Espace \u00e9conomique europ\u00e9en dont les lois pr\u00e9voient une norme de protection de vos informations personnelles diff\u00e9rente de celle pr\u00e9vue par la loi britannique. Dans de telles circonstances :<\/p>\n<ul>\n<li>Nous ne transf\u00e9rerons vos donn\u00e9es personnelles qu'aux pays qui ont \u00e9t\u00e9 jug\u00e9s par la Commission europ\u00e9enne comme assurant un niveau de protection ad\u00e9quat des donn\u00e9es personnelles. Pour plus de d\u00e9tails, <a href=\"https:\/\/ec.europa.eu\/info\/law\/law-topic\/data-protection\/international-dimension-data-protection\/adequacy-decisions_en\">voir Commission europ\u00e9enne : Ad\u00e9quation de la protection des donn\u00e9es \u00e0 caract\u00e8re personnel dans les pays tiers<\/a>.<\/li>\n<li>Lorsque nous faisons appel \u00e0 certains fournisseurs de services, nous pouvons avoir recours \u00e0 des contrats sp\u00e9cifiques approuv\u00e9s par la Commission europ\u00e9enne qui accordent aux donn\u00e9es personnelles la m\u00eame protection qu'en Europe. Pour plus de d\u00e9tails, voir <a href=\"https:\/\/ec.europa.eu\/info\/law\/law-topic\/data-protection\/international-dimension-data-protection\/standard-contractual-clauses-scc_en\">Commission europ\u00e9enne : Mod\u00e8les de contrats pour le transfert de donn\u00e9es \u00e0 caract\u00e8re personnel vers des pays tiers<\/a>.<\/li>\n<li>Lorsque nous utilisons des fournisseurs bas\u00e9s aux \u00c9tats-Unis, nous pouvons leur transf\u00e9rer des donn\u00e9es s'ils font partie du bouclier de protection de la vie priv\u00e9e qui les oblige \u00e0 fournir une protection similaire aux donn\u00e9es personnelles partag\u00e9es entre l'Europe et les \u00c9tats-Unis. Pour plus de d\u00e9tails, voir <a href=\"https:\/\/ec.europa.eu\/info\/law\/law-topic\/data-protection\/international-dimension-data-protection\/eu-us-data-transfers_en\">Commission europ\u00e9enne : Bouclier de protection de la vie priv\u00e9e UE\/\u00c9tats-Unis<\/a>.<\/li>\n<\/ul>\n<p>Si vous souhaitez obtenir de plus amples informations sur le m\u00e9canisme sp\u00e9cifique que nous utilisons lors du transfert de vos donn\u00e9es personnelles hors de l'EEE, veuillez contacter : <a href=\"mailto:contact@carideal.com\">contact@carideal.com<\/a><\/p>\n<p>Vos donn\u00e9es personnelles ne seront pas divulgu\u00e9es aux institutions et autorit\u00e9s de l'\u00c9tat, sauf si la loi ou une autre r\u00e9glementation l'exige. Avant de communiquer des donn\u00e9es sur cette base, nous nous assurerons que les informations sont fournies \u00e0 une enqu\u00eate v\u00e9ritable et d\u00fbment autoris\u00e9e.<\/p>\n<p>Nous nous r\u00e9servons le droit de r\u00e9viser ou de modifier cette politique de confidentialit\u00e9 \u00e0 tout moment afin de refl\u00e9ter les changements dans nos activit\u00e9s ou les changements dans la loi. Lorsque ces changements sont importants, nous nous efforcerons d'envoyer un courriel \u00e0 tous nos utilisateurs inscrits pour nous assurer qu'ils sont inform\u00e9s de ces changements. Toutefois, il est de votre responsabilit\u00e9 de v\u00e9rifier cette politique de confidentialit\u00e9 avant chaque utilisation du site Web.<\/p>\n<h2>Qui nous sommes<\/h2>\n<p>Metadosi dispose d'un portefeuille de plus de 30 marques qui op\u00e8rent dans quatre domaines d'excellence : Sport, Technologie, Automobile et Style de vie, qui sont tous r\u00e9gis par la pr\u00e9sente politique de confidentialit\u00e9. Pour obtenir une liste \u00e0 jour de ces marques, veuillez nous contacter.<\/p>\n<h2>Quelles donn\u00e9es nous recueillons<\/h2>\n<p>Lorsque vous nous envoyez des informations, que vous nous contactez par t\u00e9l\u00e9phone, que vous nous soumettez un formulaire en ligne ou que vous visitez l'un de nos sites Web, nous pouvons recueillir des donn\u00e9es personnelles et pseudonymes vous concernant.<\/p>\n<ul>\n<li>Donn\u00e9es que vous nous fournissez<\/li>\n<li>Donn\u00e9es sur les enfants<\/li>\n<li>Les donn\u00e9es que nous achetons d'une tierce partie<\/li>\n<li>Les donn\u00e9es que nous recueillons par le biais de votre utilisation de notre site Web<\/li>\n<\/ul>\n<p>Lorsque nous parlons de donn\u00e9es personnelles, nous entendons toute information permettant de vous identifier en tant qu'individu, telle que votre nom et votre adresse postale. Les donn\u00e9es pseudonymes ne vous identifient pas en tant que personne, mais elles peuvent \u00eatre utilis\u00e9es dans leur ensemble, par exemple lorsque vous participez \u00e0 une enqu\u00eate ou lorsque nous analysons l'interaction de l'audience avec nos produits et services.<\/p>\n<h3>Donn\u00e9es que vous nous fournissez<\/h3>\n<p>Lorsque vous participez, acc\u00e9dez, achetez ou vous abonnez \u00e0 l'un de nos services, activit\u00e9s ou contenus en ligne, tels que les abonnements \u00e0 des magazines, bulletins, concours ou \u00e9v\u00e9nements, nous recevons des renseignements personnels vous concernant. Il peut s'agir d'informations telles que votre nom, votre adresse \u00e9lectronique, votre adresse postale, votre num\u00e9ro de t\u00e9l\u00e9phone ou de portable, ainsi que des informations recueillies sur votre utilisation de nos services (par exemple, quand vous acc\u00e9dez \u00e0 nos sites et combien de temps vous y restez).<\/p>\n<h3>Donn\u00e9es sur les enfants<\/h3>\n<p>Si vous \u00eates le parent ou le tuteur d'un enfant de moins de 13 ans et que vous nous avez fourni des informations appartenant \u00e0 un Enfant, nous pouvons \u00e9galement, en plus des donn\u00e9es fournies par l'Enfant, traiter des donn\u00e9es personnelles limit\u00e9es vous concernant, afin que nous puissions enregistrer votre consentement \u00e0 stocker, traiter et utiliser ces informations concernant l'Enfant pour fournir le service achet\u00e9 ou souscrit pour leur compte. Nous pouvons utiliser vos coordonn\u00e9es pour communiquer avec vous au sujet de l'utilisation de ces produits ou services par l'enfant. Si vous croyez que nous avons recueilli des renseignements personnels sur votre enfant sans votre consentement, vous pouvez communiquer avec nous \u00e0 <a href=\"http:\/\/www.carideal.com\/blog\/contactez-nous\/\">contact<\/a> et nous demander de supprimer les renseignements sur votre enfant.<\/p>\n<h3>Donn\u00e9es que nous achetons d'un tiers<\/h3>\n<p>Nous achetons occasionnellement des donn\u00e9es aupr\u00e8s de fournisseurs tiers. Les donn\u00e9es que nous achetons sont principalement des donn\u00e9es commerciales. Les donn\u00e9es commerciales peuvent inclure, sans s'y limiter, une adresse \u00e9lectronique professionnelle, l'intitul\u00e9 du poste professionnel et une adresse postale professionnelle. Un tel achat peut vous permettre de recevoir des communications de Metadosi concernant votre secteur d'activit\u00e9 ou vos int\u00e9r\u00eats commerciaux sans que vous nous ayez fourni directement vos renseignements personnels. Nous conservons des registres clairs des fournisseurs de donn\u00e9es et offrons une option de d\u00e9sabonnement \u00e0 chaque contact. Si vous avez des questions concernant l'utilisation des donn\u00e9es commerciales que nous d\u00e9tenons \u00e0 votre sujet, veuillez envoyer un courriel \u00e0 <a href=\"http:\/\/www.carideal.com\/blog\/contactez-nous\/\">confidentialit\u00e9@metadosi.fr<\/a><\/p>\n<h3>Les donn\u00e9es que nous recueillons par le biais de votre utilisation de nos sites Web<\/h3>\n<p>Nous pouvons recueillir des renseignements sur la fa\u00e7on dont vous utilisez nos sites Web ou d'autres contenus en ligne et sur les dispositifs que vous utilisez pour acc\u00e9der aux services. Cela comprend la collecte d'identifiants en ligne uniques tels que les adresses IP, qui sont des num\u00e9ros permettant d'identifier de mani\u00e8re unique un ordinateur ou un autre p\u00e9riph\u00e9rique r\u00e9seau sp\u00e9cifique sur Internet. Des donn\u00e9es anonymes seront enregistr\u00e9es dans le but de rapporter des statistiques de trafic web, des clics publicitaires, et\/ou d'autres activit\u00e9s sur nos sites. Nous pouvons \u00eatre amen\u00e9s \u00e0 recevoir des informations vous concernant de la part de tout tiers avec lequel nous pourrions nous associer par le biais de l'utilisation de technologies de cookies pour personnaliser les publicit\u00e9s de biens et services (voir Publicit\u00e9 en ligne ci-dessous pour plus d'informations). Pour refuser de recevoir des publicit\u00e9s adapt\u00e9es \u00e0 vos int\u00e9r\u00eats par nos partenaires, visitez l'Alliance europ\u00e9enne de publicit\u00e9 interactive num\u00e9rique sur <a href=\"http:\/\/youronlinechoices.eu\/\">http:\/\/youronlinechoices.eu\/<\/a><\/p>\n<p>Pour plus d'informations sur les cookies que nous utilisons, veuillez consulter la section Cookies et comment nous les utilisons ainsi que notre politique en mati\u00e8re de cookies.<\/p>\n<h2>Comment nous utilisons vos donn\u00e9es<\/h2>\n<p>Nous pouvons utiliser les informations que vous partagez avec nous et les informations que nous recueillons par votre utilisation de nos sites de la mani\u00e8re d\u00e9crite ci-dessous et comme d\u00e9crit au moment de la capture.<\/p>\n<ul>\n<li>Concours et tirages au sort<\/li>\n<li>Bulletins d'information<\/li>\n<li>\u00c9v\u00e9nements<\/li>\n<li>Abonnement au magazine<\/li>\n<li>Achat d'un v\u00e9hicule ou demande de renseignements<\/li>\n<li>Service \u00e0 la client\u00e8le<\/li>\n<li>Recherche<\/li>\n<li>Marketing direct<\/li>\n<li>Int\u00e9r\u00eat l\u00e9gitime<\/li>\n<li>Cookies et comment nous les utilisons<\/li>\n<li>Analytique<\/li>\n<li>Publicit\u00e9 en ligne<\/li>\n<li>Liens vers des sites Web de tiers<\/li>\n<li>Utilisation de nos sites Web \u00e0 partir de l'ext\u00e9rieur de France<\/li>\n<\/ul>\n<h3>Concours et tirages au sort<\/h3>\n<p>Nous utiliserons les informations que vous nous avez communiqu\u00e9es pour g\u00e9rer votre participation \u00e0 tout concours ou tirage au sort. Il peut s'agir de votre nom, de votre adresse \u00e9lectronique et de votre num\u00e9ro de t\u00e9l\u00e9phone. Nous utiliserons ces informations pour vous informer si vous \u00eates le gagnant. Vos donn\u00e9es ne seront conserv\u00e9es que pendant la dur\u00e9e du concours et ne seront ajout\u00e9es \u00e0 aucune liste de marketing \u00e0 moins que vous n'y ayez consenti, et ne seront partag\u00e9es avec un tiers que si celui-ci a \u00e9t\u00e9 nomm\u00e9 au moment de la saisie des donn\u00e9es et que vous avez explicitement consenti au partage de vos donn\u00e9es ou si ce tiers a \u00e9t\u00e9 nomm\u00e9 par nous pour g\u00e9rer la livraison de votre prix. Pour plus d'informations sur les concours et les tirages au sort, cliquez ici.<\/p>\n<h3>Bulletins d'information<\/h3>\n<p>Nous utiliserons les informations que vous nous avez communiqu\u00e9es pour vous envoyer la newsletter \u00e0 laquelle vous \u00eates abonn\u00e9. Nous ne les ajouterons \u00e0 aucune liste de marketing, \u00e0 moins que vous n'y ayez consenti. Nous vous fournirons un moyen de vous d\u00e9sabonner \u00e0 chaque newsletter que nous vous enverrons. Les informations que vous partagez avec nous dans le but de vous abonner \u00e0 la newsletter ne seront jamais partag\u00e9es avec une tierce partie.<\/p>\n<h3>\u00c9v\u00e9nements<\/h3>\n<p>Nous utiliserons les informations que vous nous avez communiqu\u00e9es pour g\u00e9rer votre inscription et votre participation \u00e0 notre \u00e9v\u00e9nement. Il peut s'agir d'un contact par t\u00e9l\u00e9phone, par courriel, par SMS ou par la poste avec des informations relatives \u00e0 l'\u00e9v\u00e9nement auquel vous vous \u00eates inscrit. Vos donn\u00e9es ne seront pas ajout\u00e9es \u00e0 des listes de marketing \u00e0 moins que vous n'y ayez consenti, et ne seront partag\u00e9es qu'avec une tierce partie l\u00e0 o\u00f9 elles ont \u00e9t\u00e9 nomm\u00e9es au moment de la saisie des donn\u00e9es et o\u00f9 vous avez explicitement consenti au partage de vos donn\u00e9es ou lorsque cette tierce partie a \u00e9t\u00e9 nomm\u00e9e par nous pour g\u00e9rer la livraison de l'\u00e9v\u00e9nement.<\/p>\n<h3>Abonnement au magazine<\/h3>\n<p>Nous utiliserons les informations que vous nous avez communiqu\u00e9es pour g\u00e9rer votre abonnement \u00e0 notre magazine, ce qui comprend l'envoi du magazine, la gestion de l'acc\u00e8s \u00e0 toute version num\u00e9rique, la prise de paiements s\u00e9curis\u00e9s, pour r\u00e9pondre \u00e0 tout cadeau offert au moment de l'achat, pour traiter toute question que vous pourriez avoir et pour vous contacter par t\u00e9l\u00e9phone, e-mail, SMS et courrier avec des informations relatives \u00e0 votre abonnement au magazine, par exemple pour vous informer de la date de fin de votre abonnement, du retard possible de livraison ou pour vous rappeler un mot de passe ou vous informer des modifications de notre politique de confidentialit\u00e9, des r\u00e8gles relatives aux t\u00e9moins ou des Conditions d'utilisation. Vos donn\u00e9es ne seront pas ajout\u00e9es \u00e0 des listes de marketing \u00e0 moins que vous n'y ayez consenti, et ne seront partag\u00e9es avec des tiers que si nous les avons mandat\u00e9s pour g\u00e9rer des aspects sp\u00e9cifiques de votre abonnement au magazine.<\/p>\n<h3>Achat d'un v\u00e9hicule ou demande de renseignements<\/h3>\n<p>Nous utiliserons les informations que vous nous avez communiqu\u00e9es pour g\u00e9rer votre demande ou l'achat d'un v\u00e9hicule et toute demande de financement par l'interm\u00e9diaire de Carideal ou ses partenaires, ce qui peut inclure la saisie et le traitement d'informations financi\u00e8res sensibles, pour vous contacter par t\u00e9l\u00e9phone, e-mail, SMS et courrier avec des informations concernant votre demande ou achat. Nous pouvons enregistrer les appels t\u00e9l\u00e9phoniques \u00e0 des fins de contr\u00f4le de la qualit\u00e9, de formation et de conformit\u00e9 aux obligations l\u00e9gales, comme les r\u00e8gles de l'Autorit\u00e9 de conduite financi\u00e8re. Vos donn\u00e9es ne seront pas ajout\u00e9es \u00e0 des listes de marketing \u00e0 moins que vous n'y ayez consenti, et ne seront partag\u00e9es avec des tiers que si nous les avons mandat\u00e9s pour g\u00e9rer des aspects sp\u00e9cifiques de votre demande ou achat, tels que des pr\u00eateurs s\u00e9lectionn\u00e9s, des courtiers en cr\u00e9dit, des concessionnaires automobiles et des groupes automobiles, des soci\u00e9t\u00e9s de pi\u00e8ces d\u00e9tach\u00e9es et des soci\u00e9t\u00e9s de livraison, pour nous permettre de vous obtenir un devis ou vous fournir un service associ\u00e9. Leur utilisation de toute donn\u00e9e que nous fournissons sera r\u00e9gie par leurs propres conditions d'utilisation et politique de confidentialit\u00e9 et en nous demandant de fournir les services pertinents, vous acceptez \u00e9galement les conditions g\u00e9n\u00e9rales et la politique de confidentialit\u00e9 du tiers concern\u00e9. Des renseignements sur les tiers qui fournissent nos services financiers ainsi que leurs modalit\u00e9s et conditions et leurs politiques de confidentialit\u00e9 vous seront fournis lorsque vous obtiendrez un devis. Afin de vous fournir un devis, certains fournisseurs de services peuvent rechercher des sources externes telles que les listes \u00e9lectorales, les jugements des tribunaux, les registres de faillite, les agences de r\u00e9f\u00e9rence de cr\u00e9dit fran\u00e7ais et les sources \u00e9ducatives, le cas \u00e9ch\u00e9ant, pour v\u00e9rifier et \u00e9valuer les informations que vous fournissez lorsque vous demandez un devis. Nous obtiendrons toujours votre consentement avant de fournir des donn\u00e9es aux pr\u00eateurs ou aux agences de r\u00e9f\u00e9rence en mati\u00e8re de cr\u00e9dit qui pourraient affecter votre cote de cr\u00e9dit.<\/p>\n<h2>Service \u00e0 la client\u00e8le<\/h2>\n<p>Nous utiliserons les renseignements que vous nous fournissez pour vous offrir un service \u00e0 la client\u00e8le li\u00e9 \u00e0 votre achat et pour r\u00e9pondre aux demandes de renseignements ou aux demandes que vous nous adressez. Vos donn\u00e9es ne seront pas ajout\u00e9es \u00e0 des listes de marketing \u00e0 moins que vous n'y ayez consenti, et ne seront partag\u00e9es avec des tiers que lorsque nous les aurons d\u00e9sign\u00e9s pour g\u00e9rer des aspects sp\u00e9cifiques de votre service client\u00e8le.<\/p>\n<h3>Recherche<\/h3>\n<p>Nous pouvons utiliser les renseignements que vous nous fournissez pour vous inviter \u00e0 participer \u00e0 des sondages et \u00e0 des groupes de discussion sur nos produits, annonceurs et services. La participation est toujours volontaire et les r\u00e9ponses que vous fournissez sont anonymes et agr\u00e9g\u00e9es pour soutenir nos apprentissages et informer les changements que nous pouvons apporter pour am\u00e9liorer nos produits et services. Vos donn\u00e9es ne seront pas ajout\u00e9es \u00e0 des listes de marketing \u00e0 moins que vous n'y ayez consenti et que vous n'en ayez \u00e9t\u00e9 inform\u00e9 au moment de leur saisie, et elles ne seront partag\u00e9es avec des tiers que lorsque nous les aurons d\u00e9sign\u00e9s pour g\u00e9rer les activit\u00e9s de recherche en notre nom.<\/p>\n<p>Occasionnellement, nous sommes pay\u00e9s par des partenaires commerciaux pour effectuer des recherches en leur nom. Dans ce cas, les donn\u00e9es que nous partageons avec eux seront anonymes, mais il se peut que nous partagions vos donn\u00e9es personnelles avec des partenaires commerciaux sp\u00e9cifiques o\u00f9 ils ont \u00e9t\u00e9 nomm\u00e9s au moment de la capture et o\u00f9 vous avez accept\u00e9 de partager vos donn\u00e9es personnelles avec eux.<\/p>\n<h3>Marketing direct<\/h3>\n<p>Nous pouvons utiliser les informations que vous partagez avec nous pour vous envoyer des offres et des promotions par e-mail, courrier, t\u00e9l\u00e9phone ou SMS lorsque nous avons des raisons l\u00e9gitimes de le faire et que vous ne vous y \u00eates pas oppos\u00e9. Nous vous fournirons un moyen de refuser de recevoir des promotions marketing \u00e0 la fois au moment de la saisie des donn\u00e9es et chaque fois que nous vous contacterons par la suite. Vous pouvez \u00e9galement envoyer un e-mail \u00e0 <a href=\"http:\/\/www.carideal.com\/blog\/contactez-nous\/\">confidentialit\u00e9@carideal<\/a> pour demander que vos coordonn\u00e9es soient supprim\u00e9es de toutes les campagnes promotionnelles. Nous n'utiliserons pas vos donn\u00e9es personnelles \u00e0 des fins de marketing si vous nous l'avez demand\u00e9.<\/p>\n<h3>Int\u00e9r\u00eat l\u00e9gitime<\/h3>\n<p>Nous pouvons traiter vos donn\u00e9es personnelles sur la base d'un int\u00e9r\u00eat l\u00e9gitime apr\u00e8s avoir soigneusement examin\u00e9 l'\u00e9quilibre entre vos droits et le b\u00e9n\u00e9fice de l'objectif pour lequel nous avons l'intention d'utiliser vos donn\u00e9es personnelles. Ces int\u00e9r\u00eats l\u00e9gitimes peuvent inclure : \u2013<\/p>\n<ul>\n<li>La promotion de produits ou services similaires, par le biais d'activit\u00e9s de marketing direct, que nous avons identifi\u00e9s comme pouvant vous int\u00e9resser en fonction de vos ant\u00e9c\u00e9dents d'interaction avec nous et pour lesquels vous n'avez pas choisi de ne pas recevoir ces informations. Pour plus d'informations sur la fa\u00e7on dont nous utilisons vos donn\u00e9es \u00e0 des fins de marketing.<\/li>\n<li>G\u00e9rer les demandes de suppression et de d\u00e9sabonnement re\u00e7ues de votre part.<\/li>\n<li>Vous inviter \u00e0 participer \u00e0 des enqu\u00eates de recherche sur nos produits ou services pour nous aider \u00e0 les am\u00e9liorer. Pour plus d'informations sur la fa\u00e7on dont nous utilisons vos donn\u00e9es \u00e0 des fins de recherche.<\/li>\n<li>Pour l'analyse statistique et l'analyse des donn\u00e9es afin d'am\u00e9liorer les produits et services qui vous sont offerts. Pour plus d'informations sur la fa\u00e7on dont nous utilisons vos donn\u00e9es \u00e0 des fins d'analyse.<\/li>\n<li>Personnaliser et am\u00e9liorer nos services en utilisant l'historique de vos achats ou de vos communications avec nous.<br \/>\nIdentifier et pr\u00e9venir les comportements frauduleux.<\/li>\n<li>Utilisation de vos donn\u00e9es pour aider \u00e0 trouver des publics similaires gr\u00e2ce \u00e0 l'utilisation de la fonction d'audience de Facebook et de l'appariement des clients Google.<\/li>\n<li>Identifier les tendances d'utilisation et d\u00e9terminer l'efficacit\u00e9 de nos campagnes pour am\u00e9liorer la publicit\u00e9 cibl\u00e9e. Pour plus d'informations sur l'utilisation de vos donn\u00e9es \u00e0 des fins publicitaires en ligne.<\/li>\n<\/ul>\n<p>Chaque fois que nous traitons des donn\u00e9es \u00e0 ces fins, nous veillons \u00e0 ce que vos droits en mati\u00e8re de donn\u00e9es personnelles soient toujours respect\u00e9s et pris en compte. Pour en savoir plus sur vos droits et sur la fa\u00e7on de les exercer.<\/p>\n<h3>Cookies et comment nous les utilisons<\/h3>\n<p>Les \"\u00a0cookies\u00a0\" sont de petits \u00e9l\u00e9ments d'information qu'un site Web envoie sur le disque dur de votre ordinateur pendant que vous visitez un site Web. Nous utilisons les cookies pour un certain nombre de raisons :<\/p>\n<p>Cookies strictement n\u00e9cessaires - Ces cookies sont n\u00e9cessaires au fonctionnement du site Web et ne peuvent pas \u00eatre d\u00e9sactiv\u00e9s dans nos syst\u00e8mes. Elles ne sont g\u00e9n\u00e9ralement d\u00e9finies qu'en r\u00e9ponse \u00e0 des actions que vous avez effectu\u00e9es et qui constituent une demande de services, telles que la d\u00e9finition de vos pr\u00e9f\u00e9rences en mati\u00e8re de confidentialit\u00e9, la connexion ou le remplissage de formulaires. Vous pouvez configurer votre navigateur pour qu'il bloque ou vous avertisse de l'existence de ces cookies, mais certaines parties du site ne fonctionneront alors pas. Ces cookies ne stockent pas d'informations personnelles identifiables.<\/p>\n<p><strong>T\u00e9moins de performance<\/strong> - Ces t\u00e9moins nous permettent de compter les visites et les sources de trafic afin que nous puissions mesurer et am\u00e9liorer la performance de notre site. Ils nous aident \u00e0 savoir quelles pages sont les plus et les moins populaires et \u00e0 voir comment les visiteurs se d\u00e9placent sur le site. Toutes les informations que ces cookies collectent sont agr\u00e9g\u00e9es et donc anonymes. Si vous n'autorisez pas ces cookies, nous ne saurons pas quand vous avez visit\u00e9 notre site et nous ne serons pas en mesure de surveiller ses performances.<\/p>\n<p><strong>Cookies fonctionnels<\/strong> - Ces cookies permettent au site Web d'offrir une fonctionnalit\u00e9 et une personnalisation am\u00e9lior\u00e9es. Ils peuvent \u00eatre \u00e9tablis par nous ou par des fournisseurs tiers dont nous avons ajout\u00e9 les services \u00e0 nos pages. Si vous n'autorisez pas ces cookies, il se peut que certains ou tous ces services ne fonctionnent pas correctement.<\/p>\n<p><strong>Cookies de ciblage<\/strong> - Ces cookies peuvent \u00eatre mis en place \u00e0 travers notre site par nos partenaires publicitaires. Ils peuvent \u00eatre utilis\u00e9s par ces soci\u00e9t\u00e9s pour \u00e9tablir un profil de vos int\u00e9r\u00eats et vous montrer des annonces pertinentes sur d'autres sites. Ils ne stockent pas directement des informations personnelles, mais sont bas\u00e9s sur l'identification unique de votre navigateur et de votre appareil Internet. Si vous n'autorisez pas ces cookies, vous obtiendrez une publicit\u00e9 moins cibl\u00e9e.<\/p>\n<p><strong>Cookies de r\u00e9seaux sociaux<\/strong> - Ces cookies sont mis en place par une s\u00e9rie de services de m\u00e9dias sociaux que nous avons ajout\u00e9s au site pour vous permettre de partager notre contenu avec vos amis et r\u00e9seaux. Ils sont capables de suivre votre navigateur sur d'autres sites et d'\u00e9tablir un profil de vos int\u00e9r\u00eats. Cela peut avoir un impact sur le contenu et les messages que vous voyez sur les autres sites Web que vous visitez. Si vous n'autorisez pas ces cookies, il se peut que vous ne puissiez pas utiliser ou voir ces outils de partage.<\/p>\n<p>Pour plus d'informations sur la fa\u00e7on dont nous utilisons les cookies, veuillez lire notre Politique sur les cookies.<\/p>\n<h2>Analytique<\/h2>\n<p>Le portefeuille de sites Web de Carideal utilise Google Analytics comme solution principale pour le suivi des visites, des interactions et des \u00e9v\u00e9nements des sites Web. Dennis utilise les donn\u00e9es d'analyse du site Web pour aider \u00e0 am\u00e9liorer la fa\u00e7on dont nous livrons le contenu et les exp\u00e9riences en ligne aux visiteurs.<\/p>\n<p>Pour plus d'informations sur le traitement de vos donn\u00e9es par Google, veuillez consulter le site : <a href=\"https:\/\/support.google.com\/analytics\/topic\/2919631?hl=fr&amp;ref_topic=1008008\">https:\/\/support.google.com\/analytics\/topic\/2919631?hl=fr&amp;ref_topic=1008008<\/a><\/p>\n<h3>Publicit\u00e9 en ligne<\/h3>\n<p>Notre site Web Carideal montre de la publicit\u00e9 aux utilisateurs. Une partie de cette publicit\u00e9 est adapt\u00e9e \u00e0 l'utilisateur individuel, comme c'est la pratique connue sous le nom de \"Publicit\u00e9 comportementale en ligne\" qui utilise des cookies pour d\u00e9couvrir des informations g\u00e9n\u00e9rales sur les pages que vous visitez. C'est pourquoi bon nombre de nos sites Web et services que vous utilisez sont gratuits. Nos syst\u00e8mes de diffusion de publicit\u00e9 et nos partenaires utilisent les informations limit\u00e9es dont ils disposent pour vous diffuser des publicit\u00e9s qu'ils jugent pertinentes. Elle ne recueille pas de renseignements personnels tels que votre nom, votre adresse \u00e9lectronique, votre adresse postale ou votre num\u00e9ro de t\u00e9l\u00e9phone.<\/p>\n<p>De temps \u00e0 autre, Carideal peut partager ces donn\u00e9es agr\u00e9g\u00e9es avec ses partenaires publicitaires. Cela pourrait signifier que lorsque vous \u00eates sur d'autres sites Web, on vous sert de la publicit\u00e9 en fonction de votre comportement sur d'autres sites.<\/p>\n<p>Le reciblage comportemental est une autre forme de publicit\u00e9 comportementale en ligne qui nous permet, ainsi qu'\u00e0 certains de nos partenaires publicitaires, de vous montrer des publicit\u00e9s bas\u00e9es sur les habitudes de navigation et les interactions avec d'autres site hors de nos sites. Par exemple, si vous avez visit\u00e9 le site Web d'un concessionnaire automobile, vous pouvez commencer \u00e0 voir des publicit\u00e9s de ce m\u00eame site de concession affichant des offres sp\u00e9ciales ou vous montrant les produits que vous avez consult\u00e9s. Cela permet aux entreprises de faire de la publicit\u00e9 aupr\u00e8s des visiteurs de leur site Web qui quittent leur site sans faire d'achat.<\/p>\n<p>Si vous ne souhaitez plus recevoir de publicit\u00e9 comportementale en ligne, cela ne signifie pas que vous ne recevrez plus de publicit\u00e9 lorsque vous utilisez nos sites. Cela signifie simplement que la publicit\u00e9 que vous voyez ne sera pas personnalis\u00e9e pour vous. Si vous souhaitez obtenir plus d'informations sur le ciblage comportemental en ligne et sur la mani\u00e8re de s'en d\u00e9sinscrire, veuillez consulter le site <a href=\"http:\/\/www.youronlinechoices.com\/\">www.youronlinechoices.com<\/a> ou vous pouvez \u00e9galement consulter le site de la <a href=\"https:\/\/www.cnil.fr\/fr\/publicite-en-ligne-la-cnil-precise-les-regles-respecter-lissue-de-ses-controles\">cnil<\/a><\/p>\n<p>Nos sites Web utilisent JavaScript pour d\u00e9tecter l'utilisation d'extensions de blocage des publicit\u00e9s pour les navigateurs Web, nous ne stockons aucune information sur les appareils des utilisateurs et ne traitons aucune donn\u00e9e personnelle.<\/p>\n<h3>Liens vers des sites Web de tiers<\/h3>\n<p>Lorsque vous cliquez sur des publicit\u00e9s ou des liens sur l'un de nos sites, vous quittez ce site et vous vous rendez sur un site tiers, ce qui est hors de notre contr\u00f4le. Lorsque nous pla\u00e7ons une annonce sur l'un de nos sites, cela ne signifie pas que nous approuvons le produit ou le service de cet annonceur. Nous n'acceptons aucune responsabilit\u00e9 quant au contenu, n'avons aucun contr\u00f4le sur et notre politique de confidentialit\u00e9 ne s'applique pas \u00e0 ces soci\u00e9t\u00e9s, sites ou contenus et si de tels sites tiers collectent des donn\u00e9es personnelles, nous ne pouvons contr\u00f4ler comment ces donn\u00e9es sont trait\u00e9es, enregistr\u00e9es ou utilis\u00e9es. Nous vous conseillons de lire leurs d\u00e9clarations de collecte de donn\u00e9es, qui accompagnent toute inscription et leurs politiques de confidentialit\u00e9 avant de soumettre vos renseignements personnels.<\/p>\n<h2>Utilisation de nos sites Web \u00e0 partir de l'ext\u00e9rieur de France<\/h2>\n<p>Nous utilisons des serveurs situ\u00e9s dans l'EEE pour stocker les donn\u00e9es. Lorsque vous communiquez vos coordonn\u00e9es et quel que soit le pays dans lequel vous vous trouvez, vous acceptez que les donn\u00e9es soient transf\u00e9r\u00e9es \u00e0 l'EEE et trait\u00e9es conform\u00e9ment aux dispositions du r\u00e8glement (UE) 2016\/679 (<strong>GDPR<\/strong>), y compris toute l\u00e9gislation d'application en mati\u00e8re de protection des donn\u00e9es en France. Si vous n'\u00eates pas d'accord, veuillez ne pas ajouter vos donn\u00e9es personnelles sur le site web. Carideal ne fait aucune d\u00e9claration et ne donne aucune garantie que le contenu et le mat\u00e9riel du site Web sont appropri\u00e9s ou disponibles pour une utilisation dans des endroits \u00e0 l'ext\u00e9rieur de France. Ceux qui choisissent d'acc\u00e9der au site Web ou d'utiliser les services \u00e0 partir d'autres endroits le font de leur propre initiative et \u00e0 leurs propres risques, et sont responsables du respect des lois locales, le cas \u00e9ch\u00e9ant et dans la mesure applicable.<\/p>\n<h2>Comment nous prot\u00e9geons vos donn\u00e9es personnelles<\/h2>\n<p>Les politiques, r\u00e8gles et mesures techniques de s\u00e9curit\u00e9 de Carideal ont \u00e9t\u00e9 mises en place pour prot\u00e9ger vos informations personnelles contre une utilisation non autoris\u00e9e ou inappropri\u00e9e et contre une perte accidentelle.<\/p>\n<p>Tous nos employ\u00e9s et les responsables du traitement des donn\u00e9es qui ont acc\u00e8s au traitement de vos renseignements personnels et qui y sont associ\u00e9s sont l\u00e9galement tenus de respecter la confidentialit\u00e9 de vos donn\u00e9es.<\/p>\n<p>Notez que certains de nos sites Web offrent des forums et des possibilit\u00e9s de commentaires o\u00f9 vous pouvez afficher de l'information. Lorsque vous le faites, sachez que d'autres visiteurs peuvent recueillir toute information que vous rendez publique.<\/p>\n<p>Nous avons mis en place des proc\u00e9dures pour traiter toute atteinte pr\u00e9sum\u00e9e \u00e0 la protection des donn\u00e9es personnelles et nous vous aviserons, ainsi que tout organisme de r\u00e9glementation comp\u00e9tent, de toute atteinte \u00e0 la protection des donn\u00e9es lorsque nous y sommes l\u00e9galement tenus.<\/p>\n<h2>Avec qui partageons-nous vos donn\u00e9es personnelles ?<\/h2>\n<p>Carideal a form\u00e9 des partenariats avec une vari\u00e9t\u00e9 d'entreprises soigneusement s\u00e9lectionn\u00e9es avec lesquelles nous partageons des donn\u00e9es afin de mener \u00e0 bien les activit\u00e9s d\u00e9crites dans la section Comment nous utilisons vos donn\u00e9es.<\/p>\n<p>Nous pouvons \u00e9galement \u00eatre amen\u00e9s \u00e0 partager vos donn\u00e9es personnelles avec des tiers que nous pouvons choisir de vendre, transf\u00e9rer ou fusionner des parties de notre entreprise ou de nos actifs. Par ailleurs, nous pourrions chercher \u00e0 acqu\u00e9rir d'autres entreprises ou \u00e0 fusionner avec elles. En cas de modification de nos activit\u00e9s, les nouveaux propri\u00e9taires peuvent utiliser vos donn\u00e9es personnelles de la m\u00eame mani\u00e8re que celle d\u00e9crite dans la pr\u00e9sente politique de confidentialit\u00e9.<\/p>\n<h3>Pendant combien de temps conservons-nous vos donn\u00e9es personnelles ?<\/h3>\n<p>Nous ne conserverons vos renseignements personnels dans nos syst\u00e8mes qu'aussi longtemps que n\u00e9cessaire pour vous fournir les produits et\/ou services que vous avez demand\u00e9s.<\/p>\n<p>Lorsque vous vous inscrivez pour recevoir des courriels marketing de notre part, nous conserverons votre adresse \u00e9lectronique apr\u00e8s que vous vous serez d\u00e9sist\u00e9 de la r\u00e9ception de courriels afin de nous assurer que nous continuons \u00e0 honorer et \u00e0 respecter cette demande. Pour vous d\u00e9sabonner des courriels de marketing en tout temps, veuillez cliquer sur le lien de d\u00e9sabonnement au bas de tout courriel de marketing et mettre \u00e0 jour les pr\u00e9f\u00e9rences de votre compte. Vous pouvez \u00e9galement nous contacter pour nous informer si vous ne souhaitez pas recevoir de mat\u00e9riel marketing de notre part.<\/p>\n<p>Dans certains cas, vous pouvez nous demander de supprimer vos donn\u00e9es : voir la rubrique \" Vos droits \" ci-dessous pour plus d'informations.<\/p>\n<p>Dans certains cas, nous pouvons anonymiser vos donn\u00e9es personnelles (afin qu'elles ne puissent plus vous \u00eatre associ\u00e9es) \u00e0 des fins de recherche ou de statistiques, auquel cas nous pouvons utiliser ces informations ind\u00e9finiment et sans autre pr\u00e9avis.<\/p>\n<h2>Donn\u00e9es personnelles - Vos droits<\/h2>\n<p>Dans le cadre du GDPR, y compris toute l\u00e9gislation de mise en \u0153uvre de la protection des donn\u00e9es en France, vous disposez des droits indiqu\u00e9s ci-dessous:-<\/p>\n<ul>\n<li>Votre droit d'\u00eatre inform\u00e9<\/li>\n<li>Votre droit d'acc\u00e8s<\/li>\n<li>Votre droit de rectification<\/li>\n<li>Votre droit \u00e0 l'effacement<\/li>\n<li>Votre droit de restreindre le traitement<\/li>\n<li>Votre droit \u00e0 la transf\u00e9rabilit\u00e9 des donn\u00e9es<\/li>\n<li>Votre droit d'opposition<\/li>\n<li>Vos droits en mati\u00e8re de prise de d\u00e9cision et de profilage automatis\u00e9s.<\/li>\n<\/ul>\n<h3>Droit d'acc\u00e8s<\/h3>\n<p>Vous pouvez, \u00e0 tout moment, demander l'acc\u00e8s aux donn\u00e9es personnelles que nous d\u00e9tenons vous concernant (vous avez peut-\u00eatre entendu parler de ce droit comme d'une \"demande d'acc\u00e8s par sujet\").<\/p>\n<p>Veuillez noter que ce droit vous donne le droit de recevoir une copie des donn\u00e9es personnelles que nous d\u00e9tenons \u00e0 votre sujet afin de vous permettre de v\u00e9rifier qu'elles sont correctes et que nous les traitons l\u00e9galement. Il ne s'agit pas d'un droit qui vous permet de demander des donn\u00e9es personnelles sur d'autres personnes, ni d'un droit de nous demander des documents sp\u00e9cifiques qui ne sont pas li\u00e9s \u00e0 vos donn\u00e9es personnelles.<\/p>\n<p>Vous pouvez exercer ce droit \u00e0 tout moment en nous \u00e9crivant aux coordonn\u00e9es indiqu\u00e9es ici et en nous indiquant que vous demandez la rectification ou l'effacement de vos donn\u00e9es personnelles et sur quelle base vous faites cette demande. Si vous voulez que nous remplacions des donn\u00e9es inexactes par de nouvelles donn\u00e9es, vous devez nous dire quelles sont ces nouvelles donn\u00e9es. Vous n'avez pas besoin de remplir un formulaire sp\u00e9cifique pour faire ce genre de demande.<\/p>\n<h3>Votre droit de restreindre le traitement<\/h3>\n<p>Lorsque nous traitons vos donn\u00e9es personnelles sur la base d'un int\u00e9r\u00eat l\u00e9gitime (voir la section Comment nous utilisons vos donn\u00e9es de la pr\u00e9sente Politique qui explique pourquoi nous utilisons vos donn\u00e9es personnelles), vous avez le droit de nous demander de cesser de les traiter de cette mani\u00e8re si vous estimez que notre poursuite a un impact sur vos droits et libert\u00e9s fondamentaux ou si vous pensez que ces int\u00e9r\u00eats l\u00e9gitimes ne sont pas valables.<\/p>\n<p>Vous pouvez \u00e9galement nous demander de cesser de traiter vos donn\u00e9es personnelles (a) si vous contestez l'exactitude de ces donn\u00e9es personnelles et souhaitez que nous v\u00e9rifiions leur exactitude ; (b) s'il a \u00e9t\u00e9 \u00e9tabli que notre utilisation des donn\u00e9es est ill\u00e9gale mais que vous ne voulez pas que nous les effacions ; (c) si nous n'avons plus besoin de traiter vos donn\u00e9es personnelles (et que nous en disposons autrement) mais que vous souhaitez que nous les conservions afin de pouvoir \u00e9tablir, exercer ou d\u00e9fendre votre droit \u00e0 la vie priv\u00e9e.<\/p>\n<p>Veuillez noter que si, pour quelque raison que ce soit, nous estimons avoir une bonne raison l\u00e9gale de continuer \u00e0 traiter des donn\u00e9es personnelles que vous nous demandez de cesser de traiter, nous vous en informerons, soit au moment o\u00f9 nous r\u00e9pondrons pour la premi\u00e8re fois \u00e0 votre demande, soit apr\u00e8s avoir eu l'occasion de l'\u00e9tudier et de l'examiner.<\/p>\n<p>Vous pouvez exercer ce droit \u00e0 tout moment en nous \u00e9crivant \u00e0 l'aide des coordonn\u00e9es indiqu\u00e9es ici et en nous indiquant que vous nous demandez de cesser le traitement de l'aspect pertinent de vos donn\u00e9es personnelles et en d\u00e9crivant les conditions ci-dessus que vous jugez pertinentes pour cette demande. Vous n'avez pas besoin de remplir un formulaire sp\u00e9cifique pour faire ce genre de demande.<\/p>\n<h3>Votre droit \u00e0 la transf\u00e9rabilit\u00e9<\/h3>\n<p>Si vous souhaitez transf\u00e9rer certaines donn\u00e9es personnelles que nous d\u00e9tenons \u00e0 votre sujet et qui sont trait\u00e9es par des moyens automatis\u00e9s \u00e0 un tiers, vous pouvez nous \u00e9crire et nous demander de vous les fournir dans un format lisible par machine couramment utilis\u00e9.<\/p>\n<p>En raison du type de travail que nous faisons et des syst\u00e8mes que nous utilisons, nous ne pensons pas que ce droit soit particuli\u00e8rement pertinent pour la majorit\u00e9 des personnes avec lesquelles nous interagissons. Toutefois, si vous souhaitez transf\u00e9rer vos donn\u00e9es de notre part \u00e0 un tiers, nous serons heureux d'\u00e9tudier de telles demandes.<\/p>\n<h3>Votre droit de cesser de recevoir des communications<\/h3>\n<p>Pour plus de d\u00e9tails sur vos droits de nous demander de cesser de vous envoyer divers types de communications, veuillez nous <a href=\"http:\/\/www.carideal.com\/blog\/contactez-nous\/\">contacter<\/a>.<\/p>\n<h3>Votre droit de vous opposer \u00e0 la prise de d\u00e9cision et au profilage automatis\u00e9s<\/h3>\n<p>Vous avez le droit d'\u00eatre inform\u00e9 de l'existence d'un processus d\u00e9cisionnel automatis\u00e9 et du profilage de vos donn\u00e9es personnelles et, le cas \u00e9ch\u00e9ant, de recevoir des informations significatives sur la logique en jeu, ainsi que sur l'importance et les cons\u00e9quences envisag\u00e9es d'un tel traitement qui vous concerne.<\/p>\n<h3>L'exercice de vos droits<\/h3>\n<p>Si vous souhaitez exercer l'un de ces droits ou simplement savoir quelles informations, le cas \u00e9ch\u00e9ant, nous d\u00e9tenons \u00e0 votre sujet, vous devez en faire la demande par \u00e9crit en envoyant un courriel \u00e0 <a href=\"http:\/\/www.carideal.com\/blog\/contactez-nous\/\">contact<\/a> ou une lettre \u00e0 Politique de confidentialit\u00e9, Carideal, Metadosi 13 av de Turin,73000 Bassens<\/p>\n<p>Vous pouvez nous aider \u00e0 traiter votre demande rapidement en nous fournissant des renseignements qui nous aideront \u00e0 identifier les dossiers que nous d\u00e9tenons \u00e0 votre sujet. Par exemple, votre nom, votre adresse, votre adresse \u00e9lectronique, votre num\u00e9ro de t\u00e9l\u00e9phone, votre num\u00e9ro d'abonn\u00e9 ou, dans le cas d'informations saisies via des cookies, l'adresse IP de l'appareil que vous avez utilis\u00e9.<\/p>\n<h3>Contactez notre \u00e9quipe de protection des donn\u00e9es<\/h3>\n<p>Si vous avez des questions ou des pr\u00e9occupations concernant le contenu de notre politique de confidentialit\u00e9 ou le traitement et l'utilisation de vos donn\u00e9es, veuillez envoyer un courriel \u00e0 l'\u00e9quipe de confidentialit\u00e9 sur <a href=\"http:\/\/www.carideal.com\/blog\/contactez-nous\/\">CONTACT<\/a> ou envoyer une lettre \u00e0 Politique de confidentialit\u00e9 Carideal, Metadosi 13 av de Turin 73000 Bassens.<\/p>\n<p>Si nous d\u00e9cidons de modifier notre Avis de confidentialit\u00e9, nous afficherons ces modifications sur cette page afin que vous soyez toujours au courant des renseignements que nous recueillons, de la fa\u00e7on dont nous les utilisons et dans quelles circonstances nous les divulguons.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>POLITIQUE DE PROTECTION DE LA VIE PRIV\u00c9E Derni\u00e8re mise \u00e0 jour : Juillet 2019. Introduction et conditions g\u00e9n\u00e9rales Qui nous sommes Quelles donn\u00e9es nous recueillons Comment nous utilisons vos donn\u00e9es Comment nous prot\u00e9geons vos donn\u00e9es personnelles Avec qui partageons-nous vos donn\u00e9es personnelles ? Combien de temps conservons-nous vos donn\u00e9es ? Donn\u00e9es personnelles &#8211; Vos droits &#8230; <a title=\"Politique de confidentialit\u00e9\" class=\"read-more\" href=\"https:\/\/www.carideal.com\/blog\/politique-confidentialite\/\" aria-label=\"En savoir plus sur Politique de confidentialit\u00e9\">Lire plus<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"class_list":["post-19497","page","type-page","status-publish"],"wppr_data":{"cwp_meta_box_check":"No"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Politique de confidentialit\u00e9 - Blog auto Carid\u00e9al<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.carideal.com\/blog\/politique-confidentialite\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Politique de confidentialit\u00e9 - Blog auto Carid\u00e9al\" \/>\n<meta property=\"og:description\" content=\"POLITIQUE DE PROTECTION DE LA VIE PRIV\u00c9E Derni\u00e8re mise \u00e0 jour : Juillet 2019. Introduction et conditions g\u00e9n\u00e9rales Qui nous sommes Quelles donn\u00e9es nous recueillons Comment nous utilisons vos donn\u00e9es Comment nous prot\u00e9geons vos donn\u00e9es personnelles Avec qui partageons-nous vos donn\u00e9es personnelles ? Combien de temps conservons-nous vos donn\u00e9es ? Donn\u00e9es personnelles - Vos droits ... Lire plus\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.carideal.com\/blog\/politique-confidentialite\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog auto Carid\u00e9al\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Carideal.mandataire.automobile\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2016\/03\/logo-carideal-mandataire-automobile.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@caridealauto\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"31 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.carideal.com\/blog\/politique-confidentialite\/\",\"url\":\"https:\/\/www.carideal.com\/blog\/politique-confidentialite\/\",\"name\":\"Politique de confidentialit\u00e9 - Blog auto Carid\u00e9al\",\"isPartOf\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/#website\"},\"datePublished\":\"2019-07-03T17:51:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/politique-confidentialite\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.carideal.com\/blog\/politique-confidentialite\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.carideal.com\/blog\/politique-confidentialite\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog Carid\u00e9al\",\"item\":\"https:\/\/www.carideal.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Politique de confidentialit\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.carideal.com\/blog\/#website\",\"url\":\"https:\/\/www.carideal.com\/blog\/\",\"name\":\"Blog auto Carid\u00e9al\",\"description\":\"Actualit\u00e9 auto par des passionn\u00e9s\",\"publisher\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.carideal.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.carideal.com\/blog\/#organization\",\"name\":\"Carideal\",\"url\":\"https:\/\/www.carideal.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.carideal.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2016\/03\/logo-carideal-mandataire-automobile.png\",\"contentUrl\":\"http:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2016\/03\/logo-carideal-mandataire-automobile.png\",\"width\":300,\"height\":300,\"caption\":\"Carideal\"},\"image\":{\"@id\":\"https:\/\/www.carideal.com\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Carideal.mandataire.automobile\",\"https:\/\/x.com\/caridealauto\",\"https:\/\/www.instagram.com\/carideal1\/\",\"https:\/\/www.linkedin.com\/company\/carideal.com\",\"https:\/\/fr.pinterest.com\/schiavonsas\/\",\"https:\/\/www.youtube.com\/user\/caridealsas\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Politique de confidentialit\u00e9 - Blog auto Carid\u00e9al","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.carideal.com\/blog\/politique-confidentialite\/","og_locale":"fr_FR","og_type":"article","og_title":"Politique de confidentialit\u00e9 - Blog auto Carid\u00e9al","og_description":"POLITIQUE DE PROTECTION DE LA VIE PRIV\u00c9E Derni\u00e8re mise \u00e0 jour : Juillet 2019. Introduction et conditions g\u00e9n\u00e9rales Qui nous sommes Quelles donn\u00e9es nous recueillons Comment nous utilisons vos donn\u00e9es Comment nous prot\u00e9geons vos donn\u00e9es personnelles Avec qui partageons-nous vos donn\u00e9es personnelles ? Combien de temps conservons-nous vos donn\u00e9es ? Donn\u00e9es personnelles - Vos droits ... Lire plus","og_url":"https:\/\/www.carideal.com\/blog\/politique-confidentialite\/","og_site_name":"Blog auto Carid\u00e9al","article_publisher":"https:\/\/www.facebook.com\/Carideal.mandataire.automobile","og_image":[{"width":300,"height":300,"url":"https:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2016\/03\/logo-carideal-mandataire-automobile.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@caridealauto","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"31 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.carideal.com\/blog\/politique-confidentialite\/","url":"https:\/\/www.carideal.com\/blog\/politique-confidentialite\/","name":"Politique de confidentialit\u00e9 - Blog auto Carid\u00e9al","isPartOf":{"@id":"https:\/\/www.carideal.com\/blog\/#website"},"datePublished":"2019-07-03T17:51:21+00:00","breadcrumb":{"@id":"https:\/\/www.carideal.com\/blog\/politique-confidentialite\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.carideal.com\/blog\/politique-confidentialite\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.carideal.com\/blog\/politique-confidentialite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog Carid\u00e9al","item":"https:\/\/www.carideal.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Politique de confidentialit\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/www.carideal.com\/blog\/#website","url":"https:\/\/www.carideal.com\/blog\/","name":"Blog auto Carid\u00e9al","description":"Actualit\u00e9 auto par des passionn\u00e9s","publisher":{"@id":"https:\/\/www.carideal.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.carideal.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.carideal.com\/blog\/#organization","name":"Carideal","url":"https:\/\/www.carideal.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.carideal.com\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2016\/03\/logo-carideal-mandataire-automobile.png","contentUrl":"http:\/\/www.carideal.com\/blog\/wp-content\/uploads\/2016\/03\/logo-carideal-mandataire-automobile.png","width":300,"height":300,"caption":"Carideal"},"image":{"@id":"https:\/\/www.carideal.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Carideal.mandataire.automobile","https:\/\/x.com\/caridealauto","https:\/\/www.instagram.com\/carideal1\/","https:\/\/www.linkedin.com\/company\/carideal.com","https:\/\/fr.pinterest.com\/schiavonsas\/","https:\/\/www.youtube.com\/user\/caridealsas"]}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"wppr-widget":false},"uagb_author_info":{"display_name":"Nicolas SCHIAVON","author_link":"https:\/\/www.carideal.com\/blog\/author\/nschiavon\/"},"uagb_comment_info":0,"uagb_excerpt":"POLITIQUE DE PROTECTION DE LA VIE PRIV\u00c9E Derni\u00e8re mise \u00e0 jour : Juillet 2019. Introduction et conditions g\u00e9n\u00e9rales Qui nous sommes Quelles donn\u00e9es nous recueillons Comment nous utilisons vos donn\u00e9es Comment nous prot\u00e9geons vos donn\u00e9es personnelles Avec qui partageons-nous vos donn\u00e9es personnelles ? Combien de temps conservons-nous vos donn\u00e9es ? Donn\u00e9es personnelles - Vos droits\u2026","_links":{"self":[{"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/pages\/19497"}],"collection":[{"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/comments?post=19497"}],"version-history":[{"count":0,"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/pages\/19497\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.carideal.com\/blog\/wp-json\/wp\/v2\/media?parent=19497"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}